{"id":11529,"date":"2025-05-08T09:22:22","date_gmt":"2025-05-08T09:22:22","guid":{"rendered":"https:\/\/www.tasgroup.eu\/it\/?page_id=11529"},"modified":"2026-05-13T10:45:46","modified_gmt":"2026-05-13T10:45:46","slug":"back-office-finanza","status":"publish","type":"page","link":"https:\/\/tasgroup.jumpgroup.it\/it\/soluzioni\/capital-markets\/back-office-finanza\/","title":{"rendered":"Back Office Finanza"},"content":{"rendered":"<style>.kb-row-layout-id11529_601415-1c > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id11529_601415-1c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id11529_601415-1c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:5rem;padding-bottom:5rem;grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}.kb-row-layout-id11529_601415-1c > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id11529_601415-1c ,.kb-row-layout-id11529_601415-1c h1,.kb-row-layout-id11529_601415-1c h2,.kb-row-layout-id11529_601415-1c h3,.kb-row-layout-id11529_601415-1c h4,.kb-row-layout-id11529_601415-1c h5,.kb-row-layout-id11529_601415-1c h6{color:#ffffff;}@media all and (max-width: 1024px){.kb-row-layout-id11529_601415-1c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id11529_601415-1c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_601415-1c alignfull has-blue-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"intro\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-equal kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column11529_f1e0ac-b7 > .kt-inside-inner-col,.kadence-column11529_f1e0ac-b7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_f1e0ac-b7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_f1e0ac-b7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_f1e0ac-b7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_f1e0ac-b7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_f1e0ac-b7{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_f1e0ac-b7 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_f1e0ac-b7 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_f1e0ac-b7 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h1 class=\"wp-block-heading has-text-align-left has-white-color has-text-color\">Advanced Multi-Asset Back Office Management: Digitalization and Innovation<\/h1>\n\n\n\n<p><strong>BOSS \u2013 La piattaforma modulare per il back office\nfinanziario<\/strong><br><\/p>\n\n\n\n<p><strong>Back office moderno. Multi-asset. Completamente integrato. Pronto per il futuro.<\/strong><\/p>\n\n\n\n<p><strong>BOSS (Back Office Securities Solution)<\/strong> \u00e8 la piattaforma di nuova generazione di TAS<br>per l\u2019amministrazione titoli e il post-trade.<br><br>Basata su <strong>Open API, microservizi<\/strong> e <strong>architettura cloud-ready<\/strong>, BOSS supporta banche e<br>istituzioni finanziarie nella digitalizzazione e automazione delle attivit\u00e0 di back office,<br>garantendo <strong>elevata efficienza operativa, qualit\u00e0 dei dati e conformit\u00e0 normativa.<\/strong><br>La piattaforma offre <strong>copertura completa del ciclo di vita degli strumenti finanziari,<\/strong><br>integrazione fluida con sistemi di front office e di mercato, e interoperabilit\u00e0 nativa con le<br>suite <strong>TAS Trading<\/strong> e <strong>Market Compliance<\/strong>, abilitando un modello operativo completamente<br>integrato <strong>front-to-back<\/strong>.<\/p>\n\n\n\n<p><span id=\"docs-internal-guid-36fba533-7fff-bf7a-b084-5b38d2769551\"><\/span><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column11529_167356-34 > .kt-inside-inner-col,.kadence-column11529_167356-34 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_167356-34 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_167356-34 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_167356-34 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_167356-34 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_167356-34{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_167356-34 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_167356-34 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_167356-34 inner-column-2 animated fadeInDown\"><div class=\"kt-inside-inner-col\"><div class=\"CardBlock CardBlock--Right\">\n  <div class=\"Card Card--Gradient\">\n    <div class=\"Card__Wrapper Card__Wrapper--Center\">\n              <h4 class=\"Card__Title\">Talk to our experts<\/h4>\n            \n              <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/contatti\/\" class=\"Button Button--Default\" target=\"_self\">\n    Contattaci\n<\/a>          <\/div>\n  <\/div>\n<\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_6efb2b-2e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_6efb2b-2e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_6efb2b-2e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:30px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_6efb2b-2e > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id11529_6efb2b-2e .kt-row-layout-bottom-sep{height:30px;}.kb-row-layout-id11529_6efb2b-2e .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id11529_6efb2b-2e .kt-row-layout-bottom-sep svg{fill:linear-gradient(270deg, rgb(243,150,0) 1.73%, rgb(160,50,243) 96.01%)!important;}@media all and (max-width: 1024px){.kb-row-layout-id11529_6efb2b-2e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id11529_6efb2b-2e .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_6efb2b-2e .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id11529_6efb2b-2e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_6efb2b-2e .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id11529_6efb2b-2e .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_6efb2b-2e alignnone has-violet-to-orange-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"divider\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_629333-79 > .kt-inside-inner-col,.kadence-column11529_629333-79 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_629333-79 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_629333-79 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_629333-79 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_629333-79 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_629333-79{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_629333-79 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_629333-79 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_629333-79 inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_72c6d1-df > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_72c6d1-df > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_72c6d1-df > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:5rem;padding-bottom:1rem;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id11529_72c6d1-df > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id11529_72c6d1-df ,.kb-row-layout-id11529_72c6d1-df h1,.kb-row-layout-id11529_72c6d1-df h2,.kb-row-layout-id11529_72c6d1-df h3,.kb-row-layout-id11529_72c6d1-df h4,.kb-row-layout-id11529_72c6d1-df h5,.kb-row-layout-id11529_72c6d1-df h6{color:#ffffff;}@media all and (max-width: 1024px){.kb-row-layout-id11529_72c6d1-df > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id11529_72c6d1-df > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_72c6d1-df alignfull has-blue-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"api-first-title\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_e88bc8-ab > .kt-inside-inner-col,.kadence-column11529_e88bc8-ab > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_e88bc8-ab > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_e88bc8-ab > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_e88bc8-ab > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_e88bc8-ab > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_e88bc8-ab{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_e88bc8-ab > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_e88bc8-ab > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_e88bc8-ab inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">Vantaggi<\/h2>\n\n\n\n<p><strong>Tecnologia all&#8217; avanguardia per un back office digitale, flessibile e scalabile<br><\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column11529_0c08bc-ee > .kt-inside-inner-col,.kadence-column11529_0c08bc-ee > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_0c08bc-ee > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_0c08bc-ee > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_0c08bc-ee > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_0c08bc-ee > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_0c08bc-ee{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_0c08bc-ee > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_0c08bc-ee > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_0c08bc-ee\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_159b95-ab > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_159b95-ab > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_159b95-ab > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0rem;padding-bottom:5rem;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id11529_159b95-ab > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id11529_159b95-ab ,.kb-row-layout-id11529_159b95-ab h1,.kb-row-layout-id11529_159b95-ab h2,.kb-row-layout-id11529_159b95-ab h3,.kb-row-layout-id11529_159b95-ab h4,.kb-row-layout-id11529_159b95-ab h5,.kb-row-layout-id11529_159b95-ab h6{color:#ffffff;}@media all and (max-width: 1024px){.kb-row-layout-id11529_159b95-ab > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id11529_159b95-ab > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_159b95-ab alignfull has-blue-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"api-first\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_ecbd79-bd > .kt-inside-inner-col,.kadence-column11529_ecbd79-bd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_ecbd79-bd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_ecbd79-bd > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_ecbd79-bd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_ecbd79-bd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_ecbd79-bd{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_ecbd79-bd > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_ecbd79-bd > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_ecbd79-bd inner-column-1\"><div class=\"kt-inside-inner-col\"><div class=\"ListIconContent wp-block-lista-icona-contenuto animated fadeInRight\">\n            <div class=\"IconContent \" data-alignement=left>\n  <div class=\"IconContent__Icon\">\n          <div class=\"Icon \" data-color=\"gradient\" data-bordered=\"dull\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 63.69 67.8\">\n  <defs>\n    <linearGradient id=\"gradient\" x1=\"2.139\" x2=\"9.681\" y1=\"2\" y2=\"2\" gradientUnits=\"userSpaceOnUse\">\n      <stop stop-color=\"#F39600\"\/>\n      <stop offset=\"1\" stop-color=\"#A032F3\"\/>\n    <\/linearGradient>\n  <\/defs>\n  <path d=\"m62.68 17.81-13.4-7.74c-.62-.36-1.4-.36-2.02 0l-2.37 1.37L39.8 8.5V4.67c0-.72-.39-1.39-1.01-1.75L34.2.27c-.62-.36-1.4-.36-2.02 0l-4.59 2.65c-.62.36-1.01 1.03-1.01 1.75V8.5l-14.5 8.37-1.9-1.09c-.62-.36-1.4-.36-2.02 0l-7.15 4.13C.39 20.27 0 20.94 0 21.66v8.26c0 .72.39 1.39 1.01 1.75l6.58 3.8v12.4c0 .72.39 1.39 1.01 1.75l15.42 8.9v3.13c0 .72.39 1.39 1.01 1.75l7.15 4.13c.31.18.66.27 1.01.27s.7-.09 1.01-.27l7.16-4.13c.62-.36 1.01-1.03 1.01-1.75v-3.13l15.42-8.9c.62-.36 1.01-1.03 1.01-1.75v-8.83l3.89-2.24c.62-.36 1.01-1.03 1.01-1.75V19.57c0-.72-.39-1.39-1.01-1.75ZM40.04 53.53v7.94l-6.83 3.97-6.88-3.94-.02-7.93 6.85-3.98 6.88 3.94Zm-23.99-23.8L9.17 33.7l-6.85-3.96-.03-7.9 6.85-3.98 6.88 3.94.02 7.92ZM28.9 9.83V4.84l4.27-2.49 4.31 2.46v4.74l.02.23-4.28 2.5-4.31-2.46Zm6.26 25.07-.03-15.14 10.01-5.78 3.09-1.81 13.13 7.55v15.16l-13.08 7.58-13.13-7.55Zm6.19 16.75-7.16-4.13c-.62-.36-1.39-.36-2.02 0l-7.15 4.13c-.62.36-1.01 1.03-1.01 1.75v2.45L9.9 47.73v-11.8c.1-.04.19-.08.28-.13l7.15-4.13c.62-.36 1.01-1.03 1.01-1.75v-8.26c0-.72-.39-1.39-1.01-1.75l-2.94-1.7 12.48-7.2c.18.29.42.54.71.71l4.59 2.65c.61.35 1.4.36 2.02 0l4.59-2.65c.29-.17.54-.42.71-.71l3.06 1.77-8.72 5.03c-.62.36-1.01 1.03-1.01 1.75v15.48c0 .72.39 1.39 1.01 1.75l13.41 7.74c.61.35 1.4.35 2.02 0l7.2-4.16v7.32l-14.11 8.15v-2.45c0-.72-.39-1.39-1.01-1.75Z\" fill=\"#000\"\/>\n  <path d=\"m27.24 36.14-4.59-2.65c-.62-.36-1.4-.36-2.02 0l-4.59 2.65c-.62.36-1.01 1.03-1.01 1.75v5.3c0 .72.39 1.39 1.01 1.75l4.59 2.65c.3.18.65.27 1.01.27s.7-.09 1.01-.27l4.59-2.65c.62-.36 1.01-1.03 1.01-1.75v-5.3c0-.72-.39-1.39-1.01-1.75Zm-1.31 1.89v4.98l-4.27 2.49-4.31-2.46-.02-4.97 4.29-2.51 4.31 2.46Z\" fill=\"#000\"\/>\n<\/svg>        <\/div>\n           <\/div>\n  <div class=\"IconContent__Content\">\n          <h4 class=\"IconContent__Title\">Copertura multi-asset e multi-venue<\/h4>\n          <\/div>\n<\/div>            <div class=\"IconContent \" data-alignement=left>\n  <div class=\"IconContent__Icon\">\n          <div class=\"Icon \" data-color=\"gradient\" data-bordered=\"dull\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 63.75 62.39\">\n  <defs>\n    <linearGradient id=\"gradient\" x1=\"2.139\" x2=\"9.681\" y1=\"2\" y2=\"2\" gradientUnits=\"userSpaceOnUse\">\n      <stop stop-color=\"#F39600\"\/>\n      <stop offset=\"1\" stop-color=\"#A032F3\"\/>\n    <\/linearGradient>\n  <\/defs>\n  <path d=\"M46.88 32.08c.44 4.25 4.05 7.58 8.41 7.58 4.66 0 8.46-3.79 8.46-8.46s-3.79-8.46-8.46-8.46c-4.37 0-7.97 3.33-8.41 7.58h-7.76V10.36c0-.56.45-1.01 1.01-1.01h6.74c.44 4.25 4.05 7.58 8.41 7.58 4.66 0 8.46-3.79 8.46-8.46S59.96 0 55.29 0c-4.37 0-7.97 3.33-8.41 7.58h-6.74c-1.53 0-2.78 1.25-2.78 2.78v19.95h-7.75c-.46-7.76-6.9-13.94-14.78-13.94S0 23.02 0 31.2s6.65 14.82 14.82 14.82 14.32-6.18 14.78-13.94h7.75v19.96c0 1.53 1.25 2.78 2.78 2.78h6.74c.44 4.25 4.05 7.58 8.41 7.58 4.66 0 8.46-3.79 8.46-8.46s-3.79-8.46-8.46-8.46c-4.37 0-7.97 3.33-8.41 7.58h-6.74c-.56 0-1.01-.45-1.01-1.01V32.09h7.76Zm8.41-7.58c3.69 0 6.7 3 6.7 6.7s-3 6.7-6.7 6.7-6.7-3-6.7-6.7 3-6.7 6.7-6.7Zm0-22.74c3.69 0 6.7 3 6.7 6.7s-3 6.7-6.7 6.7-6.7-3-6.7-6.7 3-6.7 6.7-6.7Zm-40.47 42.5c-7.2 0-13.06-5.86-13.06-13.06s5.86-13.06 13.06-13.06S27.88 24 27.88 31.2s-5.86 13.06-13.06 13.06Zm40.47 2.98c3.69 0 6.7 3 6.7 6.7s-3 6.7-6.7 6.7-6.7-3-6.7-6.7 3-6.7 6.7-6.7Z\" fill=\"#000\"\/>\n  <path d=\"M14.4 25.92c1.45-.25 3.23.32 3.82 1.91.17.46.68.69 1.13.52.46-.17.69-.68.52-1.13-.67-1.78-2.24-2.75-3.87-3.02v-2.31c0-.49-.39-.88-.88-.88s-.88.39-.88.88v2.28s-.1 0-.15.01c-2.16.38-3.58 1.92-3.6 3.92-.02 1.85 1.63 3.22 4.42 3.66 2.13.34 3.37 1.35 3.24 2.65-.11 1.11-1.29 2.21-3.06 2.12-3.08-.15-3.62-2.25-3.63-2.28-.09-.48-.55-.8-1.03-.7-.48.09-.79.55-.7 1.03.17.9 1.33 3.13 4.5 3.6v2.32c0 .49.39.88.88.88s.88-.39.88-.88v-2.28c2.25-.3 3.73-1.96 3.9-3.64.18-1.74-.95-3.98-4.72-4.58-.49-.08-2.95-.53-2.93-1.89.02-1.7 1.64-2.12 2.14-2.2Z\" fill=\"#000\"\/>\n<\/svg>        <\/div>\n           <\/div>\n  <div class=\"IconContent__Content\">\n          <h4 class=\"IconContent__Title\">Automazione della gestione delle informazioni e dei workflow manuali<\/h4>\n          <\/div>\n<\/div>            <div class=\"IconContent \" data-alignement=left>\n  <div class=\"IconContent__Icon\">\n          <div class=\"Icon \" data-color=\"gradient\" data-bordered=\"dull\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 66.94 62.35\">\n  <defs>\n    <linearGradient id=\"gradient\" x1=\"2.139\" x2=\"9.681\" y1=\"2\" y2=\"2\" gradientUnits=\"userSpaceOnUse\">\n      <stop stop-color=\"#F39600\"\/>\n      <stop offset=\"1\" stop-color=\"#A032F3\"\/>\n    <\/linearGradient>\n  <\/defs>\n  <path d=\"M66.6 31c-.19-.19-.38-.37-.56-.54-.01-.01-.02-.03-.04-.04-.02-.02-.04-.04-.07-.06-.08-.07-.15-.13-.23-.2-.16-.14-.33-.28-.49-.41-.07-.05-.13-.1-.2-.15-.17-.13-.35-.26-.52-.37-.06-.04-.12-.08-.19-.12-.18-.11-.36-.22-.54-.32l-.18-.09c-.18-.09-.36-.18-.55-.26-.06-.03-.12-.05-.18-.08-.18-.07-.36-.14-.55-.2-.06-.02-.13-.04-.19-.06-.18-.05-.36-.1-.54-.14-.07-.01-.13-.03-.2-.04-.18-.03-.36-.06-.54-.07-.07 0-.14-.01-.21-.02-.18-.01-.36-.02-.53-.01h-.22c-.18 0-.35.02-.53.04-.08 0-.15.02-.23.03-.17.03-.35.06-.52.1-.08.02-.16.03-.24.05-.17.04-.35.1-.52.16-.08.03-.16.05-.24.08-.17.06-.35.14-.52.21-.08.03-.16.07-.24.1-.18.08-.36.18-.54.27-.08.04-.15.08-.23.12-.19.11-.38.23-.57.35-.07.04-.13.08-.2.12-.26.17-.51.36-.77.55-3.17 2.44-7.8 6.07-9.81 7.65-.03-.04-.07-.08-.1-.11s-.05-.06-.08-.09c-.12-.14-.25-.27-.39-.39l-.05-.04c-.15-.13-.29-.25-.45-.37h-.01c-.65-.48-1.36-.81-2.09-1h-.04c-.16-.04-.33-.08-.5-.11-.06 0-.11-.01-.17-.02-.12-.02-.25-.04-.37-.05-.18-.02-.37-.02-.55-.02h-7.36c-3.81-2.55-6.33-2.99-10.44-2.99-5.31 0-9.59 2.59-14.63 8.88l-1.23-1.26c-.23-.23-.53-.36-.86-.36-.39.02-.63.13-.86.37L.34 44.47c-.46.48-.45 1.23.03 1.69.48.46 1.23.45 1.69-.03l3.35-3.47L19.17 56.8l-3.4 3.52c-.46.48-.45 1.23.03 1.69.23.22.53.34.83.34s.63-.12.86-.37l4.2-4.36c.45-.46.45-1.2 0-1.66l-2.77-2.85h26.02c.31 0 .61-.12.83-.34l20.81-20.08c.23-.22.36-.52.37-.84 0-.32-.12-.63-.34-.85ZM17.96 50.72c-.38 0-.7.19-.92.47L9.17 43.1c4.67-5.9 8.33-8.22 12.95-8.22 3.95 0 5.97.42 9.4 2.78.2.14.44.21.68.21h7.95c1.2.06 3.46.68 3.86 4.36H28.99c-.66 0-1.2.54-1.2 1.2s.54 1.2 1.2 1.2h16.28c.66 0 1.2-.54 1.2-1.2 0-.25-.02-.48-.03-.72v-.09c0-.04 0-.08-.01-.13 0-.14-.03-.27-.04-.41-.02-.19-.04-.39-.07-.57-.02-.12-.04-.23-.06-.35-.03-.18-.07-.36-.11-.53-.03-.12-.06-.23-.09-.34-.04-.15-.09-.3-.14-.45 0-.02-.01-.03-.02-.05 1.82-1.43 6.76-5.31 10.09-7.87 2.9-2.23 5.41-2.27 8.02-.07L44.39 50.72H17.96Z\" fill=\"#000\"\/>\n  <path d=\"m53.45 14.27-4.58-.98s-.12-.09-.16-.17l-1.74-3.05s-.02-.13-.02-.15l1.45-4.51c.3-.9-.1-1.97-.9-2.44L42.88.26c-.81-.48-1.93-.29-2.54.42l-3.13 3.54s-.14.06-.21.05h-3.49s-.1-.04-.11-.05L30.27.69c-.62-.72-1.74-.91-2.56-.43l-4.59 2.69c-.81.47-1.21 1.54-.91 2.42l1.45 4.52s-.02.16-.06.23l-1.73 3.06s-.1.08-.11.09l-4.58.99c-.92.18-1.64 1.07-1.64 2.02v5.39c0 .94.71 1.83 1.62 2.01l4.57.99s.12.09.16.17l1.74 3.05s.02.13.02.15l-.5 1.55.68.06c.45.04.9.1 1.33.16l.46.07.34-1.07c.24-.71.12-1.67-.27-2.22l-1.65-2.89c-.32-.7-1.06-1.29-1.8-1.44l-4.28-.93V16.6l4.26-.92c.73-.14 1.5-.73 1.77-1.35l1.64-2.9c.43-.63.57-1.57.33-2.29L24.61 4.9l4.02-2.36 2.92 3.28c.49.57 1.37.94 2.04.88h3.29c.75.07 1.63-.28 2.13-.86l2.92-3.3 4.03 2.37-1.35 4.21c-.24.71-.12 1.67.27 2.22l1.65 2.89c.32.69 1.08 1.29 1.8 1.44l4.28.92v4.73l-4.27.92c-.73.15-1.49.74-1.77 1.35l-1.64 2.89c-.44.63-.57 1.57-.33 2.29l1.41 4.43 2.05-1.63-1.13-3.54s.02-.16.06-.23l1.73-3.06s.1-.08.1-.09l4.58-.99c.92-.18 1.64-1.07 1.64-2.02v-5.39c0-.95-.71-1.83-1.62-2.01Z\" fill=\"#000\"\/>\n  <path d=\"M42.1 17.75c-.67 0-1.22.55-1.22 1.23 0 3.12-2.5 5.67-5.57 5.67s-5.57-2.54-5.57-5.67 2.5-5.67 5.57-5.67c.67 0 1.22-.55 1.22-1.23s-.55-1.23-1.22-1.23c-4.42 0-8.02 3.65-8.02 8.13s3.6 8.13 8.02 8.13 8.02-3.65 8.02-8.13c0-.68-.55-1.23-1.22-1.23Z\" fill=\"#000\"\/>\n<\/svg>        <\/div>\n           <\/div>\n  <div class=\"IconContent__Content\">\n          <h4 class=\"IconContent__Title\">Elevata flessibilit\u00e0 e capacit\u00e0 di integrazione<\/h4>\n          <\/div>\n<\/div>      <\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column11529_677d39-4d > .kt-inside-inner-col,.kadence-column11529_677d39-4d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_677d39-4d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_677d39-4d > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_677d39-4d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_677d39-4d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_677d39-4d{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_677d39-4d > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_677d39-4d > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_677d39-4d inner-column-2\"><div class=\"kt-inside-inner-col\"><div class=\"ListIconContent wp-block-lista-icona-contenuto animated fadeInRight\">\n            <div class=\"IconContent \" data-alignement=left>\n  <div class=\"IconContent__Icon\">\n          <div class=\"Icon \" data-color=\"gradient\" data-bordered=\"dull\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64.53 52.06\">\n  <defs>\n    <linearGradient id=\"gradient\" x1=\"2.139\" x2=\"9.681\" y1=\"2\" y2=\"2\" gradientUnits=\"userSpaceOnUse\">\n      <stop stop-color=\"#F39600\"\/>\n      <stop offset=\"1\" stop-color=\"#A032F3\"\/>\n    <\/linearGradient>\n  <\/defs>\n  <path d=\"M14.99 52.06c-.83 0-1.58-.61-1.74-1.43l-.92-4.32c-.02-.06-.1-.16-.15-.19l-2.84-1.64c-.11-.07-.24-.08-.3-.07l-4.21 1.37c-.77.27-1.68-.07-2.09-.79L.23 40.64c-.41-.72-.26-1.67.37-2.22l3.28-2.95s.09-.17.09-.23v-3.28c0-.14-.06-.26-.09-.3L.59 28.7c-.61-.54-.77-1.49-.36-2.21l2.5-4.34c.42-.72 1.32-1.06 2.11-.79l4.19 1.36c.06.01.19 0 .24-.03l2.84-1.64c.12-.07.2-.17.22-.23l.92-4.33c.16-.8.91-1.41 1.74-1.41h5c.83 0 1.58.61 1.74 1.42l.92 4.32c.02.06.1.16.15.19l2.84 1.64c.11.07.25.09.3.08l4.21-1.37c.78-.26 1.68.08 2.09.79l2.51 4.35c.41.72.26 1.67-.36 2.21l-3.29 2.96s-.09.17-.09.23v3.28c0 .13.05.26.09.3l3.29 2.97c.61.54.77 1.49.36 2.21l-2.5 4.33c-.41.72-1.32 1.06-2.11.79l-4.2-1.36c-.06-.01-.19 0-.24.03l-2.84 1.64c-.12.07-.2.17-.22.23l-.92 4.33c-.16.8-.9 1.41-1.73 1.41h-5Zm4.76-1.83Zm-4.53-.01Zm-6.14-7.83c.47 0 .97.14 1.34.4l2.7 1.55c.53.24 1.05.91 1.18 1.57l.88 4.13h4.61l.89-4.15c.13-.65.65-1.31 1.26-1.59l2.7-1.56c.48-.34 1.31-.46 1.95-.24l4.02 1.31 2.31-4-3.15-2.84c-.5-.43-.81-1.21-.75-1.88v-3.11c-.06-.58.25-1.37.76-1.81l3.14-2.82-2.31-4.01-4.03 1.31c-.62.22-1.46.1-2.01-.29l-2.7-1.55c-.53-.24-1.05-.91-1.18-1.57l-.88-4.13H15.2l-.89 4.15c-.13.65-.65 1.31-1.26 1.59l-2.69 1.56c-.48.34-1.31.46-1.95.24l-4.02-1.31-2.31 4 3.15 2.84c.5.44.81 1.22.75 1.89v3.11c.06.59-.25 1.37-.76 1.81l-3.14 2.83 2.31 4 4.03-1.31c.21-.07.44-.11.67-.11ZM4.2 43.87Zm26.56 0Zm2.28-3.93Zm-31.11-.01Zm-.02-12.72Zm2.28-3.92Zm26.59 0Zm-11.03-6.35Zm-4.53-.01Z\" fill=\"#000\"\/>\n  <path d=\"M17.49 40.9c-4.09 0-7.42-3.33-7.42-7.42s3.33-7.42 7.42-7.42c.56 0 1.01.45 1.01 1.01s-.45 1.01-1.01 1.01c-2.98 0-5.41 2.43-5.41 5.41s2.43 5.41 5.41 5.41 5.41-2.43 5.41-5.41c0-.56.45-1.01 1.01-1.01s1.01.45 1.01 1.01c0 4.09-3.33 7.42-7.42 7.42Zm25.02-9.63c-.29 0-.57-.07-.83-.22l-3.84-2.21c-.68-.4-1.01-1.26-.75-2l1.48-4L37 20.21l-4.11-.69c-.8-.16-1.39-.87-1.39-1.66v-4.45c0-.79.58-1.5 1.36-1.65l4.2-.71 1.49-2.67-1.46-3.91c-.26-.77.06-1.64.75-2.03L41.67.22c.68-.4 1.59-.24 2.11.35l2.72 3.28 3.06-.05L52.22.58c.54-.62 1.44-.77 2.13-.37l3.84 2.22c.68.4 1.01 1.26.75 2l-1.48 4 1.56 2.62 4.11.69c.8.16 1.39.87 1.39 1.66v4.45c0 .79-.58 1.5-1.36 1.65l-4.2.71-1.49 2.67 1.46 3.91c.26.77-.06 1.63-.74 2.03l-3.85 2.22c-.68.4-1.59.24-2.11-.35l-2.72-3.28-3.06.05-2.66 3.22c-.34.39-.82.59-1.3.59Zm-3.42-4.04 3.36 1.94 2.51-3.03c.43-.49 1.15-.78 1.77-.72h2.67c.54-.06 1.25.23 1.66.7l2.53 3.05 3.37-1.95-1.37-3.69c-.21-.61-.1-1.38.25-1.89l1.33-2.31c.22-.49.83-.97 1.45-1.09l3.91-.66v-3.9l-3.88-.65c-.64-.12-1.25-.6-1.51-1.17L55.8 9.55c-.31-.44-.42-1.2-.22-1.79l1.38-3.72L53.6 2.1l-2.51 3.03c-.43.49-1.14.78-1.77.72h-2.67c-.53.06-1.25-.23-1.66-.7L42.46 2.1l-3.37 1.95 1.37 3.69c.21.61.1 1.38-.25 1.89l-1.33 2.31c-.22.49-.83.97-1.45 1.09l-3.91.66v3.9l3.88.65c.64.13 1.25.6 1.51 1.17l1.34 2.31c.31.44.42 1.2.22 1.79l-1.38 3.72Zm-.25-23.05Z\" fill=\"#000\"\/>\n  <path d=\"M48.01 22.18c-3.6 0-6.53-2.93-6.53-6.53s2.93-6.53 6.53-6.53c.56 0 1.01.45 1.01 1.01s-.45 1.01-1.01 1.01c-2.49 0-4.52 2.03-4.52 4.52s2.03 4.52 4.52 4.52 4.52-2.03 4.52-4.52c0-.56.45-1.01 1.01-1.01s1.01.45 1.01 1.01c0 3.6-2.93 6.53-6.53 6.53Z\" fill=\"#000\"\/>\n<\/svg>        <\/div>\n           <\/div>\n  <div class=\"IconContent__Content\">\n          <h4 class=\"IconContent__Title\">Esperienza utente unificata e intuitiva<\/h4>\n          <\/div>\n<\/div>            <div class=\"IconContent \" data-alignement=left>\n  <div class=\"IconContent__Icon\">\n          <div class=\"Icon \" data-color=\"gradient\" data-bordered=\"dull\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 56.13 56.13\">\n  <defs>\n    <linearGradient id=\"gradient\" x1=\"2.139\" x2=\"9.681\" y1=\"2\" y2=\"2\" gradientUnits=\"userSpaceOnUse\">\n      <stop stop-color=\"#F39600\"\/>\n      <stop offset=\"1\" stop-color=\"#A032F3\"\/>\n    <\/linearGradient>\n  <\/defs>\n  <path d=\"M14.65 38.24h-.31c-2.93-.15-5.4-2.88-5.4-5.95v-2.03c0-.53-.43-.96-.96-.96H1.23v-2.46h6.76c1.89 0 3.42 1.54 3.42 3.43v2.03c0 1.74 1.46 3.41 3.06 3.49.9.04 1.76-.27 2.41-.88.65-.62 1.01-1.45 1.01-2.35v-2.28c0-1.89 1.53-3.43 3.42-3.43h5.53v-5.52c0-.53-.43-.96-.96-.96h-2.02c-3.07 0-5.79-2.47-5.95-5.4-.08-1.58.47-3.08 1.56-4.23 1.07-1.13 2.58-1.78 4.14-1.78h2.28c.53 0 .96-.43.96-.96V2.46H6.78c-2.38 0-4.31 1.94-4.31 4.31v17.85H0V6.78C0 3.04 3.04 0 6.78 0h21.28c.68 0 1.23.55 1.23 1.23v6.75c0 1.89-1.54 3.43-3.43 3.43h-2.28c-.9 0-1.73.36-2.35 1.01-.62.65-.93 1.51-.88 2.41.08 1.6 1.75 3.06 3.49 3.06h2.02c1.89 0 3.43 1.54 3.43 3.43v6.75c0 .68-.55 1.23-1.23 1.23H21.3c-.53 0-.96.43-.96.96v2.28c0 1.56-.65 3.07-1.78 4.14-1.07 1.02-2.45 1.57-3.92 1.57Z\" fill=\"#000\"\/>\n  <path d=\"M24.62 56.13H6.78C3.04 56.13 0 53.09 0 49.35V28.06c0-.68.55-1.23 1.23-1.23h6.75c1.89 0 3.43 1.54 3.43 3.43v2.28c0 .9.36 1.73 1.01 2.35s1.52.94 2.41.88c1.6-.08 3.07-1.75 3.07-3.49v-2.02c0-1.89 1.54-3.43 3.43-3.43h6.75c.68 0 1.23.55 1.23 1.23v6.76c0 .53.43.96.96.96h2.28c1.56 0 3.07.65 4.14 1.78 1.09 1.15 1.64 2.65 1.56 4.23-.15 2.93-2.88 5.4-5.95 5.4h-2.02c-.53 0-.96.43-.96.96v6.76h-2.46v-6.76c0-1.89 1.54-3.42 3.43-3.42h2.02c1.74 0 3.41-1.46 3.49-3.07.05-.9-.27-1.76-.88-2.41-.62-.65-1.45-1.01-2.35-1.01h-2.28c-1.89 0-3.43-1.53-3.43-3.42V29.3h-5.52c-.53 0-.96.43-.96.96v2.02c0 3.07-2.47 5.8-5.4 5.95-1.6.08-3.08-.47-4.23-1.56-1.13-1.07-1.78-2.58-1.78-4.14v-2.28c0-.53-.43-.96-.96-.96H2.46v20.06c0 2.38 1.93 4.31 4.31 4.31h17.85v2.46Z\" fill=\"#000\"\/>\n  <path d=\"M49.35 56.13H28.06c-.68 0-1.23-.55-1.23-1.23v-6.75c0-1.89 1.54-3.43 3.43-3.43h2.28c.9 0 1.73-.36 2.35-1.01.62-.65.93-1.51.88-2.41-.08-1.6-1.75-3.07-3.49-3.07h-2.02c-1.89 0-3.43-1.54-3.43-3.43v-6.75c0-.68.55-1.23 1.23-1.23h6.76c.53 0 .96-.43.96-.96v-2.28c0-1.56.65-3.07 1.78-4.14 1.15-1.09 2.65-1.65 4.23-1.56 2.93.15 5.4 2.88 5.4 5.95v2.02c0 .53.43.96.96.96h6.76v2.46h-6.76c-1.89 0-3.42-1.54-3.42-3.43v-2.02c0-1.74-1.46-3.41-3.06-3.49-.92-.05-1.76.27-2.41.88-.65.62-1.01 1.45-1.01 2.35v2.28c0 1.89-1.53 3.43-3.42 3.43h-5.52v5.52c0 .53.43.96.96.96h2.02c3.07 0 5.79 2.47 5.95 5.4.08 1.58-.47 3.08-1.56 4.23-1.07 1.13-2.58 1.78-4.14 1.78h-2.28c-.53 0-.96.43-.96.96v5.52h20.06c2.38 0 4.31-1.93 4.31-4.31V31.51h2.46v17.85c0 3.74-3.04 6.78-6.78 6.78Z\" fill=\"#000\"\/>\n  <path d=\"M54.9 29.3h-6.75c-1.89 0-3.43-1.54-3.43-3.43v-2.28c0-.9-.36-1.73-1.01-2.35-.65-.62-1.51-.93-2.41-.88-1.6.08-3.07 1.75-3.07 3.49v2.02c0 1.89-1.54 3.43-3.43 3.43h-6.75c-.68 0-1.23-.55-1.23-1.23v-6.76c0-.53-.43-.96-.96-.96h-2.28c-1.56 0-3.07-.65-4.14-1.78-1.09-1.15-1.64-2.65-1.56-4.23.15-2.93 2.88-5.4 5.95-5.4h2.02c.53 0 .96-.43.96-.96V1.23h2.46v6.76c0 1.89-1.54 3.42-3.43 3.42h-2.02c-1.74 0-3.41 1.46-3.49 3.06-.05.9.27 1.76.88 2.41.62.65 1.45 1.01 2.35 1.01h2.28c1.89 0 3.43 1.53 3.43 3.42v5.52h5.52c.53 0 .96-.43.96-.96v-2.02c0-3.07 2.47-5.8 5.4-5.95 1.58-.08 3.08.47 4.23 1.56 1.13 1.07 1.78 2.58 1.78 4.14v2.28c0 .53.43.96.96.96h5.52V6.78c0-2.38-1.93-4.31-4.31-4.31H31.51V0h17.85c3.74 0 6.78 3.04 6.78 6.78v21.28c0 .68-.55 1.23-1.23 1.23Z\" fill=\"#000\"\/>\n<\/svg>        <\/div>\n           <\/div>\n  <div class=\"IconContent__Content\">\n          <h4 class=\"IconContent__Title\">Adattabilit\u00e0 al modello operativo di ogni istituzione finanziaria<\/h4>\n          <\/div>\n<\/div>      <\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_ec4941-44 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_ec4941-44 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_ec4941-44 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:30px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_ec4941-44 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id11529_ec4941-44 .kt-row-layout-bottom-sep{height:30px;}.kb-row-layout-id11529_ec4941-44 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id11529_ec4941-44 .kt-row-layout-bottom-sep svg{fill:linear-gradient(270deg, rgb(243,150,0) 1.73%, rgb(160,50,243) 96.01%)!important;}@media all and (max-width: 1024px){.kb-row-layout-id11529_ec4941-44 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id11529_ec4941-44 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_ec4941-44 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id11529_ec4941-44 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_ec4941-44 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id11529_ec4941-44 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_ec4941-44 alignnone has-violet-to-orange-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"divider\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_48fb5c-21 > .kt-inside-inner-col,.kadence-column11529_48fb5c-21 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_48fb5c-21 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_48fb5c-21 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_48fb5c-21 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_48fb5c-21 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_48fb5c-21{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_48fb5c-21 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_48fb5c-21 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_48fb5c-21 inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_4a75eb-bc > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_4a75eb-bc > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_4a75eb-bc > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_4a75eb-bc > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id11529_4a75eb-bc ,.kb-row-layout-id11529_4a75eb-bc h1,.kb-row-layout-id11529_4a75eb-bc h2,.kb-row-layout-id11529_4a75eb-bc h3,.kb-row-layout-id11529_4a75eb-bc h4,.kb-row-layout-id11529_4a75eb-bc h5,.kb-row-layout-id11529_4a75eb-bc h6{color:#ffffff;}@media all and (max-width: 1024px){.kb-row-layout-id11529_4a75eb-bc > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11529_4a75eb-bc > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_4a75eb-bc alignfull wp-block-kadence-rowlayout\" id=\"one-platform\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_ade561-a2 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column11529_ade561-a2 > .kt-inside-inner-col,.kadence-column11529_ade561-a2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_ade561-a2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_ade561-a2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_ade561-a2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_ade561-a2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_ade561-a2{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_ade561-a2 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_ade561-a2 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_ade561-a2 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-media-text alignfull has-media-on-the-right is-stacked-on-mobile is-style-jmp-media-text has-blue-background-color has-background\"><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading has-white-color has-text-color\">Architettura e integrazione<\/h2>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<ul class=\"CheckmarkList wp-block-checkmark-list\">\n          <li class=\"CheckmarkList__Item\"><p>BOSS \u00e8 costruita su un\u2019architettura moderna, cloud-ready, basata su <strong>Open API<\/strong> e<br \/>\n<strong>microservizi<\/strong>, che garantisce elevata scalabilit\u00e0, interoperabilit\u00e0 e automazione.<\/p>\n<\/li>\n          <li class=\"CheckmarkList__Item\"><p>L\u2019integrazione nativa con TAS Trading e Market Compliance consente <strong>flussi dati coerenti<br \/>\nfront-to-back<\/strong>, rafforza la resilienza operativa e semplifica i processi regolamentari su tutti<br \/>\ngli strumenti finanziari.<\/p>\n<\/li>\n      <\/ul>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/www.tasgroup.eu\/app\/uploads\/sites\/2\/2025\/10\/TRADING-1-1024x574.jpg\" alt=\"Trading\" class=\"wp-image-11742 size-full\" srcset=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/10\/TRADING-1-1024x574.jpg 1024w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/10\/TRADING-1-300x168.jpg 300w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/10\/TRADING-1-768x430.jpg 768w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/10\/TRADING-1-1536x861.jpg 1536w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/10\/TRADING-1-2048x1148.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_9656ec-70 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_9656ec-70 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_9656ec-70 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_9656ec-70 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id11529_9656ec-70 ,.kb-row-layout-id11529_9656ec-70 h1,.kb-row-layout-id11529_9656ec-70 h2,.kb-row-layout-id11529_9656ec-70 h3,.kb-row-layout-id11529_9656ec-70 h4,.kb-row-layout-id11529_9656ec-70 h5,.kb-row-layout-id11529_9656ec-70 h6{color:#ffffff;}@media all and (max-width: 1024px){.kb-row-layout-id11529_9656ec-70 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11529_9656ec-70 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_9656ec-70 alignfull bubbleBlur bubbleBlur--TopRight wp-block-kadence-rowlayout\" id=\"one-platform\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_4e421f-4d > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column11529_4e421f-4d > .kt-inside-inner-col,.kadence-column11529_4e421f-4d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_4e421f-4d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_4e421f-4d > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_4e421f-4d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_4e421f-4d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_4e421f-4d{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_4e421f-4d > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_4e421f-4d > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_4e421f-4d inner-column-1\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-media-text alignfull is-stacked-on-mobile is-style-jmp-media-text has-blue-background-color has-background\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/www.tasgroup.eu\/app\/uploads\/sites\/2\/2025\/05\/abstract-financial-chart-with-neon-lights-1-1024x574.jpg\" alt=\"\" class=\"wp-image-11544 size-full\" srcset=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/05\/abstract-financial-chart-with-neon-lights-1-1024x574.jpg 1024w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/05\/abstract-financial-chart-with-neon-lights-1-300x168.jpg 300w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/05\/abstract-financial-chart-with-neon-lights-1-768x430.jpg 768w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/05\/abstract-financial-chart-with-neon-lights-1-1536x861.jpg 1536w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/05\/abstract-financial-chart-with-neon-lights-1-2048x1148.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading has-white-color has-text-color\">Interfaccia utente evoluta (UI\/UX)<\/h2>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<ul class=\"CheckmarkList wp-block-checkmark-list\">\n          <li class=\"CheckmarkList__Item\"><p><strong>Personalizzazione<\/strong> di dashboard, filtri, menu e funzionalit\u00e0 utente<\/p>\n<\/li>\n          <li class=\"CheckmarkList__Item\"><p><strong>Navigazione intuitiva<\/strong> con storico completo<\/p>\n<\/li>\n          <li class=\"CheckmarkList__Item\"><p>Autonomia elevata nell\u2019<strong>analisi dati<\/strong><\/p>\n<\/li>\n          <li class=\"CheckmarkList__Item\"><p><strong>Dashboard dinamiche<\/strong> con drill-down e grafici interattivi<\/p>\n<\/li>\n      <\/ul>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_0ae9fe-7e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_0ae9fe-7e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_0ae9fe-7e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_0ae9fe-7e > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id11529_0ae9fe-7e ,.kb-row-layout-id11529_0ae9fe-7e h1,.kb-row-layout-id11529_0ae9fe-7e h2,.kb-row-layout-id11529_0ae9fe-7e h3,.kb-row-layout-id11529_0ae9fe-7e h4,.kb-row-layout-id11529_0ae9fe-7e h5,.kb-row-layout-id11529_0ae9fe-7e h6{color:#ffffff;}@media all and (max-width: 1024px){.kb-row-layout-id11529_0ae9fe-7e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11529_0ae9fe-7e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_0ae9fe-7e alignfull bubbleBlur bubbleBlur--TopLeft wp-block-kadence-rowlayout\" id=\"one-platform\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_d6b9ae-9a > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column11529_d6b9ae-9a > .kt-inside-inner-col,.kadence-column11529_d6b9ae-9a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_d6b9ae-9a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_d6b9ae-9a > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_d6b9ae-9a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_d6b9ae-9a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_d6b9ae-9a{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_d6b9ae-9a > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_d6b9ae-9a > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_d6b9ae-9a inner-column-1\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-media-text alignfull has-media-on-the-right is-stacked-on-mobile is-style-jmp-media-text has-blue-background-color has-background\"><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading has-white-color has-text-color\">Abilitatori Core<\/h2>\n\n\n\n<p>Un insieme completo di capacit\u00e0 trasversali che garantiscano coerenza, qualit\u00e0 e controllo su tutti i<br>moduli BOSS:<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<ul class=\"CheckmarkList wp-block-checkmark-list\">\n          <li class=\"CheckmarkList__Item\"><p>Funzionalit\u00e0 di <strong>Matching e riconciliazione<\/strong> cross-modulo<\/p>\n<\/li>\n          <li class=\"CheckmarkList__Item\"><p><strong>Persistenza centralizzata<\/strong> dei dati per dashboard multi-asset<\/p>\n<\/li>\n          <li class=\"CheckmarkList__Item\"><p>Interoperabilit\u00e0 <strong>ISO 20022<\/strong><\/p>\n<\/li>\n          <li class=\"CheckmarkList__Item\"><p><strong>Native Interoperability<\/strong> with TAS <strong>Trading<\/strong> and <strong>Market Compliance<\/strong> suites.<\/p>\n<\/li>\n      <\/ul>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.tasgroup.eu\/app\/uploads\/sites\/2\/2025\/05\/immagine15-1024x683.jpeg\" alt=\"\" class=\"wp-image-11558 size-full\" srcset=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/05\/immagine15-1024x683.jpeg 1024w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/05\/immagine15-300x200.jpeg 300w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/05\/immagine15-768x512.jpeg 768w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2025\/05\/immagine15-1536x1024.jpeg 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_901556-2d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_901556-2d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_901556-2d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:2.5rem;padding-bottom:5rem;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_901556-2d > .kt-row-layout-overlay{opacity:1;background:linear-gradient(180deg, #07112c 50%, #00000000 50%);mix-blend-mode:normal;}@media all and (max-width: 1024px){.kb-row-layout-id11529_901556-2d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11529_901556-2d > .kt-row-column-wrap{padding-bottom:3rem;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_901556-2d alignfull has-violet-to-orange-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"supportiamo-list\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_e028a0-06 > .kt-inside-inner-col,.kadence-column11529_e028a0-06 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_e028a0-06 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_e028a0-06 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_e028a0-06 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_e028a0-06 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_e028a0-06{text-align:left;}.kadence-column11529_e028a0-06{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_e028a0-06 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_e028a0-06 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_e028a0-06 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"CarouselsWithModal js-carouselsWithModal\">\n        <div id=\"swiper-carousel-Za72l\" class=\"Swiper swiper Swiper--CarouselSlider js-CarouselSlider\" data-type=\"modal\" data-card-count=\"9\">\n  <div class=\"Swiper__Wrapper swiper-wrapper \">\n    <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        Gestione portafoglio di propriet\u00e0\n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>Questo modulo fornisce una gestione completa dei portafogli di propriet\u00e0 della banca, coprendo l&#8217; intero ciclo di vita degli strumenti finanziari per tutte le asset classi.<\/p>\n<p>Progettato per la gestione di volumi significativi e attivit\u00e0 di alta complessit\u00e0, garantisce automazione operativa, valutazioni accurate e conformit\u00e0 end-to-end agli standard contabili e normativi.<\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n                            <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        Derivati OTC\n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>Questo modulo gestisce l&#8217; intero ciclo di vita dei derivati OTC \u2014 dalla definizione del contratto alla liquidazione \u2014 supportando sia i flussi di lavoro bilaterali che quelli compensati.<br \/>\nFornisce automatizzazione dei prezzi, marginazione, gestione dei collaterali e reportistica regolamentare, riducendo il rischio operativo e garantendo il pieno allineamento con le pratiche di mercato attuali. La soluzione si integra perfettamente con trading desk, motori di pricing e piattaforme di collateral, consentendo una visione unificata di esposizioni e obblighi.<\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n                            <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        Derivati Listati (ETD)\n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>Questo modulo automatizza l\u2019intero ciclo di vita dei derivati quotati, integrando i modelli operativi di sedi di negoziazione, broker e clearing house. Supporta in modo end-to-end i processi di acquisizione delle operazioni, compensazione, marginazione, riconciliazione e regolamento, garantendo elevati livelli di affidabilit\u00e0, automazione e performance operative.<\/p>\n<p>Progettato per istituzioni attive su mercati e infrastrutture multiple, il modulo offre visibilit\u00e0 in tempo reale su posizioni, esposizioni e margini, assicurando al contempo coerenza contabile, controllo operativo e conformit\u00e0 ai requisiti normativi.<\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n                            <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        Amministrato titoli di terzi\n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>Questo modulo supporta l\u2019intero ciclo di custodia e amministrazione degli strumenti finanziari detenuti per conto della clientela, combinando efficienza operativa e gestione puntuale degli adempimenti fiscali e regolamentari.<br \/>\nCopre i processi di apertura rapporti, negoziazione, trasferimenti, regolamento, fiscalit\u00e0, corporate actions e reporting, garantendo coerenza con i requisiti MiFID, FATCA\/CRS e con le normative di vigilanza locali.<br \/>\nL\u2019integrazione nativa con sistemi di front office, advisory e back office assicura continuit\u00e0 operativa nei processi di servizio alla clientela e riduzione delle attivit\u00e0 manuali.<\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n                            <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        Corporate Actions and Events\n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>Questo modulo garantisce l\u2019automazione end-to-end delle corporate actions, dalla ricezione e validazione degli eventi fino al calcolo dei diritti, alla gestione delle istruzioni operative e alla contabilizzazione finale, assicurando coerenza con le disposizioni dell\u2019emittente e con i requisiti normativi.<\/p>\n<p>Il modulo si integra con Custodian, CSD e flussi informativi ISO 20022, garantendo elevati livelli di accuratezza nella gestione sia degli eventi mandatory sia voluntary.<\/p>\n<p>Workflow configurabili consentono di adattare l\u2019applicazione alle esigenze dei modelli operativi delle diverse istituzioni finanziare, riducendo attivit\u00e0 manuali e mantenendo completa tracciabilit\u00e0 degli aggiornamenti lungo tutto il ciclo di vita dell\u2019evento.<\/p>\n<p>La soluzione \u00e8 CA4U-ready e pu\u00f2 rappresentare un abilitatore strategico nei percorsi di migrazione progressiva dei sistemi di back office.<\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n                            <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        MiFID\n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>Il modulo garantisce la piena conformit\u00e0 ai requisiti MiFID II in ambito profilazione della clientela, product governance e verifica di adeguatezza e appropriatezza.<\/p>\n<p>La soluzione supporta la gestione dinamica dei questionari, controlli real-time, monitoraggio continuo e completa tracciabilit\u00e0 delle decisioni operative e consulenziali.<\/p>\n<p>Completamente configurabile, il modulo si adatta all\u2019evoluzione dei framework normativi, ai diversi modelli distributivi e alle policy di rischio delle singole istituzioni finanziarie, consentendo una compliance coerente, dimostrabile e ripetibile.<\/p>\n<p>L\u2019integrazione con strumenti di advisory e sistemi di trading permette di incorporare i controlli di compliance direttamente nei processi di investimento, supportando decisioni operative documentate e consistenti.<\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n                            <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        Settlement\n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>Questo modulo gestisce l\u2019intero ciclo di regolamento titoli e cash, fornendo\u00a0 generazione automatica delle istruzioni, monitoraggio del lifecycle, processi di matching, riconciliazione e gestione delle eccezioni operative.<\/p>\n<p>La soluzione centralizza la gestione delle Standard Settlement Instructions (SSI), garantisce coerenza nelle regole di instradamento e offre visibilit\u00e0 in tempo reale su saldi, posizioni e stato del regolamento.<\/p>\n<p>Progettato per contesti multi-custodian e multi-CSD, il modulo contribuisce alla riduzione dei settlement fails e al miglioramento dell\u2019affidabilit\u00e0 operativa lungo tutto il processo post-trade.<\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n                            <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        Collocamento fondi e SICAV\n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>Questo modulo supporta la distribuzione e l\u2019amministrazione end-to-end di fondi comuni e SICAV, dalla sottoscrizione fino alle attivit\u00e0 di reporting.<\/p>\n<p>La soluzione abilita processi straight-through processing per ordini, monitoraggio, regolamento, gestione della liquidit\u00e0 e attivit\u00e0 di back office, garantendo al contempo la gestione integrata dei rapporti con societ\u00e0 di gestione e transfer agent.<\/p>\n<p>L\u2019architettura flessibile consente alle banche di scalare le attivit\u00e0 di distribuzione e offrire alla clientela servizi trasparenti, efficienti e conformi ai requisiti normativi.<\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n                            <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        Collocamento GPM\n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>La piattaforma supporta i processi di collocamento e amministrazione delle Gestioni Patrimoniali, integrandosi in modo nativo con asset manager, strumenti di advisory e suitability e sistemi core banking.<\/p>\n<p>La soluzione abilita workflow straight-through processing per le attivit\u00e0 operative, amministrative e di rendicontazione, garantendo al contempo governance, documentazione e tracciabilit\u00e0 conformi ai requisiti MiFID.<\/p>\n<p>L\u2019architettura flessibile consente una gestione efficiente dei rapporti con societ\u00e0 prodotto e reti distributive, semplificando i processi di sottoscrizione, monitoraggio e servicing della clientela.<\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n  <\/div>\n  <div class=\"Swiper__Scrollbar swiper-scrollbar js-Swiper-Scrollbar\"><\/div>\n<\/div>        \n        <div class=\"Modal js-CarouselModal\">\n    <div class=\"Modal__Container\">\n        <span class=\"Modal__Close js-ModalClose\">&times;<\/span>\n        <div class=\"Modal__Wrapper\">  \n            <div class=\"Swiper swiper Swiper--ModalSlider js-ModalSlider\" data-card-count=\"0\" id=\"swiper-carousel-navigation-zK4kB\">\n  <div class=\"Swiper__Wrapper swiper-wrapper\">\n    <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">Gestione portafoglio di propriet\u00e0<\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>Questo modulo fornisce una gestione completa dei portafogli di propriet\u00e0 della banca, coprendo l&#8217; intero ciclo di vita degli strumenti finanziari per tutte le asset classi.<\/p>\n<p>Progettato per la gestione di volumi significativi e attivit\u00e0 di alta complessit\u00e0, garantisce automazione operativa, valutazioni accurate e conformit\u00e0 end-to-end agli standard contabili e normativi.<\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">Derivati OTC<\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>Questo modulo gestisce l&#8217; intero ciclo di vita dei derivati OTC \u2014 dalla definizione del contratto alla liquidazione \u2014 supportando sia i flussi di lavoro bilaterali che quelli compensati.<br \/>\nFornisce automatizzazione dei prezzi, marginazione, gestione dei collaterali e reportistica regolamentare, riducendo il rischio operativo e garantendo il pieno allineamento con le pratiche di mercato attuali. La soluzione si integra perfettamente con trading desk, motori di pricing e piattaforme di collateral, consentendo una visione unificata di esposizioni e obblighi.<\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">Derivati Listati (ETD)<\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>Questo modulo automatizza l\u2019intero ciclo di vita dei derivati quotati, integrando i modelli operativi di sedi di negoziazione, broker e clearing house. Supporta in modo end-to-end i processi di acquisizione delle operazioni, compensazione, marginazione, riconciliazione e regolamento, garantendo elevati livelli di affidabilit\u00e0, automazione e performance operative.<\/p>\n<p>Progettato per istituzioni attive su mercati e infrastrutture multiple, il modulo offre visibilit\u00e0 in tempo reale su posizioni, esposizioni e margini, assicurando al contempo coerenza contabile, controllo operativo e conformit\u00e0 ai requisiti normativi.<\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">Amministrato titoli di terzi<\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>Questo modulo supporta l\u2019intero ciclo di custodia e amministrazione degli strumenti finanziari detenuti per conto della clientela, combinando efficienza operativa e gestione puntuale degli adempimenti fiscali e regolamentari.<br \/>\nCopre i processi di apertura rapporti, negoziazione, trasferimenti, regolamento, fiscalit\u00e0, corporate actions e reporting, garantendo coerenza con i requisiti MiFID, FATCA\/CRS e con le normative di vigilanza locali.<br \/>\nL\u2019integrazione nativa con sistemi di front office, advisory e back office assicura continuit\u00e0 operativa nei processi di servizio alla clientela e riduzione delle attivit\u00e0 manuali.<\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">Corporate Actions and Events<\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>Questo modulo garantisce l\u2019automazione end-to-end delle corporate actions, dalla ricezione e validazione degli eventi fino al calcolo dei diritti, alla gestione delle istruzioni operative e alla contabilizzazione finale, assicurando coerenza con le disposizioni dell\u2019emittente e con i requisiti normativi.<\/p>\n<p>Il modulo si integra con Custodian, CSD e flussi informativi ISO 20022, garantendo elevati livelli di accuratezza nella gestione sia degli eventi mandatory sia voluntary.<\/p>\n<p>Workflow configurabili consentono di adattare l\u2019applicazione alle esigenze dei modelli operativi delle diverse istituzioni finanziare, riducendo attivit\u00e0 manuali e mantenendo completa tracciabilit\u00e0 degli aggiornamenti lungo tutto il ciclo di vita dell\u2019evento.<\/p>\n<p>La soluzione \u00e8 CA4U-ready e pu\u00f2 rappresentare un abilitatore strategico nei percorsi di migrazione progressiva dei sistemi di back office.<\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">MiFID<\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>Il modulo garantisce la piena conformit\u00e0 ai requisiti MiFID II in ambito profilazione della clientela, product governance e verifica di adeguatezza e appropriatezza.<\/p>\n<p>La soluzione supporta la gestione dinamica dei questionari, controlli real-time, monitoraggio continuo e completa tracciabilit\u00e0 delle decisioni operative e consulenziali.<\/p>\n<p>Completamente configurabile, il modulo si adatta all\u2019evoluzione dei framework normativi, ai diversi modelli distributivi e alle policy di rischio delle singole istituzioni finanziarie, consentendo una compliance coerente, dimostrabile e ripetibile.<\/p>\n<p>L\u2019integrazione con strumenti di advisory e sistemi di trading permette di incorporare i controlli di compliance direttamente nei processi di investimento, supportando decisioni operative documentate e consistenti.<\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">Settlement<\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>Questo modulo gestisce l\u2019intero ciclo di regolamento titoli e cash, fornendo\u00a0 generazione automatica delle istruzioni, monitoraggio del lifecycle, processi di matching, riconciliazione e gestione delle eccezioni operative.<\/p>\n<p>La soluzione centralizza la gestione delle Standard Settlement Instructions (SSI), garantisce coerenza nelle regole di instradamento e offre visibilit\u00e0 in tempo reale su saldi, posizioni e stato del regolamento.<\/p>\n<p>Progettato per contesti multi-custodian e multi-CSD, il modulo contribuisce alla riduzione dei settlement fails e al miglioramento dell\u2019affidabilit\u00e0 operativa lungo tutto il processo post-trade.<\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">Collocamento fondi e SICAV<\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>Questo modulo supporta la distribuzione e l\u2019amministrazione end-to-end di fondi comuni e SICAV, dalla sottoscrizione fino alle attivit\u00e0 di reporting.<\/p>\n<p>La soluzione abilita processi straight-through processing per ordini, monitoraggio, regolamento, gestione della liquidit\u00e0 e attivit\u00e0 di back office, garantendo al contempo la gestione integrata dei rapporti con societ\u00e0 di gestione e transfer agent.<\/p>\n<p>L\u2019architettura flessibile consente alle banche di scalare le attivit\u00e0 di distribuzione e offrire alla clientela servizi trasparenti, efficienti e conformi ai requisiti normativi.<\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">Collocamento GPM<\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>La piattaforma supporta i processi di collocamento e amministrazione delle Gestioni Patrimoniali, integrandosi in modo nativo con asset manager, strumenti di advisory e suitability e sistemi core banking.<\/p>\n<p>La soluzione abilita workflow straight-through processing per le attivit\u00e0 operative, amministrative e di rendicontazione, garantendo al contempo governance, documentazione e tracciabilit\u00e0 conformi ai requisiti MiFID.<\/p>\n<p>L\u2019architettura flessibile consente una gestione efficiente dei rapporti con societ\u00e0 prodotto e reti distributive, semplificando i processi di sottoscrizione, monitoraggio e servicing della clientela.<\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n  <\/div>\n  <div class=\"Swiper__Arrow Swiper__Arrow--Next swiper-button-next\"><\/div>\n  <div class=\"Swiper__Arrow Swiper__Arrow--Prev swiper-button-prev\"><\/div>\n  <\/div>         <\/div>\n    <\/div>\n<\/div> \n    <\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_e6c40b-78 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_e6c40b-78 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_e6c40b-78 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:80%;margin-left:auto;margin-right:auto;padding-top:5rem;padding-bottom:5rem;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_e6c40b-78 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id11529_e6c40b-78 > .kt-row-column-wrap{max-width:90%;margin-left:auto;margin-right:auto;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11529_e6c40b-78 > .kt-row-column-wrap{max-width:100%;margin-left:auto;margin-right:auto;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_e6c40b-78 alignfull has-blue-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"soluzione-in-evidenza\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_504270-ac > .kt-inside-inner-col,.kadence-column11529_504270-ac > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_504270-ac > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_504270-ac > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_504270-ac > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_504270-ac > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_504270-ac{text-align:center;}.kadence-column11529_504270-ac{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_504270-ac > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_504270-ac > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_504270-ac inner-column-1\"><div class=\"kt-inside-inner-col\"><div class=\"CardBlock CardBlock--Center\">\n  <div class=\"Card Card--Wide\">\n    <div class=\"Card__Wrapper Card__Wrapper--Left\">\n              <h4 class=\"Card__Title\">Discover BOSS and Revolutionize Your Back Office<\/h4>\n                    <div class=\"Card__Content\"> \n          <p>Turn to <strong>TAS<\/strong> for effective <strong>digital transformation<\/strong> in the banking sector. Contact us for a personalized demo!<\/p>\n\n        <\/div>\n      \n              <a href=\"\/it\/contatti\/\" class=\"Button Button--Default Button--HoverGradient\" target=\"_self\">\n    Contattaci\n<\/a>          <\/div>\n  <\/div>\n<\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_0d0c4f-d1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_0d0c4f-d1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_0d0c4f-d1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:5rem;padding-bottom:5rem;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_0d0c4f-d1{background-image:url('\/app\/uploads\/2022\/07\/sfondo1-1.jpg');background-size:cover;background-position:center center;background-attachment:fixed;background-repeat:no-repeat;}.kb-row-layout-id11529_0d0c4f-d1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (min-width: 1025px){.kb-row-layout-id11529_0d0c4f-d1{display:none !important;}}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (orientation: landscape) and (hover: none){.kb-row-layout-id11529_0d0c4f-d1{background-attachment:scroll;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_0d0c4f-d1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (min-width: 768px) and (max-width: 1024px){.kb-row-layout-id11529_0d0c4f-d1{display:none !important;}}@media all and (max-width: 767px){.kb-row-layout-id11529_0d0c4f-d1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_0d0c4f-d1{display:none !important;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_0d0c4f-d1 alignfull kb-v-lg-hidden kb-v-md-hidden kb-v-sm-hidden kt-row-has-bg kt-jarallax wp-block-kadence-rowlayout\" id=\"success-stories\" data-img-position=\"center center\" data-img-size=\"cover\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_3b77f7-99 > .kt-inside-inner-col,.kadence-column11529_3b77f7-99 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_3b77f7-99 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_3b77f7-99 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_3b77f7-99 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_3b77f7-99 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_3b77f7-99{text-align:center;}.kadence-column11529_3b77f7-99{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_3b77f7-99 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_3b77f7-99 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_3b77f7-99 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-white-color has-text-color\">Success Stories<\/h2>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_611fb1-fd > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_611fb1-fd > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_611fb1-fd > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_611fb1-fd > .kt-row-layout-overlay{opacity:0.30;}@media all and (min-width: 1025px){.kb-row-layout-id11529_611fb1-fd{display:none !important;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_611fb1-fd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (min-width: 768px) and (max-width: 1024px){.kb-row-layout-id11529_611fb1-fd{display:none !important;}}@media all and (max-width: 767px){.kb-row-layout-id11529_611fb1-fd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_611fb1-fd{display:none !important;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_611fb1-fd alignfull kb-v-lg-hidden kb-v-md-hidden kb-v-sm-hidden wp-block-kadence-rowlayout\" id=\"video\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_0c2d2c-23 > .kt-inside-inner-col,.kadence-column11529_0c2d2c-23 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_0c2d2c-23 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_0c2d2c-23 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_0c2d2c-23 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_0c2d2c-23 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_0c2d2c-23{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_0c2d2c-23 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_0c2d2c-23 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_0c2d2c-23 inner-column-1\"><div class=\"kt-inside-inner-col\"><div class=\"Video js-video-player wp-block-video\" data-poster=https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2022\/08\/video-sfondo-bg.jpg data-provider=\"youtube\">\n  <div class=\"Video__Wrapper\">\n     \n      <iframe src=\"\" data-src=\"https:\/\/www.youtube.com\/embed\/SwpkPf63304\" frameborder=\"0\" allow=\"accelerometer; autoplay; fullscreen; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n      <\/div>\n  <div class=\"Video__PlayBtn js-video-player-btn\">\n    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 103 103\">\n  <defs>\n    <linearGradient id=\"gradient\" gradientUnits=\"userSpaceOnUse\" fy=\"90%\" >\n        <stop  offset=\"0\" style=\"stop-color: var(--clr-violet-400)\"\/>\n        <stop  offset=\"1\" style=\"stop-color: var(--clr-orange-400)\"\/>\n        <animate attributeName=\"fy\" from=\"0\" to=\"1\" dur=\"5s\" repeatCount=\"indefinite\" \/>\n    <\/linearGradient>\n  <\/defs>\n  <circle cx=\"51.3906\" cy=\"51.3906\" r=\"49.3906\" stroke=\"#fff\" stroke-width=\"4\" opacity=\".8\"\/>\n  <path fill=\"#fff\" d=\"M74.8652 51.3905 39.6531 73.918V28.8629l35.2121 22.5276Z\"\/>\n<\/svg>  <\/div>\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_4facb2-4a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_4facb2-4a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_4facb2-4a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:2.5rem;padding-bottom:5rem;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_4facb2-4a > .kt-row-layout-overlay{opacity:1;background:linear-gradient(180deg, #07112c 50%, #00000000 50%);mix-blend-mode:normal;}@media all and (max-width: 1024px){.kb-row-layout-id11529_4facb2-4a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11529_4facb2-4a > .kt-row-column-wrap{padding-bottom:3rem;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_4facb2-4a alignfull has-violet-to-orange-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"insight\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_1afd03-63 > .kt-inside-inner-col,.kadence-column11529_1afd03-63 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_1afd03-63 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_1afd03-63 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_1afd03-63 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_1afd03-63 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_1afd03-63{text-align:center;}.kadence-column11529_1afd03-63{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_1afd03-63 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_1afd03-63 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_1afd03-63 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-white-color has-text-color\">Insights<\/h2>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div id=\"swiper-carousel-QPVoI\" class=\"Swiper swiper Swiper--CarouselSlider js-CarouselSlider\" data-type=\"\" data-card-count=\"10\">\n  <div class=\"Swiper__Wrapper swiper-wrapper \">\n    <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">payment networks<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">TAS<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">Euro Digitale e Digital Assets, tra sfide e opportunit\u00e0<\/h4> \n              <time class=\"Card__Date\" datetime=\"30-04-2026\" pubdate=\"pubdate\">30 Aprile 2026<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2026\/04\/creative-round-hologram-with-polygonal-pattern-euro-dark-blurry-background-money-online-banking-finance-concept-3d-rendering-scaled.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p><strong>PODCAST<\/strong> <strong>&#8211;<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>In questo episodio di\u00a0<a href=\"https:\/\/open.spotify.com\/episode\/2ukE77MepyJKwVy5U5mTsQ?si=FvWv2ZT5QzOq-zCKA7mqIA&amp;_hsmi=2&amp;utm_content=2&amp;nd=1&amp;dlsi=aa53cde728d649a8&amp;utm_source=hs_email&amp;utm_medium=email&amp;_hsenc=p2ANqtz-8gTU5lDkwDK1D2Jn5v-v2-hNq0iApnIxANi_p9bJ8hzkQJriPnzzGFl7uqsMjo2iNBZMb7\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>TAS Fintech Insights<\/strong><\/a>, il podcast TAS dedicato ai trend del mercato Fintech, \u00a0approfondiamo l&#8217;impatto dell&#8217;euro digitale e delle nuove valute programmabili sull&#8217;ecosistema bancario insieme a\u00a0<strong>Odisseo Di Michele<\/strong>, Business Development Manager Payments di TAS. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La visione di TAS supera il concetto di &#8220;silos isolato&#8221; attraverso una\u00a0<strong>piattaforma di Digital Asset Management cloud-native<\/strong>\u00a0progettata per integrare nativamente non solo l&#8217;euro digitale, ma anche stablecoin e asset tokenizzati, garantendo alle banche la flessibilit\u00e0 necessaria per gestire l&#8217;intero ciclo di vita degli asset digitali.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><a href=\"https:\/\/open.spotify.com\/episode\/2ukE77MepyJKwVy5U5mTsQ?si=FvWv2ZT5QzOq-zCKA7mqIA&amp;utm_source=hs_email&amp;utm_medium=email&amp;_hsenc=p2ANqtz-8gTU5lDkwDK1D2Jn5v-v2-hNq0iApnIxANi_p9bJ8hzkQJriPnzzGFl7uqsMjo2iNBZMb7\" target=\"_blank\" rel=\"noreferrer noopener\">Ascolta il Podcast completo<\/a><\/p>\n<!-- \/wp:paragraph --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/euro-digitale-e-digital-assets-tra-sfide-e-opportunita\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">Eventi<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">digital treasury<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">payment networks<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">PSD2<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">TAS @ Sibos 2025<\/h4> \n              <time class=\"Card__Date\" datetime=\"29-07-2025\" pubdate=\"pubdate\">29 Luglio 2025<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2022\/09\/sibos_2022-tas-2.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p><strong>29 Settembre | 2 Ottobre &#8211; Messe Frankfurt<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>TAS tra gli espositori ufficiali di Sibos 2025. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Viene a trovarci al nostro \u00a0<strong>stand F065<\/strong>\u00a0per condividere insight sulle ultime tendenze in tema di\u00a0<strong>pagamenti digitali, gestione della liquidit\u00e0, connettivit\u00e0 degli schemi di pagamento, open banking<\/strong>\u00a0e molto altro ancora.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:buttons -->\n<div class=\"wp-block-buttons\"><!-- wp:button {\"className\":\"is-style-outline\"} -->\n<div class=\"wp-block-button is-style-outline\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.tasgroup.eu\/insight\/landing\/meet-tas-at-sibos-2025\/\"><strong>Scopri di pi\u00f9 su TAS @ Sibos<\/strong><\/a><\/div>\n<!-- \/wp:button --><\/div>\n<!-- \/wp:buttons --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/eventi\/tas-sibos-2025\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">fraud management<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">TAS<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">Le nuove norme per gli Instant Payments: impatti e soluzioni<\/h4> \n              <time class=\"Card__Date\" datetime=\"01-07-2024\" pubdate=\"pubdate\">01 Luglio 2024<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2022\/10\/video-resources.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p><strong>Andrea Saracini<\/strong>, Head of IT Payments &#8211; BCC Sistemi Informatici Gruppo ICCREA, e <strong>Odisseo di Michele<\/strong>, Business Development Manager di TAS discutono l&#8217;impatto della nuova normativa sui pagamenti istantanei, evidenziando le implicazioni per le banche e la clientela sia Corporate che Retail. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:embed {\"url\":\"https:\/\/www.youtube.com\/watch?v=sBRYp8sgkUs\",\"type\":\"video\",\"providerNameSlug\":\"youtube\",\"responsive\":true,\"className\":\"wp-embed-aspect-16-9 wp-has-aspect-ratio\"} -->\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.youtube.com\/watch?v=sBRYp8sgkUs\n<\/div><\/figure>\n<!-- \/wp:embed -->\n\n<!-- wp:paragraph -->\n<p>Saracini sottolinea l&#8217;importanza dell&#8217;<strong>equiparazione dei costi tra pagamenti ordinari e istantanei<\/strong> e la necessit\u00e0 di <strong>garantire la sicurezza <\/strong>attraverso controlli di congruit\u00e0 e analisi comportamentale. Viene esplorato l&#8217;uso del <strong>cloud <\/strong>per garantire efficienza e scalabilit\u00e0 delle infrastrutture e si delinea un futuro in cui l&#8217;<strong>euro digitale<\/strong> rappresenter\u00e0 un&#8217;evoluzione naturale verso pagamenti totalmente istantanei.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><u><a rel=\"noreferrer noopener\" href=\"https:\/\/www.tasgroup.eu\/it\/contatti\/\" target=\"_blank\">Contatta i nostri esperti<\/a><\/u> per sapere come TAS pu\u00f2 essere al tuo fianco per implementare <a href=\"https:\/\/www.tasgroup.eu\/it\/soluzioni\/digital-payments\/real-time-payments\/\">soluzioni rapide, efficaci, sicure<\/a> ed in piena compliance alle nuove normative.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:buttons -->\n<div class=\"wp-block-buttons\"><!-- wp:button {\"className\":\"is-style-outline\"} -->\n<div class=\"wp-block-button is-style-outline\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.tasgroup.eu\/it\/soluzioni\/digital-payments\/real-time-payments\/\">Scopri di pi\u00f9 sulle nostre soluzioni per i Real-Time Payments<\/a><\/div>\n<!-- \/wp:button --><\/div>\n<!-- \/wp:buttons --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/le-nuove-norme-per-gli-instant-payments-impatti-e-soluzioni\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">fraud management<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">TAS<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">Nuove norme per gli Instant Payments<\/h4> \n              <time class=\"Card__Date\" datetime=\"27-03-2024\" pubdate=\"pubdate\">27 Marzo 2024<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2024\/03\/News_Instant_2.png\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p><strong>La rivoluzione dei trasferimenti finanziari oltre i confini continua per un&#8217; Europa sempre pi\u00f9 digitalizzata, equa ed efficiente.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>L&#8217;approvazione recente da parte del Parlamento Europeo di <strong>nuove normative sui trasferimenti di denaro <\/strong>segna una nuova svolta nel panorama dei pagamenti all&#8217;interno dell&#8217;Unione Europea.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Le <u><a href=\"https:\/\/www.europarl.europa.eu\/doceo\/document\/TA-9-2024-0065_EN.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">recenti disposizioni<\/a><\/u>, che entreranno in vigore dopo 20 giorni dalla pubblicazione sulla Gazzetta Ufficiale dell&#8217;UE mirano a garantire la tempestivit\u00e0 dei trasferimenti di denaro tra i conti dei consumatori e delle imprese, rappresentando un significativo passo avanti verso una maggiore efficienza e sicurezza finanziaria.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Con le nuove regole, tutti i fornitori di servizi di pagamento dovranno offrire la possibilit\u00e0 ai clienti di <strong>effettuare trasferimenti istantanei che richiedano non pi\u00f9 di dieci secondi dall&#8217;approvazione<\/strong>, in qualsiasi momento e giorno. Questo si tradurr\u00e0 in una liquidit\u00e0 quasi immediata per privati e imprese, promettendo di migliorare significativamente l&#8217;operativit\u00e0 quotidiana di milioni di europei. Inoltre, i <strong>costi dei pagamenti istantanei non dovranno superare quelli dei bonifici regolari<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Il nuovo regolamento descrive anche un processo efficiente per la gestione di ordini multipli di trasferimenti istantanei di fondi inviati in bundle ai Prestatori di Servizi di Pagamento (PSP), con particolare attenzione alle imprese nei pagamenti azienda-azienda (B2B). Quando un Utente dei Servizi di Pagamento (PSU) invia un pacchetto di ordini di trasferimento istantaneo di fondi, il PSP ricevente deve immediatamente suddividere il pacchetto, trasformando ciascun ordine in transazioni individuali di trasferimento di credito istantaneo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Inoltre, attualmente gli istituti di pagamento e di moneta elettronica sono esclusi dalla definizione di &#8220;ente&#8221; nella Direttiva 98\/26\/EC, limitando la loro partecipazione nei trasferimenti istantanei in euro. Il regolamento intende includerli, consentendo loro di partecipare ai Sistemi di Pagamento e di contribuire all&#8217;adozione dei trasferimenti di fondi istantanei.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un altro aspetto rilevante del regolamento \u00e8 l&#8217;applicabilit\u00e0 delle nuove normative anche nei Paesi membri che non utilizzano l&#8217;euro come valuta ufficiale, purch\u00e9 i loro conti bancari supportino transazioni in euro regolari. Ci\u00f2 garantir\u00e0 una condivisione diffusa dei vantaggi dei pagamenti istantanei, promuovendo ulteriormente l&#8217;integrazione economica tra i Paesi dell&#8217;UE.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Il nuovo regolamento sottolinea l&#8217;importanza delle <strong>misure antifrode<\/strong>, obbligando i fornitori di servizi di pagamento a implementare sistemi avanzati di prevenzione delle frodi e offrendo ai consumatori strumenti per limitare i rischi, come la possibilit\u00e0 di impostare un importo massimo per i trasferimenti istantanei.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Una delle principali novit\u00e0 \u00e8 inoltre l&#8217;obbligo per i fornitori di servizi di pagamento di verificare la <strong>corrispondenza dei nomi dei beneficiari e degli IBAN per tutte le transazioni<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Inoltre, il regolamento assicura l&#8217;accesso universale ai trasferimenti di fondi istantanei in euro per tutti gli Utenti dei Servizi di Pagamento (PSU). Esso stabilisce che non dovrebbero esserci disparit\u00e0 nei canali utilizzati per avviare i pagamenti istantanei rispetto ad altri tipi di trasferimenti di fondi.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>La soluzione TAS per gli Instant Payments copre completamente la conformit\u00e0 al nuovo regolamento<\/strong> con la possibilit\u00e0 di adottare la piattaforma in modo modulare e come servizio.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Grazie alle relazioni storiche con la maggior parte delle banche italiane, <strong>TAS \u00e8 leader in Italia nelle soluzioni per gli Instant Payment ed ha una conoscenza approfondita del mercato<\/strong> e una capacit\u00e0 unica di seguire le esigenze delle istituzioni finanziarie nel percorso di adozione del prodotto.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Con la sua espansione in Europa, TAS \u00e8 ben posizionata per&nbsp; guidare l&#8217;innovazione nel settore dei pagamenti istantanei, offrendo una soluzione completa, modulare e innovativa che soddisfa le esigenze delle banche italiane ed europee.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Il nostro impegno \u00e8 infatti quello di essere un vero e proprio partner per le banche, lavorando a stretto contatto con loro per comprendere e soddisfare le loro esigenze specifiche.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La modularit\u00e0 delle soluzione permette alle banche di scegliere solo i componenti effettivi necessari e di progettare un&#8217;architettura su misura in base alle proprie esigenze specifiche.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Inoltre, le nostre soluzioni sono basate su un&#8217;architettura moderna progettata per garantire una continuit\u00e0 di servizio completa, con operazioni in tempo reale 24 ore su 24.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Il nostro modello di offerta si basa su un <strong>approccio molto flessibile<\/strong> e pu\u00f2 essere implementato in cloud, on premises o in modalit\u00e0 SaaS, consentendo un rapido ed efficace time to market.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Le principali caratteristiche della <strong>soluzione TAS<\/strong>:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li><strong>Conformit\u00e0 <\/strong>completa ai requisiti del protocollo SEPA Inst: tempo di elaborazione completo &lt;10 sec., Gestione del time out.<\/li><li><strong>Piattaforma nativa del cloud<\/strong>:\u00a0 per un&#8217;offerta chiavi in mano con operazioni in tempo reale 24 \u00d7 7.<\/li><li><strong>Omni-channel<\/strong>: portale aziendale, banking retail, back-office, ecc.<\/li><li><strong>Interfacce API<\/strong>: per l&#8217;inizio del pagamento, raggiungibilit\u00e0 e richieste di messaggi.<\/li><li><strong>Potenziamento dei messaggi<\/strong>: arricchimento dei dati dei messaggi attraverso l&#8217;integrazione con il core banking.<\/li><li><strong>Screening dei messaggi<\/strong>: verifica dei messaggi attraverso l&#8217;integrazione con sistemi di screening (ad es. AML, Frode, ecc.).<\/li><li><strong>Accoppiamento dei messaggi e r-messaggi<\/strong>: accoppiamento di messaggi correlati e gestione di r-messaggi.<\/li><li><strong>Principio dei \u201cQuattro Occhi\u201d<\/strong>: \u00e8 possibile definire flussi di lavoro con processi di approvazione multilivello ovunque sia necessario.<\/li><li><strong>Allerta di errore<\/strong>: in caso di errori \u00e8 possibile inviare notifiche.<\/li><li><strong>Scalabilit\u00e0 e tolleranza<\/strong> ai guasti: la soluzione garantisce piena scalabilit\u00e0 verticale e orizzontale.<\/li><li><strong>Interfaccia<\/strong> del messaggio certificata completa <strong>SWIFT<\/strong>: l&#8217;interfaccia di rete dei messaggi \u00e8 un&#8217;applicazione completamente certificata SWIFT.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p><u><a rel=\"noreferrer noopener\" href=\"https:\/\/www.tasgroup.eu\/it\/contatti\/\" target=\"_blank\">Contatta i nostri esperti<\/a><\/u> per sapere come TAS pu\u00f2 essere al tuo fianco per implementare <a href=\"https:\/\/www.tasgroup.eu\/it\/soluzioni\/digital-payments\/real-time-payments\/\">soluzioni rapide, efficaci, sicure<\/a> ed in piena compliance alle nuove normative.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:buttons -->\n<div class=\"wp-block-buttons\"><!-- wp:button {\"className\":\"is-style-outline\"} -->\n<div class=\"wp-block-button is-style-outline\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.tasgroup.eu\/it\/soluzioni\/digital-payments\/real-time-payments\/\">Scopri di pi\u00f9 sulle nostre soluzioni per i Real-Time Payments<\/a><\/div>\n<!-- \/wp:button --><\/div>\n<!-- \/wp:buttons --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/nuove-norme-per-gli-instant-payments\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">fraud management<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">TAS<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">Investiamo sull\u2019AI: Dai Chatbot Intelligenti alla Prevenzione delle Frodi<\/h4> \n              <time class=\"Card__Date\" datetime=\"11-03-2024\" pubdate=\"pubdate\">11 Marzo 2024<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2024\/03\/LIA_Insight.png\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p>Continuiamo ad investire per l&#8217;innovazione nel settore dei pagamenti, introducendo soluzioni avanzate di intelligenza artificiale (AI) che mirano a migliorare significativamente l&#8217;efficienza, la sicurezza e l&#8217;esperienza complessiva dell&#8217;utente.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><br>\u00c8 ora disponibile sul nostro sito web un <strong>chatbot intelligente di nome LIA<\/strong>, progettato per rispondere alle domande degli utenti in modo rapido ed efficiente. Questo rappresenta solo un esempio del nostro percorso di innovazione focalizzato su due principali ambiti: l&#8217;integrazione di funzionalit\u00e0 avanzate basate su modelli di intelligenza artificiale all&#8217;interno dei nostri prodotti e l&#8217;ottimizzazione dei processi interni attraverso l&#8217;implementazione efficace dell&#8217;AI.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Sicurezza potenziata con &#8220;Fraud Protect&#8221;<\/strong><br>La sicurezza nei sistemi di pagamento \u00e8 un must imprescindibile, soprattutto nel contesto digitale che pone continue sfide e minacce. &#8220;Fraud Protect&#8221;, la nostra soluzione per la gestione delle frodi, ora incorpora avanzate tecnologie di intelligenza artificiale per identificare schemi di transazione sospetti, migliorando notevolmente la prevenzione delle frodi e la sicurezza antiterrorismo. Inoltre, l&#8217;introduzione del chatbot intelligente &#8220;IVIC&#8221;, che dialoga con l&#8217;utente in situazioni di potenziale rischio, migliora la customer experience e contribuisce a ridurre i falsi positivi.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Elaborazione e Riconciliazione delle transazioni ottimizzate<\/strong><br>L&#8217;AI svolge un ruolo cruciale nell&#8217;automazione dei processi di elaborazione e riconciliazione delle transazioni. Riducendo gli errori manuali, aumentiamo l&#8217;efficienza operativa, garantendo una maggiore precisione nelle transazioni. L&#8217;analisi predittiva gioca un ruolo fondamentale nella gestione dei picchi di transazioni, assegnando risorse in modo pi\u00f9 efficiente. Il prodotto di Tesoreria Bancaria di TAS si sta evolvendo per implementare modelli previsionali di tesoreria basati sull&#8217;AI, in grado di prevedere le esigenze di liquidit\u00e0 in tempo reale anche su base intraday.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Impatto globale dell&#8217;Intelligenza Artificiale nei Sistemi di Pagamento<\/strong><br>Crediamo che l&#8217;impiego dell&#8217;AI nel processo produttivo dei sistemi di pagamento sia diventato essenziale ed in grado di influenzare la produttivit\u00e0, la qualit\u00e0 e l&#8217;innovazione dei prodotti offerti. Dall&#8217;elaborazione delle transazioni, alla gestione progettuale, all&#8217;assistenza al cliente, l&#8217;AI sta trasformando ogni aspetto del processo, aprendo orizzonti inediti in un settore in continua evoluzione. Per questo investiamo continuamente nell&#8217;integrazione di nuove tecnologie basate sull&#8217;AI all&#8217;interno dei nostri prodotti, per rimanere all&#8217;avanguardia e garantire soluzioni di pagamento sempre pi\u00f9 efficaci e sicure.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/investiamo-sullai-dai-chatbot-intelligenti-alla-prevenzione-delle-frodi\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">Nuove esperienze di pagamento &#8211; Softpos<\/h4> \n              <time class=\"Card__Date\" datetime=\"23-05-2023\" pubdate=\"pubdate\">23 Maggio 2023<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/05\/softpos-news-tas-.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p>Una delle ultime soluzioni TAS volte a migliorare l\u2019esperienza di acquisto dell\u2019utente e del merchant \u00e8 SoftPOS, un prodotto che \u00e8 in grado di <strong>trasformare gli smartphone e i tablet Android in terminali di pagamento contactless,<\/strong> senza necessit\u00e0 di alcun supporto hardware.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>SoftPOS \u00e8 un\u2019applicazione che i commercianti possono scaricare sui propri dispositivi per trasformare qualsiasi device mobile Android (abilitato NFC) in un dispositivo di accettazione dei pagamenti.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>SoftPOS \u00e8 un\u2019alternativa completamente basata su software rispetto ai tradizionali terminali di pagamento. Con SoftPOS i merchant possono effettuare transazioni contactless sui propri dispositivi mobili, facilitando l\u2019acquisizione di PIN e l\u2019autenticazione, <strong>senza la necessit\u00e0 di un hardware aggiuntivo e mantenendo un livello di sicurezza molto elevato<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Questo \u00e8 un enorme vantaggio soprattutto per i piccoli esercenti che possono sfruttare al meglio la soluzione grazie ai costi contenuti e ai vantaggi operativi della tecnologia, in particolare nei settori dove l\u2019utilizzo delle carte contactless ha raggiunto un\u2019ampia diffusione.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Per le micro-attivit\u00e0 infatti SoftPOS \u00e8 un modo pi\u00f9 semplice ed economico per accettare pagamenti con carta di credito o di debito, evitando di dover spendere per l\u2019acquisto di dispositivi \u201chardware\u201d.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Inoltre l\u2019hardware tradizionale pu\u00f2 presentare maggiori barriere all\u2019adozione perch\u00e9 si deve fare \u201cconoscenza\u201d col dispositivo, mentre utilizzare il proprio smartphone va incontro a meno rischi di errore e maggiore propensione a sperimentare nuovi casi d\u2019uso.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Anche per le realt\u00e0 commerciali di grandi dimensioni, soggette ad afflussi importanti di clienti soprattutto in determinati orari o periodi dell\u2019anno, i vantaggi di SoftPOS sono molteplici: la possibilit\u00e0 di offrire un <strong>processo di pagamento senza interruzioni,<\/strong> la <strong>moltiplicazione dei punti di pagamento<\/strong> senza investimenti in postazioni fisiche, la possibilit\u00e0 di <strong>acquisire pagamenti in movimento<\/strong>, la f<strong>acilit\u00e0 di formazione sul processo sia del commerciante che dei dipendenti<\/strong>, la <strong>virtualizzazione dello scontrino <\/strong>con invio automatico alla mail del cliente.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Per il titolare della carta occorrer\u00e0 solamente decidere quale metodo di pagamento utilizzare tra carte e mobile wallet (<strong>Apple Pay, Google Pay, Samsung Pay<\/strong>) sul proprio device e attendere pochi secondi fino al completamento della transazione. Nel caso in cui sia richiesto un PIN, l\u2019app visualizzer\u00e0 un PIN PAD dove inserire il dato.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Tutto questo in massima sicurezza: SoftPOS \u00e8 gestita da TAS e <strong>certificata sui pi\u00f9 alti standard di sicurezza <\/strong>delle applicazioni di pagamento.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>L\u2019App \u00e8 disponibile su Google Play Store e <strong>pu\u00f2 essere utilizzata in modalit\u00e0 white label,<\/strong> permettendo il rebranding della soluzione oppure integrandola facilmente con una eventuale App gi\u00e0 in uso da parte dell\u2019esercente.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I prossimi sviluppi prevedono l\u2019estensione dei pagamenti al circuito <strong>Bancomat <\/strong>e, appena possibile, un\u2019analoga versione per <strong>IOS<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:acf\/arrow-link {\"id\":\"block_646cbea195340\",\"name\":\"acf\/arrow-link\",\"data\":{\"link_list_0_link\":{\"title\":\"Scopri di pi\u00f9 sulle nostre soluzione per l\u2019 omnichannel payment acceptance\",\"url\":\"https:\/\/www.tasgroup.eu\/it\/soluzioni\/digital-payments\/omnichannel-payment-solutions\/\",\"target\":\"\"},\"_link_list_0_link\":\"field_arrow_link_link_list_link\",\"link_list\":1,\"_link_list\":\"field_arrow_link_link_list\"},\"align\":\"\",\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/arrow-link {\"id\":\"block_646cbe889533e\",\"name\":\"acf\/arrow-link\",\"data\":{\"link_list\":\"\",\"_link_list\":\"field_arrow_link_link_list\"},\"align\":\"\",\"mode\":\"preview\"} \/--> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/nuove-esperienze-di-pagamento-softpos\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">Aggiornamenti dal mercato USA: il nostro servizio Mastercard NEX continua a migliorare<\/h4> \n              <time class=\"Card__Date\" datetime=\"23-03-2023\" pubdate=\"pubdate\">23 Marzo 2023<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/03\/Mastercard-NEX-TAS-1.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p>Nel 2020 abbiamo introdotto un nuovo servizio per consentire una connettivit\u00e0 immediata a tutti i principali circuiti di carte statunitensi, come <strong>MasterCard<\/strong>, <strong>VISA<\/strong> e di debito, come <strong>Star, NYCE<\/strong> e<strong> Pulse<\/strong>. Questo offre grandi vantaggi sia agli Issuer che agli Acquirer, in quanto consente loro di accettare un&#8217;ampia gamma di pagamenti tradizionali e innovativi in modo semplice, veloce ed efficace, con TAS che funge da aggregatore del traffico di rete verso Mastercard Network Gateway Services (MNGS).<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Mastercard ha rinominato il servizio in <strong>Mastercard Networks <a>Exchange (NEX)<\/a><\/strong>, una piattaforma di routing intelligente che fornisce un\u2019unica connessione alle reti di pagamento globali e regionali, riducendo i costi e le complicazioni della gestione delle singole connessioni. Questo approccio unificato da parte di un partner affidabile per la connettivit\u00e0 pu\u00f2 aiutare a superare la frammentazione dell&#8217;accesso alla rete e creare economie di scala impareggiabili. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Offriamo <strong>NEX in modalit\u00e0 flessibile SaaS disponibile in cloud<\/strong>, garantendo un processo di <em>onboarding<\/em> semplice come servizio autonomo, in grado di interfacciarsi perfettamente con le piattaforme e le applicazioni dei clienti. La soluzione ha dimostrato di essere scalabile e in grado di gestire un volume crescente di traffico di rete.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ulteriori aggiornamenti anche nell&#8217;area issuing dove abbiamo iniziato a fornire il nostro modulo <strong>3D Secure<\/strong> al mercato statunitense. Questo ottimizza l&#8217;esperienza di acquisto dei nostri clienti aumentando le vendite e riducendo le frodi. Il componente 3D Secure consente l&#8217;applicazione dello standard EMVco e garantisce esperienze di autenticazione personalizzate per i titolari di carta durante le transazioni. Oggi, a seguito delle richieste dei nostri clienti, abbiamo ampliato il set di transazioni supportate e fornito ai nostri clienti carte con <strong>chip e PIN conformi allo standard EMVCO.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Per quanto riguarda l&#8217;area Acquiring, stiamo iniziando la collaborazione con un nuovo cliente, una societ\u00e0 Fintech con sede negli Stati Uniti, che si concentra sulla <strong>razionalizzazione dei pagamenti e dei dati per il settore assicurativo<\/strong> fornendo soluzioni e strumenti di pagamento convenienti per promuovere l&#8217;adozione delle compagnie assicurative e la conversione dei clienti. Gestiranno tramite NEX Gateway le transazioni di credito e debito, le carte regalo e l&#8217;e-commerce.\u00a0\u00a0<\/p>\n<!-- \/wp:paragraph --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/aggiornamenti-dal-mercato-usa-il-nostro-servizio-mastercard-nex-continua-a-migliorare\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">fraud management<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">innovation<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">lab<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">TAS<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">TAS Lab, il nostro nuovo dipartimento di ricerca<\/h4> \n              <time class=\"Card__Date\" datetime=\"09-03-2023\" pubdate=\"pubdate\">09 Marzo 2023<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/03\/TAS_Lab-01-1.png\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p><strong>TAS Lab <\/strong>\u00e8 il nuovo dipartimento di TAS che ha l\u2019obiettivo di investire continuativamente sull\u2019innovazione nel settore finanziario. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>TAS Lab ha come scopo quello di progettare soluzioni tecnologicamente avanzate che migliorino il modo in cui le persone usufruiscono dei servizi finanziari, ideando prodotti innovativi per fornire a banche e aziende un vantaggio competitivo sul mercato.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Attualmente il dipartimento si concentra su tre aree di ricerca principali: il quantum computing per la prevenzione delle frodi nei pagamenti, lo sviluppo di un nuovo modello phygital di filiale bancaria (TAS Remote Teller) e le applicazioni dell\u2019intelligenza artificiale al mondo dei pagamenti.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Il <strong>quantum computing<\/strong> \u00e8 una tecnologia emergente che promette di rivoluzionare il modo in cui vengono gestiti i dati e le transazioni finanziarie. TAS Lab, <a href=\"https:\/\/www.pagamentidigitali.it\/payment-innovation\/tas-e-universita-di-verona-il-quantum-computing-arriva-nel-fraud-detection\/\" target=\"_blank\" rel=\"noreferrer noopener\">insieme all\u2019 Universit\u00e0 di Verona<\/a>, sta sfruttando questa tecnologia su casi d\u2019uso concreti per sviluppare <a href=\"https:\/\/www.tasgroup.eu\/it\/soluzioni\/digital-payments\/fraud-management-solution\/\" data-type=\"page\" data-id=\"43\">soluzioni avanzate per la prevenzione delle frodi <\/a>nei pagamenti, che <strong>consentano alle banche e agli istituti finanziari di gestire in modo sempre pi\u00f9 sicuro ed efficiente le loro transazioni<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La filiale bancaria phygital, ovvero il <a href=\"https:\/\/www.tasgroup.eu\/it\/soluzioni\/digital-payments\/branch-transformation\/\" data-type=\"page\" data-id=\"37\">TAS Remote Teller<\/a>, rappresenta una nuova frontiera nel settore bancario, che combina i vantaggi della presenza fisica con la comodit\u00e0 della tecnologia digitale. TAS Lab sta esplorando come questa tecnologia possa essere utilizzata per <strong>migliorare l&#8217;esperienza bancaria dei clienti<\/strong>, garantendo la presenza fisica sul territorio di filiali snelle con un\u2019assistenza virtuale che permetta all\u2019utente di effettuare tutte le operazioni bancarie di una filiale tradizionale in modo semplice e veloce.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Infine, TAS Lab sta investendo nell&#8217;intelligenza artificiale, sviluppando<strong> algoritmi avanzati e tecnologie di machine learning per migliorare la gestione dei dati e delle transazioni finanziarie<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Se sei un ente di ricerca, un&#8217;azienda o una persona fisica appassionata di tecnologia e innovazione e sei interessata a collaborare con TAS Lab, ti invitiamo a contattarci per sottoporre la tua idea. Il dipartimento \u00e8 sempre alla ricerca di nuovi progetti e soluzioni. Contattaci per scoprire come possiamo collaborare per creare insieme il futuro dei servizi finanziari.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Puoi scriverci all\u2019indirizzo <a href=\"mailto:solutions@tasgroup.eu\">solutions@tasgroup.eu<\/a><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Per scrivere questo articolo abbiamo usato l\u2019intelligenza artificiale di Chat GPT, partendo dalle nostre idee \ud83d\udca1.<\/p>\n<!-- \/wp:paragraph --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/tas-lab\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">PSD2<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">Come l\u2019embedded finance migliora la vita delle aziende e dei consumatori<\/h4> \n              <time class=\"Card__Date\" datetime=\"21-02-2023\" pubdate=\"pubdate\">21 Febbraio 2023<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/02\/embedded-finance-IT.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p>Il fintech sta diventando sempre pi\u00f9 pervasivo e in questi ultimi anni sono nate diverse offerte innovative volte a raggiungere target di mercato differenti. La <strong><em>finanza incorporata<\/em> (embedded finance), permette ai consumatori che utilizzano prodotti non finanziari di accedere, attraverso questi, a servizi bancari integrati, migliorando cos\u00ec la loro esperienza d&#8217;acquisto<\/strong>. I prodotti finanziari, tradizionalmente offerti dalle banche, diventano cos\u00ec parte dell\u2019esperienza digitale del cliente in un\u2019unica piattaforma che ne semplifica la fruizione.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un&#8217;azienda che fornisce servizi non finanziari, come ad esempio un sito di shopping online, pu\u00f2 quindi offrire un\u2019esperienza completa al cliente accelerandone il processo d\u2019acquisto e migliorandone la sua percezione complessiva.&nbsp;Questo tipo di modello si presta a molteplici casi d\u2019uso in diversi settori, dai fitness club, al gaming, alle organizzazioni non profit, all&#8217;assistenza sanitaria.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Secondo un recente studio di Bain &amp; Company, le transazioni tramite servizi finanziari incorporati negli Stati Uniti hanno raggiunto 2,6 trilioni di dollari nel 2021. Si prevede che questa cifra salir\u00e0 a 7 trilioni di dollari entro il 2026. Questo mostra come i clienti stanno cambiando il modo in cui interagiscono con le loro finanze e come mutano le loro esperienze come clienti.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><strong>Tipi di embedded finance<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>La maggior parte degli sviluppi di embedded finance riguardano prodotti come depositi, pagamenti, emissioni di carte, prestiti e assicurazioni.&nbsp;Queste offerte consentono di creare una facile integrazione con l\u2019esperienza del consumatore e di sviluppare semplicemente nuovi casi d&#8217;uso.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Embedded Banking<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Con l&#8217;embedded banking, noto come&nbsp;<strong>Banking-as-a-Service<\/strong>, le societ\u00e0 non finanziarie possono offrire ai propri utenti un conto virtuale o IBAN per detenere fondi ed effettuare pagamenti.&nbsp;L\u2019embedded banking in genere ha pi\u00f9 senso per venditori o fornitori di servizi che utilizzano la piattaforma di un&#8217;azienda per il proprio business.&nbsp;Spesso \u00e8 anche la base per offrire ulteriori prodotti finanziari incorporati come pagamenti, carte e prestiti.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ad esempio, un acquirer pu\u00f2 liquidare il merchant sui propri conti bancari, consentendogli di utilizzare i fondi depositati per coprire le spese relative alle forniture.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Embedded Payment<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Avere fisicamente una carta di debito o di credito, inserire il PIN, utilizzare la carta sono tutti aspetti in grado di indurre i consumatori ad abbandonare un acquisto digitale se la loro carta non \u00e8 a portata di mano.&nbsp;Con i pagamenti integrati (embedded payments), invece, non essendo richiesta alcuna carta fisica, tale problematica viene risolta grazie a esperienze di pagamento frictionless.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un esempio \u00e8 l&#8217;esperienza di pagamento del taxi Uber in cui l&#8217;app memorizza i dati della carta e i pagamenti vengono effettuati senza problemi quando si prenota un taxi.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>I pagamenti integrati non sono limitati solo alle carte, ma possono anche offrire ai consumatori la possibilit\u00e0 di pagare direttamente dai loro conti bancari<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un&#8217;interessante indagine condotta da IDC a livello globale ha rivelato che entro il 2030 il 74% dei pagamenti digitali dei consumatori verr\u00e0 effettuato con piattaforme offerte da istituzioni non finanziarie.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Embedded Card Issuing<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Le carte di debito e di credito legate a un brand esistono da diverso tempo.&nbsp;Nell&#8217;ambito della finanza incorporata, i casi d&#8217;uso per l&#8217;utilizzo delle carte al di fuori dei tradizionali pagamenti al dettaglio sono illimitati.&nbsp;Ad esempio, nel B2B oggi le applicazioni di gestione delle spese sono in grado di emettere carte T&amp;E virtuali una tantum e sono in grado di eseguire migliori controlli sulle spese per evitare che i membri del personale utilizzino le carte aziendali fisiche per uso privato.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Embedded Lending<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>In passato il prestito di denaro veniva effettuato tramite carte di credito o attraverso prestiti tradizionali concessi da un istituto finanziario.&nbsp;L&#8217;ascesa di nuovi attori nel settore fintech ha portato a una crescita significativa nell&#8217;area del credito.&nbsp;Negli ultimi anni, si sono moltiplicate le piattaforme BNPL (Buy Now Pay Later) come Klarna e Afterpay che offrono ai consumatori nuove opportunit\u00e0 per accedere facilmente ai fondi quando acquistano beni e servizi.&nbsp;Il rapporto di Bain &amp; Company stima che entro il 2026 la dimensione del mercato indotto dalle piattaforme BNPL raggiunger\u00e0 i 265 miliardi di dollari.&nbsp;La ricerca mostra anche come i clienti siano inclini a spendere leggermente di pi\u00f9 quando utilizzano le piattaforme BNPL, aumentando i tassi di conversione e i ricavi.&nbsp;Grazie a nuove tecnologie accessibili e semplici, la finanza integrata nei prestiti sta diventando una parte significativa del modo in cui consumatori e imprese accedono ai finanziamenti.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Embedded Insurance<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Il continuo aumento dei dati raccolti in tutti i campi impatta anche il mercato assicurativo che ha la possibilit\u00e0 di raccogliere maggiori informazioni da utilizzare per offrire polizze su misura e pi\u00f9 competitive.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I programmi assicurativi incorporati (embedded insurance) differiscono dalle assicurazioni tradizionali perch\u00e9 eliminano l&#8217;agente assicurativo o il broker, ad esempio quando si acquista una nuova auto o quando si utilizzano metodi di pagamento tradizionali.&nbsp;Le nuove piattaforme digitali&nbsp;<strong>consentono alle compagnie assicurative tradizionali di gestire attivit\u00e0 lunghe e laboriose come le registrazioni dei sinistri offrendo una migliore customer experience grazie a piattaforme tecnologiche avanzate<\/strong>.&nbsp;Anche al di fuori delle assicurazioni, nuovi attori utilizzano la finanza incorporata per approfondire le relazioni con i clienti e fidelizzarli.&nbsp;Un esempio \u00e8 offerto da Tesla, che offre polizze assicurative competitive per l&#8217;acquisto di una nuova auto, integrando anche questo aspetto nel processo d\u2019acquisto.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Come dovrebbe essere una piattaforma di embedded finance<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Le piattaforme finanziarie integrate&nbsp;<strong>migliorano l&#8217;esperienza del cliente, il percorso d\u2019acquisto e la progettazione delle piattaforme non finanziarie<\/strong>.&nbsp;Ci\u00f2 \u00e8 reso possibile grazie a un ecosistema fatto di partnership tra banche, fornitori di tecnologia e distributori di prodotti finanziari.&nbsp;I clienti e le aziende che utilizzano queste interfacce possono facilmente integrare il proprio software grazie all\u2019utilizzo di API e beneficiare di elevati livelli di flessibilit\u00e0 e configurabilit\u00e0.&nbsp;Inoltre, l&#8217;offerta di finanza incorporata di una piattaforma include anche&nbsp;<strong>micro-servizi scalabili e affidabili, configurazioni flessibili del flusso di lavoro e dashboard personalizzate e centralizzate<\/strong>&nbsp;che consentono alle aziende una maggiore dinamicit\u00e0 e un time-to-market pi\u00f9 breve.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>TAS Global Payment Platform (GPP): come dovrebbe essere una piattaforma di embedded finance<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Moltissime istituzioni finanziarie hanno scelto <a href=\"https:\/\/www.tasgroup.eu\/it\/global-payment-platform\/\"><strong>TAS Global Payment Platform (GPP)<\/strong><\/a><strong>\u00a0<\/strong>per fornire ai propri clienti una migliore esperienza di pagamento e consentire un time-to-market pi\u00f9 rapido.\u00a0La piattaforma GPP \u00e8 adatta a\u00a0<strong>qualsiasi operatore dell&#8217;ecosistema sia esso una banca, un provider di tecnologia o un distributore di prodotti finanziari per garantire ai clienti esperienze di fruizione e acquisto eccellenti e senza interruzioni<\/strong>. Collaboriamo con aziende nei settori del digital banking, del BNPL, delle assicurazioni, dei viaggi e dei pagamenti grazie a una piattaforma altamente configurabile con API aperte.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La nostra offerta per l\u2019embedded finance include microservizi scalabili e affidabili, configurazioni flessibili del flusso di lavoro e una dashboard personalizzata centralizzata che consente alle aziende una maggiore dinamicit\u00e0.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><a href=\"https:\/\/www.tasgroup.eu\/it\/contatti\/\" data-type=\"page\" data-id=\"28\">Contattaci per scoprire come possiamo aiutarti a sfruttare tutti i vantaggi dell\u2019embedded finance.<\/a><\/p>\n<!-- \/wp:paragraph --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/come-lembedded-finance-migliora-la-vita-delle-aziende-e-dei-consumatori\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">digital treasury<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">TAS<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">TAS pronta a crescere ancora<\/h4> \n              <time class=\"Card__Date\" datetime=\"17-01-2023\" pubdate=\"pubdate\">17 Gennaio 2023<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/02\/Intervista_Bancaforte.png\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p>L\u2019ingresso del Fondo Rivean Capital ha aperto nuove prospettive di crescita per&nbsp;<strong>TAS<\/strong>. E non solo in Italia, dove negli ultimi mesi la societ\u00e0 ha avviato un\u2019aggressiva campagna di acquisizioni, ma anche a livello internazionale, per rafforzare e ampliare la sua gi\u00e0 significativa presenza in Paesi chiave. Il 2023 sar\u00e0 dunque un anno di grandi sfide per la societ\u00e0 guidata dal&nbsp;<strong>CEO Valentino Bravi<\/strong>, tra cui \u2013 anticipa a Bancaforte \u2013 anche \u201c<strong>l\u2019ingresso nel mercato del back office titoli<\/strong>\u201d, dopo aver potenziato l\u2019offerta nel settore del&nbsp;<strong>capital market<\/strong>&nbsp;e aver riscosso un importante successo nell\u2019area della&nbsp;<strong>Liquidity<\/strong>. TAS \u00e8 infatti uno dei principali protagonisti di&nbsp;<strong>T2-T2S Consolidation<\/strong>, secondo BCE \u201ctra i pi\u00f9 complessi progetti mai affrontati dalle banche\u201d, avendo avuto la fiducia per questa complessa trasformazione da parte di una percentuale altissima delle banche italiane.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Il cambio di governance realizzato nel 2022 non modificher\u00e0 per\u00f2 la focalizzazione sui pagamenti che contraddistingue TAS da 40 anni. E, a questo proposito, proseguono gli investimenti per sviluppare ulteriormente la&nbsp;<strong>Global Payment Platform<\/strong>, un asset al momento unico sul mercato.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ne parlano, nella <a href=\"https:\/\/bancaforte.it\/video\/tas-pronta-a-crescere-ancora-RB101347x\">videointervista rilasciata a Bancaforte <\/a>in occasione del Salone dei Pagamenti, oltre al Chief Executive Officer Valentino Bravi, il COO International Business\u00a0<strong>Andrew Quartermaine<\/strong>\u00a0e il CEO Global Payments Solutions\u00a0<strong>Massimiliano Quattrocchi<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><a href=\"https:\/\/bancaforte.it\/video\/tas-pronta-a-crescere-ancora-RB101347x\">Guarda la videointervista<\/a><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:acf\/bottone {\"id\":\"block_63ef4b67b5640\",\"name\":\"acf\/bottone\",\"data\":{\"link\":\"\",\"_link\":\"field_bottone_link\",\"class\":\"Default\",\"_class\":\"field_bottone_class\",\"gradient\":\"0\",\"_gradient\":\"field_bottone_gradient\"},\"align\":\"\",\"mode\":\"preview\",\"align_content\":\"top\"} \/--> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/tas-pronta-a-crescere-ancora\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>\n  <\/div>\n  <div class=\"Swiper__Scrollbar swiper-scrollbar js-Swiper-Scrollbar\"><\/div>\n<\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_26d08c-03 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id11529_26d08c-03 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id11529_26d08c-03 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:3rem;padding-bottom:5rem;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_26d08c-03 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id11529_26d08c-03 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11529_26d08c-03 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_26d08c-03 alignfull has-violet-to-orange-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"soluzioni\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column11529_1df2fb-40 > .kt-inside-inner-col,.kadence-column11529_1df2fb-40 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_1df2fb-40 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_1df2fb-40 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_1df2fb-40 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_1df2fb-40 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_1df2fb-40{text-align:center;}.kadence-column11529_1df2fb-40{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_1df2fb-40 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_1df2fb-40 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_1df2fb-40 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color\">Scopri le nostre soluzioni per<\/h2>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:100%;margin-left:auto;margin-right:auto;padding-top:5rem;padding-bottom:5rem;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id11529_94d9bc-07 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id11529_94d9bc-07 ,.kb-row-layout-id11529_94d9bc-07 h1,.kb-row-layout-id11529_94d9bc-07 h2,.kb-row-layout-id11529_94d9bc-07 h3,.kb-row-layout-id11529_94d9bc-07 h4,.kb-row-layout-id11529_94d9bc-07 h5,.kb-row-layout-id11529_94d9bc-07 h6{color:#ffffff;}.kb-row-layout-id11529_94d9bc-07 .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id11529_94d9bc-07 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id11529_94d9bc-07 .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px){.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap{padding-top:3rem;padding-bottom:3rem;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1){order:2;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2){order:1;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3){order:12;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4){order:11;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5){order:22;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6){order:21;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7){order:32;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8){order:31;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_94d9bc-07 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id11529_94d9bc-07 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap{padding-top:3rem;padding-bottom:3rem;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1){order:2;}.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2){order:1;}.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3){order:12;}.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4){order:11;}.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5){order:22;}.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6){order:21;}.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7){order:32;}.kb-row-layout-id11529_94d9bc-07 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8){order:31;}.kb-row-layout-id11529_94d9bc-07 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id11529_94d9bc-07 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11529_94d9bc-07 alignfull has-blue-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"contact-us\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column11529_1eef13-c4 > .kt-inside-inner-col,.kadence-column11529_1eef13-c4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_1eef13-c4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_1eef13-c4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_1eef13-c4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_1eef13-c4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_1eef13-c4{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_1eef13-c4 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_1eef13-c4 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_1eef13-c4 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-white-color has-text-color\">Contact us<\/h2>\n\n\n\n<p class=\"has-white-color has-text-color\">Get in touch to discover how we can help in achieving your business goals<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n\t\t\t\t\t<script>\n\t\t\t\t\t\twindow.hsFormsOnReady = window.hsFormsOnReady || [];\n\t\t\t\t\t\twindow.hsFormsOnReady.push(()=>{\n\t\t\t\t\t\t\thbspt.forms.create({\n\t\t\t\t\t\t\t\tportalId: 8858273,\n\t\t\t\t\t\t\t\tformId: \"a9ba38cb-a889-4c9c-899b-c6bfe110ae7c\",\n\t\t\t\t\t\t\t\ttarget: \"#hbspt-form-1788331535000-9025818092\",\n\t\t\t\t\t\t\t\tregion: \"na1\",\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t})});\n\t\t\t\t\t<\/script>\n\t\t\t\t\t<div class=\"hbspt-form\" id=\"hbspt-form-1788331535000-9025818092\"><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column11529_bd4487-88 > .kt-inside-inner-col,.kadence-column11529_bd4487-88 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11529_bd4487-88 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11529_bd4487-88 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11529_bd4487-88 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11529_bd4487-88 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11529_bd4487-88{position:relative;}@media all and (max-width: 1024px){.kadence-column11529_bd4487-88 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column11529_bd4487-88 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11529_bd4487-88 kvs-md-false kvs-sm-false inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-lottie-container_034dbc-80 dotlottie-player{max-width:auto;}<\/style>\n<div class=\"kb-lottie-container kb-lottie-container_034dbc-80\"><lottie-player loop speed=\"1\" autoplay mode=\"normal\" id=\"kb-lottie-player_034dbc-80\" src=\"\/app\/uploads\/2022\/09\/animazione-2-20220921.json\" style=\"max-width:auto;height:auto;margin:0 auto\"><\/lottie-player><\/div>\n<div class=\"kb-lottie-container kb-lottie-container_034dbc-80\"><dotlottie-player loop=\"true\" speed=\"1\" autoplay=\"true\" mode=\"normal\" src=\"\/app\/uploads\/2022\/09\/animazione-2-20220921.json\"\n\t\t\t\t\t\t\tid=\"kb-lottie-player_034dbc-80\"\n\t\t\t\t\t\t><\/dotlottie-player><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Advanced Multi-Asset Back Office Management: Digitalization and Innovation BOSS \u2013 La piattaforma modulare per il back office finanziario Back office moderno. Multi-asset. Completamente integrato. Pronto per il futuro. BOSS (Back Office Securities Solution) \u00e8 la piattaforma di nuova generazione di TASper l\u2019amministrazione titoli e il post-trade. Basata su Open API, microservizi e architettura cloud-ready, BOSS &hellip; <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/soluzioni\/capital-markets\/back-office-finanza\/\">Continued<\/a><\/p>\n","protected":false},"author":17,"featured_media":0,"parent":11517,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-full.blade.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-11529","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/pages\/11529"}],"collection":[{"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/comments?post=11529"}],"version-history":[{"count":17,"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/pages\/11529\/revisions"}],"predecessor-version":[{"id":11935,"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/pages\/11529\/revisions\/11935"}],"up":[{"embeddable":true,"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/pages\/11517"}],"wp:attachment":[{"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/media?parent=11529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}