{"id":63,"date":"2022-07-14T07:21:10","date_gmt":"2022-07-14T07:21:10","guid":{"rendered":"https:\/\/tasgroup.test\/?page_id=63"},"modified":"2023-01-05T10:56:44","modified_gmt":"2023-01-05T10:56:44","slug":"pagamenti-conformi-psd2","status":"publish","type":"page","link":"https:\/\/tasgroup.jumpgroup.it\/it\/soluzioni\/psd2\/pagamenti-conformi-psd2\/","title":{"rendered":"Open Banking and Embedded Finance"},"content":{"rendered":"<style>#kt-layout-id_bf4a46-99 > .kt-row-column-wrap{align-content:center;}:where(#kt-layout-id_bf4a46-99 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}#kt-layout-id_bf4a46-99 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:5rem;padding-bottom:5rem;grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}#kt-layout-id_bf4a46-99 > .kt-row-layout-overlay{opacity:0.30;}#kt-layout-id_bf4a46-99 ,#kt-layout-id_bf4a46-99 h1,#kt-layout-id_bf4a46-99 h2,#kt-layout-id_bf4a46-99 h3,#kt-layout-id_bf4a46-99 h4,#kt-layout-id_bf4a46-99 h5,#kt-layout-id_bf4a46-99 h6{color:#ffffff;}@media all and (max-width: 1024px){#kt-layout-id_bf4a46-99 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){#kt-layout-id_bf4a46-99 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignfull\" id=\"intro-branch-transformation\"><div id=\"kt-layout-id_bf4a46-99\" class=\"kt-row-layout-inner kt-row-has-bg kt-layout-id_bf4a46-99 has-blue-background-color\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-gutter-default kt-v-gutter-default kt-row-valign-middle kt-row-layout-left-golden kt-tab-layout-equal kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_682e65-58 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_682e65-58 > .kt-inside-inner-col,.kadence-column_682e65-58 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_682e65-58 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_682e65-58 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_682e65-58 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_682e65-58 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_682e65-58{position:relative;}@media all and (max-width: 1024px){.kadence-column_682e65-58 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_682e65-58 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_682e65-58\"><div class=\"kt-inside-inner-col\">\n<h1 class=\"has-text-align-left has-white-color has-text-color wp-block-heading\">Pagamenti Conformi alla PSD2: una piattaforma Open API<\/h1>\n\n\n\n<p>La <strong>Payment Service Directive<\/strong>, voluta dalla Commissione Europea per accelerare l\u2019innovazione, ha imposto alle Banche di aprirsi per consentire l\u2019entrata di nuovi intermediari di servizi di pagamento.<\/p>\n\n\n\n<p>La direttiva dei servizi di pagamento rappresenta un\u2019opportunit\u00e0 per tutti gli operatori, sia quelli tradizionali del mondo bancario, le nuove Fintech ed i Big Tech, ma anche operatori di altri settori: Assicurazioni, GDO, Multiutility, Oil &amp; Gas, e-commerce, mobilit\u00e0.<\/p>\n\n\n\n<p>Trasformandosi in un <strong>IMEL<\/strong>, una Payment Institution o una terza parte accreditata (TPP) si pu\u00f2 garantire ai propri clienti customer experience semplificate e fidelizzanti, risparmiando sui costi di gestione degli incassi ed efficientando i processi interni di amministrazione e tesoreria.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column_c0ac31-75 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_c0ac31-75 > .kt-inside-inner-col,.kadence-column_c0ac31-75 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_c0ac31-75 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_c0ac31-75 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_c0ac31-75 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_c0ac31-75 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_c0ac31-75{position:relative;}@media all and (max-width: 1024px){.kadence-column_c0ac31-75 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_c0ac31-75 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-2 kadence-column_c0ac31-75 animated fadeInDown\"><div class=\"kt-inside-inner-col\"><div class=\"CardBlock CardBlock--Right\">\n  <div class=\"Card Card--Gradient\">\n    <div class=\"Card__Wrapper Card__Wrapper--Center\">\n              <h4 class=\"Card__Title\">Desideri una consulenza personalizzata?<\/h4>\n            \n              <a href=\"\/it\/contatti\/\" class=\"Button Button--Default\" target=\"_self\">\n    Contattaci\n<\/a>          <\/div>\n  <\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_d845e9-90 > .kt-row-column-wrap{align-content:start;}:where(#kt-layout-id_d845e9-90 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}#kt-layout-id_d845e9-90 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:0px;padding-bottom:30px;padding-left:0px;padding-right:0px;grid-template-columns:minmax(0, 1fr);}#kt-layout-id_d845e9-90 > .kt-row-layout-overlay{opacity:0.30;}#kt-layout-id_d845e9-90 .kt-row-layout-bottom-sep{height:30px;}#kt-layout-id_d845e9-90 .kt-row-layout-bottom-sep svg{width:100%;}#kt-layout-id_d845e9-90 .kt-row-layout-bottom-sep svg{fill:linear-gradient(270deg, rgb(243,150,0) 1.73%, rgb(160,50,243) 96.01%)!important;}@media all and (max-width: 1024px){#kt-layout-id_d845e9-90 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){#kt-layout-id_d845e9-90 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){#kt-layout-id_d845e9-90 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){#kt-layout-id_d845e9-90 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}#kt-layout-id_d845e9-90 .kt-row-layout-bottom-sep{height:px;}#kt-layout-id_d845e9-90 .kt-row-layout-bottom-sep svg{width:%;}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignnone\" id=\"divider\"><div id=\"kt-layout-id_d845e9-90\" class=\"kt-row-layout-inner kt-row-has-bg kt-layout-id_d845e9-90 has-violet-to-orange-background-color\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_1eb65d-de > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_1eb65d-de > .kt-inside-inner-col,.kadence-column_1eb65d-de > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_1eb65d-de > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_1eb65d-de > .kt-inside-inner-col{flex-direction:column;}.kadence-column_1eb65d-de > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_1eb65d-de > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_1eb65d-de{position:relative;}@media all and (max-width: 1024px){.kadence-column_1eb65d-de > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_1eb65d-de > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_1eb65d-de\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_ebb767-6d > .kt-row-column-wrap{align-content:start;}:where(#kt-layout-id_ebb767-6d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}#kt-layout-id_ebb767-6d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;grid-template-columns:minmax(0, 1fr);}#kt-layout-id_ebb767-6d > .kt-row-layout-overlay{opacity:0.30;}#kt-layout-id_ebb767-6d ,#kt-layout-id_ebb767-6d h1,#kt-layout-id_ebb767-6d h2,#kt-layout-id_ebb767-6d h3,#kt-layout-id_ebb767-6d h4,#kt-layout-id_ebb767-6d h5,#kt-layout-id_ebb767-6d h6{color:#ffffff;}@media all and (max-width: 1024px){#kt-layout-id_ebb767-6d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){#kt-layout-id_ebb767-6d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignfull bubbleBlur bubbleBlur--BottomRight\" id=\"ti-aiutiamo-a-riposizionarti\"><div id=\"kt-layout-id_ebb767-6d\" class=\"kt-row-layout-inner kt-layout-id_ebb767-6d\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_013eff-50 > .kt-inside-inner-col{padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}.kadence-column_013eff-50 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_013eff-50 > .kt-inside-inner-col,.kadence-column_013eff-50 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_013eff-50 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_013eff-50 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_013eff-50 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_013eff-50 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_013eff-50{position:relative;}@media all and (max-width: 1024px){.kadence-column_013eff-50 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_013eff-50 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_013eff-50\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-media-text alignfull is-stacked-on-mobile is-style-jmp-media-text has-blue-background-color has-background\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"701\" src=\"https:\/\/www.tasgroup.eu\/app\/uploads\/sites\/2\/2023\/01\/PSD2-IT.png\" alt=\"Soluzioni per la PSD2\" class=\"wp-image-10192 size-full\" srcset=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/01\/PSD2-IT.png 960w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/01\/PSD2-IT-300x219.png 300w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/01\/PSD2-IT-768x561.png 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h2 class=\"has-white-color has-text-color wp-block-heading\">Ti aiutiamo a riposizionarti nel nuovo ecosistema<\/h2>\n\n\n\n<p>Oltre il 90% delle transazioni PSD2 in Italia sono basate su componenti della nostra <strong>Global Payment Platform<\/strong> (<strong>GPP<\/strong>).&nbsp; Siamo un soggetto totalmente indipendente e, a differenza di altri provider di servizi PSD2, non in competizione con i clienti.&nbsp;<\/p>\n\n\n\n<p>La nostra GPP include il 100% dei moduli, dei livelli e dell&#8217;integrazione necessari per le operazioni di una IMEL, di un IP, PISP o AISP. \u00c8 una piattaforma fortemente modulare e personalizzabile, offerta anche a servizio.<\/p>\n\n\n\n<p>La natura deliberatamente \u201c<strong>technology-neutral<\/strong>\u201d del regolamento PSD2 ha favorito il proliferare di standard e \u201cdialetti\u201d nel dialogo tra Banche e Terze Parti, ma con noi puoi contare su<strong> una piattaforma che garantisce l\u2019interoperabilit\u00e0<\/strong>&nbsp;delle Open API adottate dalle Banche e la semplicit\u00e0 di integrazione di nuovi servizi.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"ButtonList wp-block-lista-bottoni ButtonList--Left\">\n          <a href=\"https:\/\/www.tasgroup.eu\/it\/soluzioni\/psd2\/pagamenti-conformi-psd2\/#contact-us\" class=\"Button Button--Default Button--HoverGradient\" target=\"_self\">\n    Contatta il nostro Competence Center PSD2\n<\/a>      <\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_11082c-e9 > .kt-row-column-wrap{align-content:start;}:where(#kt-layout-id_11082c-e9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}#kt-layout-id_11082c-e9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;grid-template-columns:minmax(0, 1fr);}#kt-layout-id_11082c-e9 > .kt-row-layout-overlay{opacity:0.30;}#kt-layout-id_11082c-e9 ,#kt-layout-id_11082c-e9 h1,#kt-layout-id_11082c-e9 h2,#kt-layout-id_11082c-e9 h3,#kt-layout-id_11082c-e9 h4,#kt-layout-id_11082c-e9 h5,#kt-layout-id_11082c-e9 h6{color:#ffffff;}@media all and (max-width: 1024px){#kt-layout-id_11082c-e9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){#kt-layout-id_11082c-e9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignfull bubbleBlur bubbleBlur--TopLeft\" id=\"grazie-alla-psd2-list\"><div id=\"kt-layout-id_11082c-e9\" class=\"kt-row-layout-inner kt-layout-id_11082c-e9\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_4f3e89-75 > .kt-inside-inner-col{padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}.kadence-column_4f3e89-75 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_4f3e89-75 > .kt-inside-inner-col,.kadence-column_4f3e89-75 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_4f3e89-75 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_4f3e89-75 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_4f3e89-75 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_4f3e89-75 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_4f3e89-75{position:relative;}@media all and (max-width: 1024px){.kadence-column_4f3e89-75 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_4f3e89-75 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_4f3e89-75\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-media-text alignfull has-media-on-the-right is-stacked-on-mobile is-style-jmp-media-text has-blue-background-color has-background\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"454\" src=\"https:\/\/www.tasgroup.eu\/app\/uploads\/sites\/2\/2023\/01\/PSD2-open-banking-IT.jpg\" alt=\"Soluzioni per la PSD2 ed Open banking\" class=\"wp-image-10193 size-full\" srcset=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/01\/PSD2-open-banking-IT.jpg 1024w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/01\/PSD2-open-banking-IT-300x133.jpg 300w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/01\/PSD2-open-banking-IT-768x341.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Grazie alla PSD2, oggi puoi lanciare il<strong> tuo sistema di pagamento<\/strong>, ottenendo rilevanti risparmi sui tuoi acquisti di beni e servizi e attivando nuove revenue stream dalle spese dei tuoi clienti presso altri esercizi commerciali, guadagnando visibilit\u00e0 sulle loro abitudini di spesa e fidelizzandoli con nuove proposte su misura.<\/p>\n\n\n\n<p>Ti mettiamo a disposizione:<\/p>\n\n\n<ul class=\"CheckmarkList wp-block-checkmark-list\">\n          <li class=\"CheckmarkList__Item\"><p><strong>Consulenza specializzata<\/strong> sui temi della normativa<\/p>\n<\/li>\n          <li class=\"CheckmarkList__Item\"><p><strong>Esperienza<\/strong> e centralit\u00e0 di ruolo nell\u2019ecosistema Banche-Fintech-Regulator<\/p>\n<\/li>\n          <li class=\"CheckmarkList__Item\"><p>Middleware \u201c<strong>standard like<\/strong>\u201d volto ad armonizzare e standardizzare le interfacce di colloquio TPP-ASPSP<\/p>\n<\/li>\n          <li class=\"CheckmarkList__Item\"><p><strong>Sandbox<\/strong> per facilitare l\u2019integrazione dei TPP con i PSP<\/p>\n<\/li>\n          <li class=\"CheckmarkList__Item\"><p><strong>Copertura end-to-end<\/strong> dei processi di onboarding e del pagamento in multicanalit\u00e0<\/p>\n<\/li>\n      <\/ul>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_e23ed8-10 > .kt-row-column-wrap{align-content:start;}:where(#kt-layout-id_e23ed8-10 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}#kt-layout-id_e23ed8-10 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:80%;margin-left:auto;margin-right:auto;padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:5rem;padding-bottom:5rem;grid-template-columns:minmax(0, 1fr);}#kt-layout-id_e23ed8-10 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){#kt-layout-id_e23ed8-10 > .kt-row-column-wrap{max-width:90%;margin-left:auto;margin-right:auto;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){#kt-layout-id_e23ed8-10 > .kt-row-column-wrap{max-width:100%;margin-left:auto;margin-right:auto;grid-template-columns:minmax(0, 1fr);}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignfull\" id=\"soluzione-in-evidenza\"><div id=\"kt-layout-id_e23ed8-10\" class=\"kt-row-layout-inner kt-row-has-bg kt-layout-id_e23ed8-10 has-blue-background-color\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_e203bf-b6 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_e203bf-b6 > .kt-inside-inner-col,.kadence-column_e203bf-b6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_e203bf-b6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_e203bf-b6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_e203bf-b6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_e203bf-b6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_e203bf-b6{text-align:center;}.kadence-column_e203bf-b6{position:relative;}@media all and (max-width: 1024px){.kadence-column_e203bf-b6 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_e203bf-b6 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_e203bf-b6\"><div class=\"kt-inside-inner-col\"><div class=\"CardBlock CardBlock--Center\">\n  <div class=\"Card Card--Wide\">\n    <div class=\"Card__Wrapper Card__Wrapper--Left\">\n              <h4 class=\"Card__Title\">Gestisci in modo snello l\u2019operativit\u00e0 della clientela con il nostro Light Core Banking per IMEL<\/h4>\n                    <div class=\"Card__Content\"> \n          <p>Per i nuovi operatori che vogliono affacciarsi sul mondo dei pagamenti innovativi abbiamo realizzato dei componenti che agevolano la gestione della clientela.<\/p>\n<ul>\n<li><strong>Anagrafe<\/strong>: modulo multi-PSP che consente il censimento e la gestione dei clienti finali e dei relativi canali di interazione abilitati. Prevede funzioni di inserimento, ricerca, modifica e cancellazione sia per persone giuridiche che per persone fisiche.<\/li>\n<li><strong>Condizioniere<\/strong>: permette di gestire la configurazione e la consultazione di commissioni e condizioni applicabili alla clientela, di raggrupparle in \u201cfeeset\u201d, e di configurarne le relative regole di applicazione con esecuzione real-time o a frequenza periodica<\/li>\n<li>G<strong>estione conti di pagamento<\/strong>: gestisce configurazioni di conti di tipo business, retail o conti tecnici, offrendo funzioni per configurare strutture complesse e implementare pool di conti organizzati gerarchicamente con conti master e conti slave in relazione tra loro; permette anche di configurare meccanismi automatici di cash pooling.<\/li>\n<\/ul>\n\n        <\/div>\n      \n          <\/div>\n  <\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_f118c1-84 > .kt-row-column-wrap{align-content:start;}:where(#kt-layout-id_f118c1-84 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}#kt-layout-id_f118c1-84 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:2.5rem;padding-bottom:5rem;grid-template-columns:minmax(0, 1fr);}#kt-layout-id_f118c1-84 > .kt-row-layout-overlay{opacity:1;background-image:linear-gradient(180deg, #07112c 50%, #00000000 50%);mix-blend-mode:normal;}@media all and (max-width: 1024px){#kt-layout-id_f118c1-84 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){#kt-layout-id_f118c1-84 > .kt-row-column-wrap{padding-bottom:3rem;grid-template-columns:minmax(0, 1fr);}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignfull\" id=\"carosello-modali\"><div id=\"kt-layout-id_f118c1-84\" class=\"kt-row-layout-inner kt-row-has-bg kt-layout-id_f118c1-84 has-violet-to-orange-background-color\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_1835ab-fc > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_1835ab-fc > .kt-inside-inner-col,.kadence-column_1835ab-fc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_1835ab-fc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_1835ab-fc > .kt-inside-inner-col{flex-direction:column;}.kadence-column_1835ab-fc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_1835ab-fc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_1835ab-fc{text-align:left;}.kadence-column_1835ab-fc{position:relative;}@media all and (max-width: 1024px){.kadence-column_1835ab-fc > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_1835ab-fc > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_1835ab-fc\"><div class=\"kt-inside-inner-col\">\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"CarouselsWithModal js-carouselsWithModal\">\n        <div id=\"swiper-carousel-i46NY\" class=\"Swiper swiper Swiper--CarouselSlider js-CarouselSlider\" data-type=\"modal\" data-card-count=\"4\">\n  <div class=\"Swiper__Wrapper swiper-wrapper \">\n    <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        TPP Enabler\n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>La soluzione white-label per abbattere la complessit\u00e0 di interfacciamento Open Banking<\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n                            <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        Harmonizer Hub\n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>Armonizza e standardizza le causali dei movimenti di conto utilizzate dalle diverse banche <\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n                            <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        SCA Manager\n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>Semplifica l&#8217;integrazione con gli ASPSP rimuovendo la complessit\u00e0 della gestione di SCA multiple<\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n                            <div class=\"Swiper__Item swiper-slide\">\n                    <div class=\"Card Card--Dark\">\n  <div class=\"Card__Wrapper\">\n          <h4 class=\"Card__Title\">\n        Certificati EIDAS \n      <\/h4>\n     \n\n          <div class=\"Card__Content\"><p>Gestisce il ciclo di vita dei certificati EIDAS dei TPP accreditati<\/p>\n<\/div>\n     \n\n          <div class=\"Card__Trigger\">\n        <svg class=\"js-openModal\" width=\"40\" height=\"40\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M20 13v7m0 0v7m0-7h7m-7 0h-7\" stroke=\"url(#paint0_linear_1701_1697)\" stroke-width=\"2.5\" stroke-linecap=\"round\"\/><path d=\"M20 38c10 0 18-8 18-18S30 2 20 2 2 10 2 20s8 18 18 18z\" stroke=\"url(#paint1_linear_1701_1697)\" stroke-width=\"2.5\"\/><defs><linearGradient id=\"paint0_linear_1701_1697\" x1=\"26.95\" y1=\"27.2\" x2=\"13.374\" y2=\"27.2\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><linearGradient id=\"paint1_linear_1701_1697\" x1=\"37.376\" y1=\"38\" x2=\"3.435\" y2=\"38\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#F39600\"\/><stop offset=\"1\" stop-color=\"#A032F3\"\/><\/linearGradient><\/defs><\/svg>      <\/div>\n     \n  <\/div>\n<\/div>                 <\/div>\n  <\/div>\n  <div class=\"Swiper__Scrollbar swiper-scrollbar js-Swiper-Scrollbar\"><\/div>\n<\/div>        \n        <div class=\"Modal js-CarouselModal\">\n    <div class=\"Modal__Container\">\n        <span class=\"Modal__Close js-ModalClose\">&times;<\/span>\n        <div class=\"Modal__Wrapper\">  \n            <div class=\"Swiper swiper Swiper--ModalSlider js-ModalSlider\" data-card-count=\"0\" id=\"swiper-carousel-navigation-A3nmo\">\n  <div class=\"Swiper__Wrapper swiper-wrapper\">\n    <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">TPP Enabler<\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>Questo componente \u00e8 una soluzione white-label dedicata a TPP ed aggregatori, che offre una facile integrazione \u201cout-of-the-box\u201d con la pluralit\u00e0 di standard API di mercato nell\u2019Open Banking. Permette di semplificare il consumo dei servizi esposti dalle Banche, grazie all\u2019architettura estremamente flessibile e alla ricchezza di interfacce in dotazione, pre-certificate per il dialogo con i maggiori Account Servicing Payment Service Providers e\/o Gateway Open Banking. Offre una vasta libreria di Open API ed una dashboard di monitoraggio evoluta. <\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">Harmonizer Hub<\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>Questo componente risponde all\u2019esigenza di armonizzare e standardizzare le causali dei movimenti di conto al fine di permettere ai TPP (Third Party Provider) di costruire ed erogare nuovi servizi basati su viste aggregate e coerenti dei loro conti. La soluzione utilizza un motore intelligente basato su una pipeline di algoritmi di Intelligent Text Mining e di Machine Learning che permette di interpretare, riconciliare e armonizzare la complessit\u00e0 delle Voci di Causali proprie di ciascuna Banca, creando una tassonomia standard di riferimento e personalizzabile, aggiornata di continuo. <\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">SCA Manager<\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>Lo SCA Manager gestisce per conto del TPP l\u2019integrazione con le diverse tipologie di autenticazione forte del cliente richieste dai PSP detentori dei conti (ASPSP), armonizzandone i workflow di fruizione. La componente pu\u00f2 essere configurata dal TPP in modalit\u00e0 Pass Through o Active. Nel primo caso, lo SCA Manager traduce e inoltra al TPP le richieste dell\u2019ASPSP mediante le API specifiche del TPP Enabler. Nella modalit\u00e0 Active invece lo SCA Manager gestisce attivamente le diverse tipologie di SCA (redirect, embedded, decoupled, oAuth 2) implementando i workflow che intercettano le richieste e le callback dell\u2019ASPSP, e permettendo un aggiornamento dello stato dei consensi\/pagamento e, quando richiesto, costruendo dinamicamente le pagina di richiesta credenziali, successivi Token ed altro.<\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                        <div class=\"Swiper__Item swiper-slide\">\n                        <div class=\"Swiper__ItemWrapper \">\n                            <h2 class=\"Swiper__ModalTitle\">Certificati EIDAS <\/h2>\n                            <div class=\"Swiper__ModalContentWrapper\">\n                                <div class=\"Swiper__ModalContent\">\n                                    <div class=\"Swiper__TopContent\">\n                                        <p>Questo componente semplifica al TPP la gestione dei certificati richiesti dalla normativa per attestare l\u2019accreditamento del soggetto; consente il censimento ed associazione dei certificati eIDAS QWAC e QSeal, con verifica della validit\u00e0, sia in termini di scadenza, sia in termini di eventuale presenza all\u2019interno delle CRL (Certificate Revocation List) del QTSP (Qualified Trusted Service Provider) emettitore. I certificati vengono utilizzati dal Workflow Engine del TPP Enabler per garantire una connessione sicura agli ASPSP, prevedendo l\u2019import ed export dei certificati eIDAS del TPP, la gestione della chiave privata dei certificati eIDAS, nonch\u00e9 la notifica di scadenza di un certificato.<\/p>\n\n                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n  <\/div>\n  <div class=\"Swiper__Arrow Swiper__Arrow--Next swiper-button-next\"><\/div>\n  <div class=\"Swiper__Arrow Swiper__Arrow--Prev swiper-button-prev\"><\/div>\n  <\/div>         <\/div>\n    <\/div>\n<\/div> \n    <\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_7f3859-2f > .kt-row-column-wrap{align-content:center;}:where(#kt-layout-id_7f3859-2f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}#kt-layout-id_7f3859-2f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:3rem;padding-bottom:3rem;grid-template-columns:repeat(2, minmax(0, 1fr));}#kt-layout-id_7f3859-2f > .kt-row-layout-overlay{opacity:0.30;}@media all and (min-width: 1025px){#kt-layout-id_7f3859-2f{display:none !important;}}@media all and (max-width: 1024px){#kt-layout-id_7f3859-2f > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (min-width: 768px) and (max-width: 1024px){#kt-layout-id_7f3859-2f{display:none !important;}}@media all and (max-width: 767px){#kt-layout-id_7f3859-2f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}#kt-layout-id_7f3859-2f{display:none !important;}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignfull kvs-lg-false kvs-md-false kvs-sm-false\" id=\"compliance\"><div id=\"kt-layout-id_7f3859-2f\" class=\"kt-row-layout-inner kt-row-has-bg kt-layout-id_7f3859-2f has-white-background-color\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-gutter-default kt-v-gutter-default kt-row-valign-middle kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_2eb9e7-d5 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_2eb9e7-d5 > .kt-inside-inner-col,.kadence-column_2eb9e7-d5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_2eb9e7-d5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_2eb9e7-d5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_2eb9e7-d5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_2eb9e7-d5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_2eb9e7-d5{position:relative;}@media all and (max-width: 1024px){.kadence-column_2eb9e7-d5 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_2eb9e7-d5 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_2eb9e7-d5\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image alignfull size-full img-narrow-desktop is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"745\" height=\"600\" src=\"\/app\/uploads\/2022\/08\/certifications-compliance-en-1.jpg\" alt=\"\" class=\"wp-image-737\" srcset=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2022\/08\/certifications-compliance-en-1.jpg 745w, https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2022\/08\/certifications-compliance-en-1-300x242.jpg 300w\" sizes=\"(max-width: 745px) 100vw, 745px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column_42628e-a2 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_42628e-a2 > .kt-inside-inner-col,.kadence-column_42628e-a2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_42628e-a2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_42628e-a2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_42628e-a2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_42628e-a2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_42628e-a2{position:relative;}@media all and (max-width: 1024px){.kadence-column_42628e-a2 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_42628e-a2 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-2 kadence-column_42628e-a2\"><div class=\"kt-inside-inner-col\">\n<h4 class=\"has-text-align-left has-blue-color has-text-color wp-block-heading\">Compliance e Certificazioni<\/h4>\n\n\n\n<p class=\"has-text-align-left has-blue-color has-text-color\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Risus, massa auctor quis in pretium sit suspendisse faucibus. Nullam a sed mauris sit nibh purus, lorem volutpat. Posuere elementum viverra ipsum faucibus arcu.<br><br>Accumsan diam molestie sed cum nisl id metus a. Egestas massa cursus cras enim. Faucibus amet sit dictum amet, nibh. Lacus sit dictumst leo consectetur senectus enim sem malesuada. Faucibus aliquet aliquet euismod quis eget.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"ButtonList wp-block-lista-bottoni ButtonList--Left\">\n          <a href=\"\/it\/azienda\/policy-e-certificazioni\/\" class=\"Button Button--Dark Button--HoverGradient\" target=\"_self\">\n    Vedi tutte le certificazioni\n<\/a>      <\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_7c130f-6d > .kt-row-column-wrap{align-content:start;}:where(#kt-layout-id_7c130f-6d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}#kt-layout-id_7c130f-6d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:0px;padding-bottom:30px;padding-left:0px;padding-right:0px;grid-template-columns:minmax(0, 1fr);}#kt-layout-id_7c130f-6d > .kt-row-layout-overlay{opacity:0.30;}#kt-layout-id_7c130f-6d .kt-row-layout-bottom-sep{height:30px;}#kt-layout-id_7c130f-6d .kt-row-layout-bottom-sep svg{width:100%;}#kt-layout-id_7c130f-6d .kt-row-layout-bottom-sep svg{fill:linear-gradient(270deg, rgb(243,150,0) 1.73%, rgb(160,50,243) 96.01%)!important;}@media all and (min-width: 1025px){#kt-layout-id_7c130f-6d{display:none !important;}}@media all and (max-width: 1024px){#kt-layout-id_7c130f-6d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){#kt-layout-id_7c130f-6d .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){#kt-layout-id_7c130f-6d .kt-row-layout-bottom-sep svg{width:%;}}@media all and (min-width: 768px) and (max-width: 1024px){#kt-layout-id_7c130f-6d{display:none !important;}}@media all and (max-width: 767px){#kt-layout-id_7c130f-6d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}#kt-layout-id_7c130f-6d .kt-row-layout-bottom-sep{height:px;}#kt-layout-id_7c130f-6d .kt-row-layout-bottom-sep svg{width:%;}#kt-layout-id_7c130f-6d{display:none !important;}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignfull kvs-lg-false kvs-md-false kvs-sm-false\" id=\"divider\"><div id=\"kt-layout-id_7c130f-6d\" class=\"kt-row-layout-inner kt-row-has-bg kt-layout-id_7c130f-6d has-blue-background-color\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_c972a9-ac > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_c972a9-ac > .kt-inside-inner-col,.kadence-column_c972a9-ac > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_c972a9-ac > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_c972a9-ac > .kt-inside-inner-col{flex-direction:column;}.kadence-column_c972a9-ac > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_c972a9-ac > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_c972a9-ac{position:relative;}@media all and (max-width: 1024px){.kadence-column_c972a9-ac > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_c972a9-ac > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_c972a9-ac\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_18b491-a4 > .kt-row-column-wrap{align-content:start;}:where(#kt-layout-id_18b491-a4 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}#kt-layout-id_18b491-a4 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:5rem;padding-bottom:5rem;grid-template-columns:minmax(0, 1fr);}#kt-layout-id_18b491-a4{background-image:url('\/app\/uploads\/2022\/07\/sfondo1-1.jpg');background-size:cover;background-position:center center;background-attachment:fixed;background-repeat:no-repeat;}#kt-layout-id_18b491-a4 > .kt-row-layout-overlay{opacity:0.30;}@media all and (min-width: 1025px){#kt-layout-id_18b491-a4{display:none !important;}}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (orientation: landscape) and (hover: none){#kt-layout-id_18b491-a4{background-attachment:scroll;}}@media all and (max-width: 1024px){#kt-layout-id_18b491-a4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (min-width: 768px) and (max-width: 1024px){#kt-layout-id_18b491-a4{display:none !important;}}@media all and (max-width: 767px){#kt-layout-id_18b491-a4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}#kt-layout-id_18b491-a4{display:none !important;}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignfull kvs-lg-false kvs-md-false kvs-sm-false\" id=\"success-stories\"><div id=\"kt-layout-id_18b491-a4\" class=\"kt-row-layout-inner kt-row-has-bg kt-layout-id_18b491-a4 kt-jarallax\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_83b41b-ae > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_83b41b-ae > .kt-inside-inner-col,.kadence-column_83b41b-ae > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_83b41b-ae > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_83b41b-ae > .kt-inside-inner-col{flex-direction:column;}.kadence-column_83b41b-ae > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_83b41b-ae > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_83b41b-ae{text-align:center;}.kadence-column_83b41b-ae{position:relative;}@media all and (max-width: 1024px){.kadence-column_83b41b-ae > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_83b41b-ae > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_83b41b-ae\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"has-white-color has-text-color wp-block-heading\">Success Stories<\/h2>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_cc5592-57 > .kt-row-column-wrap{align-content:center;}:where(#kt-layout-id_cc5592-57 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}#kt-layout-id_cc5592-57 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:5rem;padding-bottom:5rem;grid-template-columns:minmax(0, 1fr);}#kt-layout-id_cc5592-57 > .kt-row-layout-overlay{opacity:0.30;}#kt-layout-id_cc5592-57 ,#kt-layout-id_cc5592-57 h1,#kt-layout-id_cc5592-57 h2,#kt-layout-id_cc5592-57 h3,#kt-layout-id_cc5592-57 h4,#kt-layout-id_cc5592-57 h5,#kt-layout-id_cc5592-57 h6{color:#ffffff;}@media all and (max-width: 1024px){#kt-layout-id_cc5592-57 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){#kt-layout-id_cc5592-57 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignfull\" id=\"clienti\"><div id=\"kt-layout-id_cc5592-57\" class=\"kt-row-layout-inner kt-row-has-bg kt-layout-id_cc5592-57 has-blue-background-color\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-middle kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_e040f4-08 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_e040f4-08 > .kt-inside-inner-col,.kadence-column_e040f4-08 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_e040f4-08 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_e040f4-08 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_e040f4-08 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_e040f4-08 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_e040f4-08{text-align:center;}.kadence-column_e040f4-08{position:relative;}@media all and (max-width: 1024px){.kadence-column_e040f4-08 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_e040f4-08 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_e040f4-08\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">Tra i nostri clienti<\/h2>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"Swiper swiper Swiper--TextSlider js-TextSlider\" data-card-count=\"0\" id=\"swiper-carousel-navigation-kHckk\">\n  <div class=\"Swiper__Wrapper swiper-wrapper\">\n    <div class=\"Swiper__Item swiper-slide\">\n          <div class=\"Swiper__ItemWrapper\">\n            <h4 class=\"Swiper__Text swiper-slide\">CBIGlobe<\/h4>\n          <\/div>  \n        <\/div>  \n       \n                  <div class=\"Swiper__Item swiper-slide\">\n          <div class=\"Swiper__ItemWrapper\">\n            <h4 class=\"Swiper__Text swiper-slide\">IntesaSanpaolo<\/h4>\n          <\/div>  \n        <\/div>  \n       \n                  <div class=\"Swiper__Item swiper-slide\">\n          <div class=\"Swiper__ItemWrapper\">\n            <h4 class=\"Swiper__Text swiper-slide\">Nexi<\/h4>\n          <\/div>  \n        <\/div>  \n       \n                  <div class=\"Swiper__Item swiper-slide\">\n          <div class=\"Swiper__ItemWrapper\">\n            <h4 class=\"Swiper__Text swiper-slide\">Unipol<\/h4>\n          <\/div>  \n        <\/div>\n  <\/div>\n  <div class=\"Swiper__Arrow Swiper__Arrow--Next swiper-button-next\"><\/div>\n  <div class=\"Swiper__Arrow Swiper__Arrow--Prev swiper-button-prev\"><\/div>\n  <\/div> <\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_777f87-57 > .kt-row-column-wrap{align-content:start;}:where(#kt-layout-id_777f87-57 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}#kt-layout-id_777f87-57 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:2.5rem;padding-bottom:5rem;grid-template-columns:minmax(0, 1fr);}#kt-layout-id_777f87-57 > .kt-row-layout-overlay{opacity:1;background-image:linear-gradient(180deg, #07112c 50%, #00000000 50%);mix-blend-mode:normal;}@media all and (max-width: 1024px){#kt-layout-id_777f87-57 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){#kt-layout-id_777f87-57 > .kt-row-column-wrap{padding-bottom:3rem;grid-template-columns:minmax(0, 1fr);}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignfull\" id=\"insight\"><div id=\"kt-layout-id_777f87-57\" class=\"kt-row-layout-inner kt-row-has-bg kt-layout-id_777f87-57 has-violet-to-orange-background-color\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_985b34-66 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_985b34-66 > .kt-inside-inner-col,.kadence-column_985b34-66 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_985b34-66 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_985b34-66 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_985b34-66 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_985b34-66 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_985b34-66{text-align:center;}.kadence-column_985b34-66{position:relative;}@media all and (max-width: 1024px){.kadence-column_985b34-66 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_985b34-66 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_985b34-66\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"has-white-color has-text-color wp-block-heading\">Insights<\/h2>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div id=\"swiper-carousel-O6Moi\" class=\"Swiper swiper Swiper--CarouselSlider js-CarouselSlider\" data-type=\"\" data-card-count=\"10\">\n  <div class=\"Swiper__Wrapper swiper-wrapper \">\n    <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">Eventi<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">digital treasury<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">payment networks<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">PSD2<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">TAS @ Sibos 2025<\/h4> \n              <time class=\"Card__Date\" datetime=\"29-07-2025\" pubdate=\"pubdate\">29 Luglio 2025<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2022\/09\/sibos_2022-tas-2.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p><strong>29 Settembre | 2 Ottobre &#8211; Messe Frankfurt<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>TAS tra gli espositori ufficiali di Sibos 2025. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Viene a trovarci al nostro \u00a0<strong>stand F065<\/strong>\u00a0per condividere insight sulle ultime tendenze in tema di\u00a0<strong>pagamenti digitali, gestione della liquidit\u00e0, connettivit\u00e0 degli schemi di pagamento, open banking<\/strong>\u00a0e molto altro ancora.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:buttons -->\n<div class=\"wp-block-buttons\"><!-- wp:button {\"className\":\"is-style-outline\"} -->\n<div class=\"wp-block-button is-style-outline\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.tasgroup.eu\/insight\/landing\/meet-tas-at-sibos-2025\/\"><strong>Scopri di pi\u00f9 su TAS @ Sibos<\/strong><\/a><\/div>\n<!-- \/wp:button --><\/div>\n<!-- \/wp:buttons --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/eventi\/tas-sibos-2025\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">Comunicato Stampa<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">PSD2<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">TAS<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">TPPay: Innovazione nel mercato finanziario con il primo IMEL-as-a-service<\/h4> \n              <time class=\"Card__Date\" datetime=\"18-04-2024\" pubdate=\"pubdate\">18 Aprile 2024<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2024\/04\/TPPAY.png\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p><strong>Milano \u2013 18 aprile 2024<\/strong> &#8211; TPPay, l&#8217;innovativo Istituto di Moneta Elettronica (IMEL), sta facendo il suo ingresso nel panorama finanziario italiano con una nuova proposta per la gestione dei servizi finanziari per il mondo Corporate. Specializzato nell&#8217;emissione, gestione e distribuzione di moneta elettronica, TPPay si presenta come il primo IMEL-as-a-service in Italia, aprendo la possibilit\u00e0 per le Corporate di lanciare servizi finanziari e di pagamento per i propri clienti senza bisogno di ottenere alcuna licenza.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><br>\u201c<em>La nostra missione \u00e8 di consentire alle societ\u00e0 senza licenza bancaria la possibilit\u00e0 di sfruttare i vantaggi dell\u2019open banking<\/em>\u201d spiega Matteo Bravi, Chief Strategy &amp; Transformation Officer di TAS e Chairman di TPPay. \u201c<em>Vogliamo rendere i servizi finanziari ed i sistemi di incasso e pagamento pi\u00f9 accessibili e convenienti per le imprese e i loro clienti, contribuendo cos\u00ec all&#8217;evoluzione del mondo finanziario digitale, con una gamma di soluzioni e servizi altamente adattabili alle esigenze di molteplici mercati<\/em>\u201d.<br><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Tra i servizi offerti da TPPay:<br>\u2022 <strong>Conti di Pagamento<\/strong>: wallet 100% white-label per creare sistemi closed-loop di incasso, consentendo agli utenti di inviare e ricevere pagamenti senza commissioni<br>\u2022 <strong>Carte<\/strong>: TPPay emette Carte di Debito e Prepagate in co-branding, completamente personalizzabili per rispecchiare l&#8217;identit\u00e0 visiva dei clienti e, soprattutto, condividere le fee generate dai pagamenti con queste carte<br>\u2022 <strong>Pagamenti<\/strong>: TPPay consente di incassare e inviare pagamenti in modo automatico, semplificando la riconciliazione e abbattendo le commissioni grazie ai sistemi closed-loop.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u201c<em>TPPay si distingue per la sua flessibilit\u00e0 e modularit\u00e0, adattandosi alle esigenze di una vasta gamma di settori, tra cui utilities, energia e petrolio, assicurazioni, grande distribuzione organizzata, turismo e moda, telecomunicazioni e gambling, automotive e mobilit\u00e0, fintech e marketplace<\/em>\u201d commenta Emanuele Grio, Chief Operating Officer di TPPay.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><br>Alfonso Catone, Chief Commercial Officer di TPPay, elenca i vantaggi di operare con TPPay in qualit\u00e0 di TPP (Third Party Player): \u201c<em>Grazie ai sistemi di incasso closed-loop \u00e8 possibile ottenere pagamenti istantanei e fuori dai tradizionali sistemi, risparmiando cos\u00ec sui costi di acquiring. La possibilit\u00e0 di emettere carte e altri servizi di pagamento personalizzati apre nuovi canali di fatturato e contribuisce ad aumentare la fidelizzazione dell\u2019utente. Non da ultimo, TPPay offre un\u2019esperienza 100% White-Label consentendo la piena personalizzazione dell&#8217;esperienza utente e garantendo il massimo controllo della brand identity<\/em>\u201d.<br><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>TPPay \u00e8 una societ\u00e0 del gruppo TAS, leader italiano nel settore delle tecnologie per la monetica e i pagamenti, con oltre 40 anni di esperienza e un market share del 75% nel settore bancario e del 90% su IMEL e operatori PSD2. TAS porta con s\u00e9 un portafoglio prodotti PSD2 completo e una profonda conoscenza del settore dei pagamenti.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><a href=\"https:\/\/www.tasgroup.eu\/app\/uploads\/sites\/2\/2024\/04\/TPPay-CS.pdf\">Scarica il comunicato stampa<\/a><\/p>\n<!-- \/wp:paragraph --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/tppay-innovazione-nel-mercato-finanziario-con-il-primo-imel-as-a-service\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">Eventi<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">digital treasury<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">payment networks<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">TAS @ EBAday 2023<\/h4> \n              <time class=\"Card__Date\" datetime=\"05-06-2023\" pubdate=\"pubdate\">05 Giugno 2023<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/02\/TAS-ebaday-2023-1.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p>20 &#8211; 21 Giugno 2023 | THE IFEMA, MADRID<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Advancing next generation payments &#8211; a quest for global interoperability<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>L&#8217;appuntamento annuale con EBAday quest&#8217;anno si terr\u00e0 Madrid e siamo entusiasti di essere ancora una volta tra gli sponsor dell&#8217;evento.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Il summit, organizzato da <strong>Finextra<\/strong> e dall&#8217;<strong>Euro Banking Association<\/strong>, \u00e8 il luogo ideale per approfondire le tematiche pi\u00f9 attuali nel mondo dei pagamenti, incontrare professionisti del settore, banche e istituzioni finanziarie e costruire opportunit\u00e0 di confronto e collaborazione.  <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I temi chiave dell&#8217;evento di quest&#8217;anno riguarderanno le valute digitali della banca centrale (CBDC), le banche di nuova generazione, il banking-as-a-service (BaaS) e l&#8217;interoperabilit\u00e0 dei pagamenti transfrontalieri.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ti aspettiamo al nostro stand dove presenteremo le nostre soluzioni per:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li><strong>Liquidit\u00e0 real-time<\/strong><\/li><li><strong>Connettivit\u00e0 alle reti<\/strong><\/li><li><strong>Open Banking e Embedded Finance<\/strong><\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:acf\/bottone {\"id\":\"block_647f0d617e5f8\",\"name\":\"acf\/bottone\",\"data\":{\"link\":{\"title\":\"Scopri di pi\u00f9 su TAS @ EBAday 2023\",\"url\":\"https:\/\/www.tasgroup.eu\/insight\/landing\/join-us-at-ebaday-2023\/\",\"target\":\"\"},\"_link\":\"field_bottone_link\",\"class\":\"Default\",\"_class\":\"field_bottone_class\",\"gradient\":\"1\",\"_gradient\":\"field_bottone_gradient\"},\"align\":\"\",\"mode\":\"edit\",\"align_content\":\"top\"} \/--> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/eventi\/tas-ebaday-2023\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">PSD2<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">Embedded Insurance: clienti protetti senza interruzioni<\/h4> \n              <time class=\"Card__Date\" datetime=\"22-05-2023\" pubdate=\"pubdate\">22 Maggio 2023<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/05\/embedded-insurance-article-1.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p>L\u2019 <em>embedded finance<\/em> sta rivoluzionando il settore finanziario e una delle sue componenti pi\u00f9 significative \u00e8 l&#8217;embedded insurance. Ma cos&#8217;\u00e8 esattamente l&#8217;assicurazione incorporata?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>In questo articolo esploreremo i dettagli dell&#8217;embedded insurance e di come si inserisce nel quadro pi\u00f9 ampio dell\u2019open finance, della PSD2 e del Banking as a Service.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Cos&#8217;\u00e8 l&#8217;assicurazione incorporata<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>La finanza incorporata \u00e8 un concetto relativamente nuovo che si riferisce all&#8217;integrazione di servizi finanziari in prodotti o servizi non finanziari. In altre parole, significa incorporare funzionalit\u00e0 finanziarie all&#8217;interno di altre applicazioni e piattaforme, come siti web di e-commerce, app di social media o persino automobili. Di conseguenza, le aziende sono in grado di offrire ai propri clienti un accesso pi\u00f9 conveniente a una gamma di prodotti e servizi finanziari.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Una delle aree pi\u00f9 promettenti in cui la finanza incorporata sta guadagnando terreno \u00e8 quella delle assicurazioni.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>L&#8217;assicurazione incorporata <strong>consiste nell\u2019integrare le polizze assicurative in prodotti o servizi che non sono focalizzati principalmente sulla fornitura di assicurazioni<\/strong>. Ci\u00f2 consente ai consumatori di sottoscrivere polizze assicurative direttamente tramite piattaforme di terze parti come parte del loro percorso di acquisto su un sito e-commerce o tramite il proprio conto bancario senza dover visitare fisicamente il sito web o l&#8217;ufficio di un assicuratore.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Integrando questi due settori, \u00e8 possibile offrire soluzioni pi\u00f9 veloci a persone interessate ai prodotti assicurativi ma che hanno poco tempo o voglia di leggere documenti e compilare modulistica aggiuntiva.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Le assicurazioni integrate sono disponibili in vari settori come quello del turismo, dell\u2019automotive, dell\u2019assistenza sanitaria e altro ancora. Ad esempio, quando si acquistano biglietti di viaggio online, \u00e8 possibile che i clienti aggiungano la copertura assicurativa di viaggio al momento del pagamento.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Vantaggi dell&#8217;assicurazione incorporata<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>L\u2019embedded insurance offre numerosi vantaggi sia ai clienti che agli assicuratori\/aziende.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Dal punto di vista dei clienti uno dei principali vantaggi \u00e8 la <strong>convenienza<\/strong>. Con le assicurazioni tradizionali, i clienti devono affrontare un lungo processo di sottoscrizione di polizze, presentazione di richieste e attesa di rimborsi. L&#8217;assicurazione incorporata semplifica questo processo integrandolo nei prodotti e servizi esistenti. I clienti possono acquistare una polizza assicurativa con pochi click sui propri dispositivi digitali invece di compilare lunghi moduli e rimanere in attesa di approvazione. Ci\u00f2 significa meno passaggi per i clienti, con conseguente aumento dei tassi di conversione.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un altro vantaggio \u00e8 <strong>l&#8217;economicit\u00e0<\/strong>. Poich\u00e9 l\u2019embedded insurance \u00e8 integrata in altri prodotti e servizi, non richiede attivit\u00e0 di marketing o canali di distribuzione separati. Ci\u00f2 pu\u00f2 comportare costi inferiori sia per gli assicuratori che per i clienti e una migliore <strong>fidelizzazione dei clienti<\/strong>. Offrendo un&#8217;assicurazione integrata, le aziende possono fornire valore aggiunto ai propri clienti senza richiedere loro di cercare fornitori di terze parti. Ci\u00f2 rende pi\u00f9 probabile che continueranno a utilizzare i prodotti o i servizi dell&#8217;azienda in futuro.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>L&#8217;assicurazione incorporata crea <strong>un&#8217;esperienza cliente pi\u00f9 fluida<\/strong> fornendo uno sportello unico per tutte le esigenze finanziarie. I clienti possono gestire con maggiore semplicit\u00e0 le proprie finanze e proteggersi allo stesso tempo. Ad esempio, quando acquistano un&#8217;auto o prenotano un viaggio online, i clienti possono facilmente aggiungere una copertura assicurativa pertinente senza dover visitare siti di terze parti.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Per gli assicuratori, l&#8217;embedded insurance apre nuovi flussi di entrate attingendo a gruppi clienti precedentemente non sfruttati che potrebbero non aver mai considerato l&#8217;acquisto di polizze in precedenza. Inoltre, tramite l\u2019analisi dei dati integrata le aziende possono raccogliere maggiori informazioni sui modelli di comportamento dei propri clienti per offrire opzioni di copertura personalizzate.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Le aziende traggono vantaggio dall&#8217;assicurazione integrata anche sfruttandola come possibilit\u00e0 di <strong>offrire servizi a valore aggiunto<\/strong> che le differenziano dai concorrenti.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>L&#8217;aspetto chiave dell\u2019embedded insurance \u00e8 anticipare i bisogni dei clienti, accorciando le fasi tradizionali del <em>customer journey<\/em>. Si passa cos\u00ec da un modello di acquisto programmato a uno di impulso in cui i consumatori non ricercano e confrontano le diverse opzioni disponibili sul mercato: l&#8217;obiettivo \u00e8 acquisire clienti prima che la transazione principale (come ad esempio l&#8217;acquisto di un biglietto aereo) sia conclusa.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>L&#8217;assicurazione incorporata sta plasmando positivamente il futuro della finanza. Man mano che sempre pi\u00f9 settori abbracciano i concetti dell\u2019open finance come il BaaS (Banking as a Service), possiamo aspettarci che queste integrazioni diventino ancora pi\u00f9 diffuse nella nostra vita quotidiana.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Problemi e opportunit\u00e0 legati all&#8217;Embedded Insurance<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Come con qualsiasi tecnologia o tendenza emergente, l\u2019embedded insurance presenta sia sfide che opportunit\u00e0.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Uno dei problemi principali \u00e8 la conformit\u00e0 normativa. Poich\u00e9 l&#8217;assicurazione incorporata opera nell&#8217;ambito della PSD2, le aziende devono districarsi in un complesso insieme di regole per garantire la conformit\u00e0 alle normative. Questo pu\u00f2 richiedere molto tempo e denaro.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un altro problema \u00e8 la consapevolezza del cliente. Molti consumatori potrebbero non capire cos&#8217;\u00e8 l&#8217;assicurazione incorporata o come funziona, il che potrebbe renderli riluttanti a utilizzarla. Le aziende devono educare i propri clienti sui vantaggi di questo tipo di assicurazione in modo che si sentano sicuri nell&#8217;usarla.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Tuttavia, come per ogni sfida, ci sono anche opportunit\u00e0 di crescita e innovazione. Con la diffusione delle piattaforme Baas (Banking-as-a-Service) e delle iniziative Open Finance, le aziende hanno pi\u00f9 accesso alla possibilit\u00e0 di integrare nuovi servizi finanziari nei loro prodotti come prestiti o pagamenti, offrendo al contempo una protezione completa attraverso l\u2019inserimento di un prodotto assicurativo, come ad esempio una copertura medica di viaggio, proprio dove gli utenti ne hanno pi\u00f9 bisogno, durante la transazione stessa.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Inoltre, utilizzando le tecnologie di analisi dei dati combinate con i dispositivi IoT installati ad esempio nelle auto o nelle case, gli assicuratori possono offrire polizze personalizzate basate sulle esigenze individuali invece di piani di copertura generali, creando cos\u00ec un vantaggio competitivo rispetto agli assicuratori tradizionali che si affidano esclusivamente ai processi di sottoscrizione manuale.<strong><\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Embedded Insurance: casi d\u2019uso<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Il panorama dell&#8217;assicurazione incorporata sta cambiando radicalmente l&#8217;approccio di molte aziende verso le polizze assicurative. Grazie all&#8217;integrazione delle polizze nel processo di acquisto dei clienti, vengono eliminate alcune delle barriere che precedentemente rendevano complicato l&#8217;acquisto della copertura assicurativa. Aree come il turismo stanno sperimentando un forte impatto da questo trend, con piattaforme di prenotazione che ora offrono assicurazioni viaggio su misura insieme alle prenotazioni di voli o hotel, e compagnie aeree che offrono coperture rapide per ritardi, cancellazioni ed altri incidenti correlati, direttamente durante il processo di check-in. I clienti dunque sperimentano un\u2019esperienza d\u2019acquisto pi\u00f9 semplice e veloce; invece per le aziende, \u00e8 un ottimo modo per ottenere nuovi flussi di entrate guadagnando con le commissioni.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Oltre al settore del turismo, l&#8217;industria automobilistica pu\u00f2 trarre vantaggi significativi dalle soluzioni assicurative integrate. Poich\u00e9 le case automobilistiche producono veicoli tecnologicamente sempre pi\u00f9 avanzati, l&#8217;offerta di polizze di assicurazione auto personalizzate basate sui dati raccolti dai sensori possono fornire una maggiore precisione nella valutazione del rischio e nella determinazione dei prezzi per i clienti. Questo approccio personalizzato offre potenziali risparmi per i conducenti, incoraggiando nel complesso abitudini di guida pi\u00f9 sicure.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Allo stesso modo, nell&#8217;ambito dell&#8217;e-commerce e della vendita al dettaglio, l&#8217;integrazione di piani di garanzia o protezione durante il checkout del prodotto pu\u00f2 portare a maggiori tassi di conversione e valore aggiunto per i clienti che cercano tranquillit\u00e0 quando effettuano acquisti online. Semplificando questo processo attraverso una perfetta integrazione con i sistemi POS esistenti, i commercianti creano un&#8217;opportunit\u00e0 per l&#8217;upselling senza interrompere l&#8217;esperienza del cliente.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Le piattaforme sanitarie digitali emergenti offrono una grande opportunit\u00e0 per l\u2019embededd insurance, per rendere l&#8217;accesso all&#8217;assicurazione sanitaria pi\u00f9 facile. Poich\u00e9 la telemedicina sta diventando sempre pi\u00f9 popolare, esiste un enorme potenziale per integrare opzioni di copertura come le assicurazioni sulla responsabilit\u00e0 medica o informatica direttamente all&#8217;interno di queste piattaforme digitali.<strong><\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Conclusioni<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>L\u2019embedded insurance \u00e8 un punto di svolta sia per il settore assicurativo che per quello finanziario. Ha il potenziale per rivoluzionare il modo in cui le persone accedono e utilizzano diversi servizi finanziari fornendo al contempo maggiore praticit\u00e0, convenienza ed esperienze personalizzate.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Con PSD2 e BaaS che aprono opportunit\u00e0 per i nuovi entranti nel mercato, la finanza incorporata continuer\u00e0 ad essere una potente area di crescita. E poich\u00e9 L\u2019embedded insurance diventa sempre pi\u00f9 popolare tra i consumatori, possiamo aspettarci pi\u00f9 partnership tra banche, assicuratori, fintech, rivenditori e altri attori nell&#8217;ecosistema.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Sebbene ci siano ancora sfide da superare, come i problemi legati alla privacy dei dati o le barriere normative per le soluzioni transfrontaliere, sembra che il futuro di questa tendenza emergente sia luminoso. Molte aziende stanno esplorando modi per sfruttare le loro attuali piattaforme ed offrire prodotti assicurativi integrati.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>TAS Global Payment Platform per l\u2019Embedded Finance<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Moltissime istituzioni finanziarie hanno scelto <strong><a href=\"https:\/\/www.tasgroup.eu\/it\/global-payment-platform\/\" data-type=\"page\" data-id=\"15\">TAS Global Payment Platform (GPP)<\/a> <\/strong>per fornire ai propri clienti una migliore esperienza di pagamento e consentire un time-to-market pi\u00f9 rapido. La piattaforma GPP \u00e8 adatta a qualsiasi operatore dell\u2019ecosistema sia esso una banca, un provider di tecnologia o un distributore di prodotti finanziari per garantire ai clienti esperienze di fruizione e acquisto eccellenti e senza interruzioni. Collaboriamo con aziende nei settori del digital banking, del BNPL, delle assicurazioni, dei viaggi e dei pagamenti grazie a una piattaforma altamente configurabile con API aperte.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La nostra offerta per l\u2019embedded finance include <strong>microservizi scalabili e affidabili, configurazioni flessibili del flusso di lavoro e una dashboard personalizzata centralizzata che consente alle aziende una maggiore dinamicit\u00e0<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong><a href=\"https:\/\/www.tasgroup.eu\/it\/contatti\/\" data-type=\"page\" data-id=\"28\">Contattaci <\/a><\/strong>per scoprire come possiamo aiutarti a sfruttare l\u2019embedded finance per il tuo caso d&#8217;uso.<\/p>\n<!-- \/wp:paragraph --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/embedded-insurance-clienti-protetti-senza-interruzioni\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">PSD2<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">Come l\u2019embedded finance migliora la vita delle aziende e dei consumatori<\/h4> \n              <time class=\"Card__Date\" datetime=\"21-02-2023\" pubdate=\"pubdate\">21 Febbraio 2023<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/02\/embedded-finance-IT.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p>Il fintech sta diventando sempre pi\u00f9 pervasivo e in questi ultimi anni sono nate diverse offerte innovative volte a raggiungere target di mercato differenti. La <strong><em>finanza incorporata<\/em> (embedded finance), permette ai consumatori che utilizzano prodotti non finanziari di accedere, attraverso questi, a servizi bancari integrati, migliorando cos\u00ec la loro esperienza d&#8217;acquisto<\/strong>. I prodotti finanziari, tradizionalmente offerti dalle banche, diventano cos\u00ec parte dell\u2019esperienza digitale del cliente in un\u2019unica piattaforma che ne semplifica la fruizione.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un&#8217;azienda che fornisce servizi non finanziari, come ad esempio un sito di shopping online, pu\u00f2 quindi offrire un\u2019esperienza completa al cliente accelerandone il processo d\u2019acquisto e migliorandone la sua percezione complessiva.&nbsp;Questo tipo di modello si presta a molteplici casi d\u2019uso in diversi settori, dai fitness club, al gaming, alle organizzazioni non profit, all&#8217;assistenza sanitaria.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Secondo un recente studio di Bain &amp; Company, le transazioni tramite servizi finanziari incorporati negli Stati Uniti hanno raggiunto 2,6 trilioni di dollari nel 2021. Si prevede che questa cifra salir\u00e0 a 7 trilioni di dollari entro il 2026. Questo mostra come i clienti stanno cambiando il modo in cui interagiscono con le loro finanze e come mutano le loro esperienze come clienti.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><strong>Tipi di embedded finance<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>La maggior parte degli sviluppi di embedded finance riguardano prodotti come depositi, pagamenti, emissioni di carte, prestiti e assicurazioni.&nbsp;Queste offerte consentono di creare una facile integrazione con l\u2019esperienza del consumatore e di sviluppare semplicemente nuovi casi d&#8217;uso.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Embedded Banking<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Con l&#8217;embedded banking, noto come&nbsp;<strong>Banking-as-a-Service<\/strong>, le societ\u00e0 non finanziarie possono offrire ai propri utenti un conto virtuale o IBAN per detenere fondi ed effettuare pagamenti.&nbsp;L\u2019embedded banking in genere ha pi\u00f9 senso per venditori o fornitori di servizi che utilizzano la piattaforma di un&#8217;azienda per il proprio business.&nbsp;Spesso \u00e8 anche la base per offrire ulteriori prodotti finanziari incorporati come pagamenti, carte e prestiti.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ad esempio, un acquirer pu\u00f2 liquidare il merchant sui propri conti bancari, consentendogli di utilizzare i fondi depositati per coprire le spese relative alle forniture.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Embedded Payment<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Avere fisicamente una carta di debito o di credito, inserire il PIN, utilizzare la carta sono tutti aspetti in grado di indurre i consumatori ad abbandonare un acquisto digitale se la loro carta non \u00e8 a portata di mano.&nbsp;Con i pagamenti integrati (embedded payments), invece, non essendo richiesta alcuna carta fisica, tale problematica viene risolta grazie a esperienze di pagamento frictionless.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un esempio \u00e8 l&#8217;esperienza di pagamento del taxi Uber in cui l&#8217;app memorizza i dati della carta e i pagamenti vengono effettuati senza problemi quando si prenota un taxi.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>I pagamenti integrati non sono limitati solo alle carte, ma possono anche offrire ai consumatori la possibilit\u00e0 di pagare direttamente dai loro conti bancari<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un&#8217;interessante indagine condotta da IDC a livello globale ha rivelato che entro il 2030 il 74% dei pagamenti digitali dei consumatori verr\u00e0 effettuato con piattaforme offerte da istituzioni non finanziarie.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Embedded Card Issuing<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Le carte di debito e di credito legate a un brand esistono da diverso tempo.&nbsp;Nell&#8217;ambito della finanza incorporata, i casi d&#8217;uso per l&#8217;utilizzo delle carte al di fuori dei tradizionali pagamenti al dettaglio sono illimitati.&nbsp;Ad esempio, nel B2B oggi le applicazioni di gestione delle spese sono in grado di emettere carte T&amp;E virtuali una tantum e sono in grado di eseguire migliori controlli sulle spese per evitare che i membri del personale utilizzino le carte aziendali fisiche per uso privato.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Embedded Lending<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>In passato il prestito di denaro veniva effettuato tramite carte di credito o attraverso prestiti tradizionali concessi da un istituto finanziario.&nbsp;L&#8217;ascesa di nuovi attori nel settore fintech ha portato a una crescita significativa nell&#8217;area del credito.&nbsp;Negli ultimi anni, si sono moltiplicate le piattaforme BNPL (Buy Now Pay Later) come Klarna e Afterpay che offrono ai consumatori nuove opportunit\u00e0 per accedere facilmente ai fondi quando acquistano beni e servizi.&nbsp;Il rapporto di Bain &amp; Company stima che entro il 2026 la dimensione del mercato indotto dalle piattaforme BNPL raggiunger\u00e0 i 265 miliardi di dollari.&nbsp;La ricerca mostra anche come i clienti siano inclini a spendere leggermente di pi\u00f9 quando utilizzano le piattaforme BNPL, aumentando i tassi di conversione e i ricavi.&nbsp;Grazie a nuove tecnologie accessibili e semplici, la finanza integrata nei prestiti sta diventando una parte significativa del modo in cui consumatori e imprese accedono ai finanziamenti.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Embedded Insurance<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Il continuo aumento dei dati raccolti in tutti i campi impatta anche il mercato assicurativo che ha la possibilit\u00e0 di raccogliere maggiori informazioni da utilizzare per offrire polizze su misura e pi\u00f9 competitive.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I programmi assicurativi incorporati (embedded insurance) differiscono dalle assicurazioni tradizionali perch\u00e9 eliminano l&#8217;agente assicurativo o il broker, ad esempio quando si acquista una nuova auto o quando si utilizzano metodi di pagamento tradizionali.&nbsp;Le nuove piattaforme digitali&nbsp;<strong>consentono alle compagnie assicurative tradizionali di gestire attivit\u00e0 lunghe e laboriose come le registrazioni dei sinistri offrendo una migliore customer experience grazie a piattaforme tecnologiche avanzate<\/strong>.&nbsp;Anche al di fuori delle assicurazioni, nuovi attori utilizzano la finanza incorporata per approfondire le relazioni con i clienti e fidelizzarli.&nbsp;Un esempio \u00e8 offerto da Tesla, che offre polizze assicurative competitive per l&#8217;acquisto di una nuova auto, integrando anche questo aspetto nel processo d\u2019acquisto.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Come dovrebbe essere una piattaforma di embedded finance<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Le piattaforme finanziarie integrate&nbsp;<strong>migliorano l&#8217;esperienza del cliente, il percorso d\u2019acquisto e la progettazione delle piattaforme non finanziarie<\/strong>.&nbsp;Ci\u00f2 \u00e8 reso possibile grazie a un ecosistema fatto di partnership tra banche, fornitori di tecnologia e distributori di prodotti finanziari.&nbsp;I clienti e le aziende che utilizzano queste interfacce possono facilmente integrare il proprio software grazie all\u2019utilizzo di API e beneficiare di elevati livelli di flessibilit\u00e0 e configurabilit\u00e0.&nbsp;Inoltre, l&#8217;offerta di finanza incorporata di una piattaforma include anche&nbsp;<strong>micro-servizi scalabili e affidabili, configurazioni flessibili del flusso di lavoro e dashboard personalizzate e centralizzate<\/strong>&nbsp;che consentono alle aziende una maggiore dinamicit\u00e0 e un time-to-market pi\u00f9 breve.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>TAS Global Payment Platform (GPP): come dovrebbe essere una piattaforma di embedded finance<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Moltissime istituzioni finanziarie hanno scelto <a href=\"https:\/\/www.tasgroup.eu\/it\/global-payment-platform\/\"><strong>TAS Global Payment Platform (GPP)<\/strong><\/a><strong>\u00a0<\/strong>per fornire ai propri clienti una migliore esperienza di pagamento e consentire un time-to-market pi\u00f9 rapido.\u00a0La piattaforma GPP \u00e8 adatta a\u00a0<strong>qualsiasi operatore dell&#8217;ecosistema sia esso una banca, un provider di tecnologia o un distributore di prodotti finanziari per garantire ai clienti esperienze di fruizione e acquisto eccellenti e senza interruzioni<\/strong>. Collaboriamo con aziende nei settori del digital banking, del BNPL, delle assicurazioni, dei viaggi e dei pagamenti grazie a una piattaforma altamente configurabile con API aperte.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La nostra offerta per l\u2019embedded finance include microservizi scalabili e affidabili, configurazioni flessibili del flusso di lavoro e una dashboard personalizzata centralizzata che consente alle aziende una maggiore dinamicit\u00e0.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><a href=\"https:\/\/www.tasgroup.eu\/it\/contatti\/\" data-type=\"page\" data-id=\"28\">Contattaci per scoprire come possiamo aiutarti a sfruttare tutti i vantaggi dell\u2019embedded finance.<\/a><\/p>\n<!-- \/wp:paragraph --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/come-lembedded-finance-migliora-la-vita-delle-aziende-e-dei-consumatori\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">digital treasury<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">TAS<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">TAS pronta a crescere ancora<\/h4> \n              <time class=\"Card__Date\" datetime=\"17-01-2023\" pubdate=\"pubdate\">17 Gennaio 2023<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2023\/02\/Intervista_Bancaforte.png\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p>L\u2019ingresso del Fondo Rivean Capital ha aperto nuove prospettive di crescita per&nbsp;<strong>TAS<\/strong>. E non solo in Italia, dove negli ultimi mesi la societ\u00e0 ha avviato un\u2019aggressiva campagna di acquisizioni, ma anche a livello internazionale, per rafforzare e ampliare la sua gi\u00e0 significativa presenza in Paesi chiave. Il 2023 sar\u00e0 dunque un anno di grandi sfide per la societ\u00e0 guidata dal&nbsp;<strong>CEO Valentino Bravi<\/strong>, tra cui \u2013 anticipa a Bancaforte \u2013 anche \u201c<strong>l\u2019ingresso nel mercato del back office titoli<\/strong>\u201d, dopo aver potenziato l\u2019offerta nel settore del&nbsp;<strong>capital market<\/strong>&nbsp;e aver riscosso un importante successo nell\u2019area della&nbsp;<strong>Liquidity<\/strong>. TAS \u00e8 infatti uno dei principali protagonisti di&nbsp;<strong>T2-T2S Consolidation<\/strong>, secondo BCE \u201ctra i pi\u00f9 complessi progetti mai affrontati dalle banche\u201d, avendo avuto la fiducia per questa complessa trasformazione da parte di una percentuale altissima delle banche italiane.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Il cambio di governance realizzato nel 2022 non modificher\u00e0 per\u00f2 la focalizzazione sui pagamenti che contraddistingue TAS da 40 anni. E, a questo proposito, proseguono gli investimenti per sviluppare ulteriormente la&nbsp;<strong>Global Payment Platform<\/strong>, un asset al momento unico sul mercato.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ne parlano, nella <a href=\"https:\/\/bancaforte.it\/video\/tas-pronta-a-crescere-ancora-RB101347x\">videointervista rilasciata a Bancaforte <\/a>in occasione del Salone dei Pagamenti, oltre al Chief Executive Officer Valentino Bravi, il COO International Business\u00a0<strong>Andrew Quartermaine<\/strong>\u00a0e il CEO Global Payments Solutions\u00a0<strong>Massimiliano Quattrocchi<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><a href=\"https:\/\/bancaforte.it\/video\/tas-pronta-a-crescere-ancora-RB101347x\">Guarda la videointervista<\/a><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:acf\/bottone {\"id\":\"block_63ef4b67b5640\",\"name\":\"acf\/bottone\",\"data\":{\"link\":\"\",\"_link\":\"field_bottone_link\",\"class\":\"Default\",\"_class\":\"field_bottone_class\",\"gradient\":\"0\",\"_gradient\":\"field_bottone_gradient\"},\"align\":\"\",\"mode\":\"preview\",\"align_content\":\"top\"} \/--> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/tas-pronta-a-crescere-ancora\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">Eventi<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">digital treasury<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">payment networks<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">PSD2<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">TAS @ Salone dei pagamenti 2022<\/h4> \n              <time class=\"Card__Date\" datetime=\"21-10-2022\" pubdate=\"pubdate\">21 Ottobre 2022<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2022\/10\/tas-at-salone22.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p>Il Salone dei Pagamenti torna in presenza dal <strong>23 al 25 novembre presso Mico &#8211; Milano<\/strong>!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Siamo felici di essere ancora una volta tra gli Sponsor del pi\u00f9 grande evento italiano dedicato all\u2019innovazione del settore dei Pagamenti.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Tante le tematiche in palinsesto, dal fututo dei pagamenti globali, all\u2019Opentech, ai driver per una societ\u00e0 pi\u00f9 sostenibile, alle sfide per la sicurezza.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:buttons -->\n<div class=\"wp-block-buttons\"><!-- wp:button {\"className\":\"is-style-outline\"} -->\n<div class=\"wp-block-button is-style-outline\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.tasgroup.eu\/it\/insight\/landing\/salone-dei-pagamenti-2022\/\">Scopri di pi\u00f9 su TAS @ Salone 2022<\/a><\/div>\n<!-- \/wp:button --><\/div>\n<!-- \/wp:buttons --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/eventi\/tas-salone-dei-pagamenti-2022\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">Eventi<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">digital treasury<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">payment networks<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">PSD2<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">TAS @ Sibos 2022<\/h4> \n              <time class=\"Card__Date\" datetime=\"20-09-2022\" pubdate=\"pubdate\">20 Settembre 2022<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2022\/09\/sibos_2022-tas-2.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p><strong>10-13 Ottobre &#8211; RAI, Amsterdam<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Sibos torna in presenza e TAS \u00e8 di nuovo tra gli espositori ufficiali. Non vediamo l&#8217;ora di incontrarti ad Amsterdam, dove SWIFT ospiter\u00e0 un programma completo di conferenze, insieme a una vasta gamma di eventi di networking. L&#8217;agenda vedr\u00e0 protagonisti leader aziendali ed esperti provenienti da tutta la comunit\u00e0 finanziaria, che discuteranno le tendenze pi\u00f9 impattanti in termini di tecnologia, regolamentazione, rischi e sostenibilit\u00e0. Se non riesci ad esserci, partecipa a Sibos virtualmente collegandoti alla&nbsp;<strong><a href=\"https:\/\/www.sibos.com\/register-and-plan\/passes#digital\">Digital conference experience<\/a>&nbsp;<\/strong>che estender\u00e0 Sibos ai delegati di tutto il mondo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Viene a trovarci al nostro &nbsp;<strong>stand D76<\/strong>&nbsp;per condividere insight sulle ultime tendenze in tema di&nbsp;<strong>pagamenti digitali, gestione della liquidit\u00e0, connettivit\u00e0 degli schemi di pagamento, open banking<\/strong>&nbsp;e molto altro ancora.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:buttons -->\n<div class=\"wp-block-buttons\"><!-- wp:button {\"className\":\"is-style-outline\"} -->\n<div class=\"wp-block-button is-style-outline\"><a class=\"wp-block-button__link\" href=\"\/insight\/landing\/join-us-at-sibos-2022\/\"><strong>Scopri di pi\u00f9 su TAS @ Sibos<\/strong><\/a><\/div>\n<!-- \/wp:button --><\/div>\n<!-- \/wp:buttons --> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/eventi\/tas-sibos-2022\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">PSD2<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">TAS<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">Request To Pay: i vantaggi del nuovo schema che costituisce il tassello mancante ai pagamenti SEPA end2end<\/h4> \n              <time class=\"Card__Date\" datetime=\"16-11-2020\" pubdate=\"pubdate\">16 Novembre 2020<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2022\/09\/request-to-pay__1_.png\"> <\/div> \n         \n      <div class=\"Card__Content\"> <p>Atteso dal mercato per inizi 2021, lo schema R2P consentir\u00e0 di standardizzare e digitalizzare l\u2019avviso al debitore, di iniziativa del creditore, delle richieste di pagamento, con una ricchezza di dati e opzioni tali da consentire moltissimi casi d\u2019uso, tutti contraddistinti dalla riconciliazione totalmente automatica dei successivi pagamenti.<\/p><p>L\u2019obiettivo \u00e8 quello di migliorare i processi d\u2019incasso e pagamento per aziende, PA e cittadini, puntando ad una user experience totalmente digitale end2end.<\/p><p>L\u2019introduzione di SEPA Instant Credit Transfer e la sua progressiva adozione in tutta Europa, la partenza dell\u2019Open Banking e l\u2019entrata in vigore della PSD2 hanno gettato le basi per i pagamenti in tempo reale 24\/7 e per delle <em>customer journey <\/em>sempre pi\u00f9 innovative e di valore, aprendo molte nuove opportunit\u00e0 per lo sviluppo di nuovi prodotti e servizi alla clientela.<\/p><p>La R2P si cala in questo contesto creando delle condizioni ancora pi\u00f9 chiare per andare a sviluppare dei servizi cooperativi e competitivi per i propri clienti declinando un\u2019ampia gamma di casi d\u2019uso: e-commerce, POI fisici e online, P2P, B2B, B2G, C2G.<\/p><p>EBA CLEARING sta attualmente sviluppando questo servizio infrastrutturale paneuropeo con il supporto di 27 Banche di 11 paesi europei che vedr\u00e0 il go live gi\u00e0 nel 2020, ma l\u2019effettivo roll-out a Marzo 2021.<\/p><p>La R2P non \u00e8 uno strumento di pagamento ma un nuovo modo (tutto digitale) di richiedere un pagamento per cui&nbsp; un beneficiario ed un pagatore scambiano elettronicamente dati strutturati attraverso un workflow di messaggi, prima di scambiarsi il denaro. L\u2019utilizzo integrato di R2P, Instant Payments e Open banking spinge verso un cambio di paradigma dell\u2019esperienza utente, sia beneficiario che pagatore, verso un ecosistema bancario sempre pi\u00f9 online e con processi real-time o near real-time.<\/p><p>Dal punto di vista della trasmissione, l&#8217;R2P \u00e8 indipendente dal canale e pu\u00f2 essere applicata a qualsiasi scenario \u00abcommerciale\u00bb e a qualsiasi transazione di pagamento, indipendentemente dagli attori in gioco, dalla vicinanza fisica tra beneficiario e pagatore, dalle modalit\u00e0 e i tempi di chiusura necessari per il completamento dell\u2019operazione.<\/p><p>Sulle piattaforme applicative e sui canali di TAS vengono realizzati, sulla base delle chiamate all\u2019infrastruttura standard R2P, una serie di servizi competitivi per la clientela sia lato Beneficiario\/Creditore che lato cliente\/pagatore: questi servizi integrano <em>use case <\/em>domestici gi\u00e0 implementati nell\u2019esperienza PayTAS per l\u2019interazione B2G\/C2G nonch\u00e9 CBI, ma sono gi\u00e0 pronti per i biller, i PSP e i client dell\u2019intera area SEPA.<\/p><p>Nell\u2019ambito della strategia pi\u00f9 ampia della Global Payment Platform di TAS, la Request to Pay<em> <\/em>va a completare il portafoglio dei prodotti e servizi&nbsp; innovativi che TAS sta realizzando in ambito pagamenti.<\/p><p>In particolare per la R2P, in sinergia con Open Banking e Instant Payments, le soluzioni TAS coprono sia i livelli infrastrutturali (standard), sia i livelli applicativi e di canale (competitivi) permettendo di realizzare una serie di use case che rendono la User Experience semplice, sicura, economica e totalmente digitale.<\/p> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/request-to-pay-i-vantaggi-del-nuovo-schema-che-costituisce-il-tassello-mancante-ai-pagamenti-sepa-end2end\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>  \n          <div class=\"Swiper__Item swiper-slide\">\n        <div class=\"Card Card--Archive Card--Dark \">\n  <div class=\"Card__Wrapper Card__Align--Left\">\n    <div class=\"Card__LabelTags\">\n                            <div class=\"LabelTag \">News<\/div> \n                                        <div class=\"LabelTag LabelTag--Outline\">card &amp; digital payments<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">consolidation<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">digital treasury<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">e-gov<\/div> \n                  <div class=\"LabelTag LabelTag--Outline\">open banking<\/div> \n                  <\/div>\n     \n      <h4 class=\"Card__Title\">TAS Group @ Salone dei Pagamenti 2020<\/h4> \n              <time class=\"Card__Date\" datetime=\"15-10-2020\" pubdate=\"pubdate\">15 Ottobre 2020<\/time>\n         \n      <div class=\"Card__Image\"> <img decoding=\"async\" src=\"https:\/\/tasgroup.jumpgroup.it\/app\/uploads\/sites\/2\/2022\/09\/salone_600x200.jpg\"> <\/div> \n         \n      <div class=\"Card__Content\"> <!-- wp:paragraph -->\n<p><strong>4-5-6 novembre 2020<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Manca ormai poco meno di un mese all\u2019avvio del <strong>Salone dei Pagamenti 2020<\/strong> e TAS, anche quest\u2019anno, \u00e8 lieta di essere sponsor ufficiale di questa 5\u00b0edizione completamente rinnovata.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La pandemia da COVID19 ha avuto un forte impatto sul nostro modo di lavorare e relazionarci. Questo 2020 ci ha decisamente insegnato che digitale e reale non sono due termini dicotomici. Le nuove tecnologie ci hanno infatti permesso di colmare gli spazi fisici e abbiamo appreso a svolgere le nostre attivit\u00e0 quotidiane in modalit\u00e0 agile. Per adattarsi al new-normal anche il Salone dei Pagamenti ha sentito l\u2019esigenza di rinnovarsi e questa edizione 2020 porta con s\u00e9 innumerevoli novit\u00e0 a cominciare dalla location: il 5\u00b0 Salone dei Pagamenti sar\u00e0 ospitato su <strong>WYTH<\/strong>, <strong>piattaforma digitale<\/strong> all\u2019avanguardia che non solo permette di ospitare pi\u00f9 eventi contemporaneamente ma abilita i partecipanti ad interagire in real-time sia tra di loro che con i panelist. Sar\u00e0 possibile, inoltre, seguire interviste, workshop e panel anche in televisione, su Class CNBC, canale 507 di Sky.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Il palinsesto, come di consueto, \u00e8 ricchissimo di appuntamenti che avranno come tematiche principali:&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li>Le Nuove Frontiere Tech<\/li><li>Open Banking &#8211; Open Innovation<\/li><li>Pagamenti di oggi e di domani<\/li><li>Fintech<\/li><li>Cyber Security<\/li><li>Digitalizzazione della PA<\/li><li>E-Commerce<\/li><li>Evoluzioni normative<\/li><li>Mercato retail e mercato corporate<\/li><li>Relazione con il cliente<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p><span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/www.salonedeipagamenti.com\/\">Iscriviti al Salone<\/a><\/strong><\/span>&nbsp; e <span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/www.salonedeipagamenti.com\/programma-2020\">scarica il palinsesto completo<\/a><\/strong><\/span>.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Il <strong>4 Novembre alle 14.00<\/strong> non perdere il nostro <strong>workshop<\/strong> &#8220;<strong><span style=\"color: #f39600;\" data-mce-mark=\"1\">Request to Pay: il tassello mancante ai pagamenti SEPA end-to-end<\/span><\/strong>&#8221; e vienici a trovare allo stand virtuale che allestiremo per accogliere chiunque fosse interessato a confrontarsi sui temi caldi del nostro mercato: <span style=\"text-decoration: underline;\"><strong><a href=\"\/n1877\/\">pagamenti digitali<\/a><\/strong><\/span>, <span style=\"text-decoration: underline;\"><strong><a href=\"\/n4370\/\">open banking e PSD2<\/a><\/strong><\/span>, <span style=\"text-decoration: underline;\"><strong><a href=\"\/n1897\/\">gestione della liquidit\u00e0 e consolidation T2\/T2S<\/a><\/strong><\/span>,&nbsp;<span style=\"text-decoration: underline;\"><strong><a href=\"\/n1903\/\">e-government<\/a><\/strong><\/span>, <span style=\"text-decoration: underline;\"><strong><a href=\"\/n5237\/\">machine learning &amp; BIG DATA<\/a><\/strong><\/span> e molto altro.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Vuoi saperne di pi\u00f9?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:acf\/arrow-link {\n    \"id\": \"block_63249615ea883\",\n    \"name\": \"acf\\\/arrow-link\",\n    \"data\": {\n        \"link_list_0_link\": {\n            \"title\": \"TAS Group @ Salone dei Pagamenti 2020\",\n            \"url\": \"\\\/n6031\\\/\",\n            \"target\": \"_blank\"\n        },\n        \"_link_list_0_link\": \"field_arrow_link_link_list_link\",\n        \"link_list\": 1,\n        \"_link_list\": \"field_arrow_link_link_list\"\n    },\n    \"align\": \"\",\n    \"mode\": \"edit\"\n} \/--> <\/div>\n      <\/div>\n   \n    <div class=\"Card__Link Card__Align--Left\"> \n      <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/insight\/news\/tas-group-salone-dei-pagamenti-2020\/\" class=\"Button Button--DarkOutline\" target=\"_self\">\n    Visualizza\n<\/a>    <\/div>\n  <\/div>\n      <\/div>\n  <\/div>\n  <div class=\"Swiper__Scrollbar swiper-scrollbar js-Swiper-Scrollbar\"><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_92bc70-f6 > .kt-row-column-wrap{align-content:start;}:where(#kt-layout-id_92bc70-f6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}#kt-layout-id_92bc70-f6 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:5rem;padding-bottom:5rem;grid-template-columns:minmax(0, 1fr);}#kt-layout-id_92bc70-f6 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){#kt-layout-id_92bc70-f6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){#kt-layout-id_92bc70-f6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignfull\" id=\"soluzioni-digital-payments\"><div id=\"kt-layout-id_92bc70-f6\" class=\"kt-row-layout-inner kt-row-has-bg kt-layout-id_92bc70-f6 has-violet-to-orange-background-color\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-equal kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row\"><style>.kadence-column_bfb9b4-51 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_bfb9b4-51 > .kt-inside-inner-col,.kadence-column_bfb9b4-51 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_bfb9b4-51 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_bfb9b4-51 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_bfb9b4-51 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_bfb9b4-51 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_bfb9b4-51{text-align:center;}.kadence-column_bfb9b4-51{position:relative;}@media all and (max-width: 1024px){.kadence-column_bfb9b4-51 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_bfb9b4-51 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_bfb9b4-51\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"has-text-align-center has-white-color has-text-color wp-block-heading\">Scopri anche le nostre soluzioni correlate<\/h2>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div id=\"swiper-carousel-bcn7n\" class=\"Swiper swiper Swiper--CarouselSlider js-CarouselSlider\" data-type=\"\" data-card-count=\"3\">\n  <div class=\"Swiper__Wrapper swiper-wrapper \">\n    <div class=\"Swiper__Item swiper-slide\">\n                    <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/global-payment-platform\/\" class=\"Card Card--White\" target=\"_self\">\n    <div class=\"Card__Wrapper \">\n              <h4 class=\"Card__Title\">Platform<\/h4>\n                <\/div>\n  <\/a>\n                <\/div>  \n                                                <div class=\"Swiper__Item swiper-slide\">\n                    <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/soluzioni\/digital-payments\/fraud-management-solution\/\" class=\"Card Card--White\" target=\"_self\">\n    <div class=\"Card__Wrapper \">\n              <h4 class=\"Card__Title\">Fraud Management<\/h4>\n                <\/div>\n  <\/a>\n                <\/div>  \n                                                <div class=\"Swiper__Item swiper-slide\">\n                    <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/soluzioni\/financial-networks\/connettivita-reti-interbancarie-e-infrastrutture-pagamento\/\" class=\"Card Card--White\" target=\"_self\">\n    <div class=\"Card__Wrapper \">\n              <h4 class=\"Card__Title\">Connettivit\u00e0 alle reti<\/h4>\n                <\/div>\n  <\/a>\n                <\/div>\n  <\/div>\n  <div class=\"Swiper__Scrollbar swiper-scrollbar js-Swiper-Scrollbar\"><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap{align-content:center;}:where(#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:100%;margin-left:auto;margin-right:auto;padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:5rem;padding-bottom:5rem;grid-template-columns:repeat(2, minmax(0, 1fr));}#kt-layout-id_78a4ab-f1 > .kt-row-layout-overlay{opacity:0.30;}#kt-layout-id_78a4ab-f1 .kt-row-layout-bottom-sep{height:100px;}#kt-layout-id_78a4ab-f1 .kt-row-layout-bottom-sep svg{width:100%;}#kt-layout-id_78a4ab-f1 .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px){#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap{padding-top:3rem;padding-bottom:3rem;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1){order:2;}}@media all and (max-width: 1024px){#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2){order:1;}}@media all and (max-width: 1024px){#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3){order:12;}}@media all and (max-width: 1024px){#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4){order:11;}}@media all and (max-width: 1024px){#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5){order:22;}}@media all and (max-width: 1024px){#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6){order:21;}}@media all and (max-width: 1024px){#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7){order:32;}}@media all and (max-width: 1024px){#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8){order:31;}}@media all and (max-width: 1024px){#kt-layout-id_78a4ab-f1 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){#kt-layout-id_78a4ab-f1 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap{padding-top:3rem;padding-bottom:3rem;grid-template-columns:minmax(0, 1fr);}#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1){order:2;}#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2){order:1;}#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3){order:12;}#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4){order:11;}#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5){order:22;}#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6){order:21;}#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7){order:32;}#kt-layout-id_78a4ab-f1 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8){order:31;}#kt-layout-id_78a4ab-f1 .kt-row-layout-bottom-sep{height:px;}#kt-layout-id_78a4ab-f1 .kt-row-layout-bottom-sep svg{width:%;}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignfull\" id=\"contact-us\"><div id=\"kt-layout-id_78a4ab-f1\" class=\"kt-row-layout-inner kt-row-has-bg kt-layout-id_78a4ab-f1 has-blue-background-color\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-gutter-default kt-v-gutter-default kt-row-valign-middle kt-row-layout-equal kt-tab-layout-row kt-m-colapse-right-to-left kt-mobile-layout-row\"><style>.kadence-column_ed5c2f-59 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_ed5c2f-59 > .kt-inside-inner-col,.kadence-column_ed5c2f-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_ed5c2f-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_ed5c2f-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_ed5c2f-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_ed5c2f-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_ed5c2f-59{position:relative;}@media all and (max-width: 1024px){.kadence-column_ed5c2f-59 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_ed5c2f-59 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_ed5c2f-59\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"has-white-color has-text-color wp-block-heading\">Contattaci<\/h2>\n\n\n\n<p class=\"has-white-color has-text-color\">Scrivici per capire come possiamo aiutarti a raggiungere i tuoi obiettivi di business.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n\t\t\t\t\t<script>\n\t\t\t\t\t\twindow.hsFormsOnReady = window.hsFormsOnReady || [];\n\t\t\t\t\t\twindow.hsFormsOnReady.push(()=>{\n\t\t\t\t\t\t\thbspt.forms.create({\n\t\t\t\t\t\t\t\tportalId: 8858273,\n\t\t\t\t\t\t\t\tformId: \"00fa0dad-279c-47b6-87b1-34db68a51006\",\n\t\t\t\t\t\t\t\ttarget: \"#hbspt-form-1788330923000-3628094233\",\n\t\t\t\t\t\t\t\tregion: \"na1\",\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t})});\n\t\t\t\t\t<\/script>\n\t\t\t\t\t<div class=\"hbspt-form\" id=\"hbspt-form-1788330923000-3628094233\"><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column_771f77-40 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_771f77-40 > .kt-inside-inner-col,.kadence-column_771f77-40 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_771f77-40 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_771f77-40 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_771f77-40 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_771f77-40 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_771f77-40{position:relative;}@media all and (max-width: 1024px){.kadence-column_771f77-40 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column_771f77-40 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-2 kadence-column_771f77-40 kvs-md-false kvs-sm-false\"><div class=\"kt-inside-inner-col\"><style>.kb-lottie-container_034dbc-80 dotlottie-player{max-width:auto;}<\/style>\n<div class=\"kb-lottie-container kb-lottie-container_034dbc-80\"><lottie-player loop speed=\"1\" autoplay mode=\"normal\" id=\"kb-lottie-player_034dbc-80\" src=\"\/app\/uploads\/2022\/09\/Illustrazione_2.json\" style=\"max-width:auto;height:auto;margin:0 auto\"><\/lottie-player><\/div>\n<div class=\"kb-lottie-container kb-lottie-container_034dbc-80\"><dotlottie-player loop=\"true\" speed=\"1\" autoplay=\"true\" mode=\"normal\" src=\"\/app\/uploads\/2022\/09\/Illustrazione_2.json\"\n\t\t\t\t\t\t\tid=\"kb-lottie-player_034dbc-80\"\n\t\t\t\t\t\t><\/dotlottie-player><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pagamenti Conformi alla PSD2: una piattaforma Open API La Payment Service Directive, voluta dalla Commissione Europea per accelerare l\u2019innovazione, ha imposto alle Banche di aprirsi per consentire l\u2019entrata di nuovi intermediari di servizi di pagamento. La direttiva dei servizi di pagamento rappresenta un\u2019opportunit\u00e0 per tutti gli operatori, sia quelli tradizionali del mondo bancario, le nuove &hellip; <a href=\"https:\/\/tasgroup.jumpgroup.it\/it\/soluzioni\/psd2\/pagamenti-conformi-psd2\/\">Continued<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"parent":61,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-full.blade.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-63","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/pages\/63"}],"collection":[{"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/comments?post=63"}],"version-history":[{"count":78,"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/pages\/63\/revisions"}],"predecessor-version":[{"id":10251,"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/pages\/63\/revisions\/10251"}],"up":[{"embeddable":true,"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/pages\/61"}],"wp:attachment":[{"href":"https:\/\/tasgroup.jumpgroup.it\/it\/wp-json\/wp\/v2\/media?parent=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}